
{"id":57129,"date":"2023-03-01T13:08:15","date_gmt":"2023-03-01T16:08:15","guid":{"rendered":"https:\/\/nutritotal.com.br\/pro\/?post_type=parceiros&#038;p=57129"},"modified":"2023-06-02T13:46:46","modified_gmt":"2023-06-02T16:46:46","slug":"envelhecimento-longevidade","status":"publish","type":"parceiros","link":"https:\/\/nutritotal.com.br\/pro\/parceiros\/envelhecimento-longevidade\/","title":{"rendered":"Envelhecimento e Longevidade: atua\u00e7\u00e3o do Nutricionista"},"content":{"rendered":"<p>Envelhecer e ter longevidade \u00e9 a mesma coisa? Muita gente acredita que sim, mas a verdade \u00e9 que esses termos representam formas diferentes de encarar o passar dos anos e chegar a terceira idade.<\/p>\n<p>Antes de mais nada, precisamos lembrar que o processo de envelhecimento \u00e9 inevit\u00e1vel e j\u00e1 discutimos aqui os motivos pelos quais <a href=\"https:\/\/nutritotal.com.br\/pro\/por-que-e-importante-entender-o-processo-de-envelhecimento\/\">profissionais da sa\u00fade<\/a> devem entender sobre esse processo fisiol\u00f3gico da vida.<\/p>\n<p>Mas, \u00e9 fato, voc\u00ea pode chegar aos 60 anos bem e saud\u00e1vel, processo definido como senesc\u00eancia, ou acompanhando de uma lista de doen\u00e7as, o que chamamos de senilidade, processo que s\u00e3o reflexos das nossas escolhas ao longo da vida.<\/p>\n<h2>\u00c9 poss\u00edvel ter longevidade?<\/h2>\n<p>Para ter um belo exemplo do que \u00e9 enfrentar o envelhecimento atrav\u00e9s da \u00f3tica da senesc\u00eancia, te convido a assistir a discuss\u00e3o de caso de uma paciente de 97 anos, acompanhada pela equipe de nutri\u00e7\u00e3o cl\u00ednica da <a href=\"https:\/\/br.sodexo.com\/sobre-a-sodexo\/bons-negocios-que-beneficiam-a-t\/historia-da-sodexo\/sodexo-brasil-on-site.html\">Sodexo On-site<\/a>.<\/p>\n<p>Caracter\u00edsticas dessa paciente:<\/p>\n<p>&#8211; Diagn\u00f3stico: Vasculopatia Venosa cr\u00f4nica<\/p>\n<p>&#8211; Aus\u00eancia de comorbidades associadas<\/p>\n<p>&#8211; N\u00e3o utiliza nenhum medicamento<\/p>\n<p>&#8211; Estado nutricional de eutrofia<\/p>\n<p>&#8211; <a href=\"https:\/\/nutritotal.com.br\/pro\/existem-marcadores-bioquimicos-para-diagnosticar-sarcopenia\/\">Exames laboratoriais<\/a> normais<\/p>\n<p>No v\u00eddeo, as nutricionistas Ana Cristina Ambrosio, da Sodexo On-site, e Nat\u00e1lia Magalh\u00e3es, do Ganep Educa\u00e7\u00e3o, discutem as particularidades do caso e os fatores de hist\u00f3ria cl\u00ednica que contribu\u00edram para que essa senhora chegasse aos 97 anos ainda t\u00e3o saud\u00e1vel.<\/p>\n<p>Al\u00e9m disso, elas apresentam estrat\u00e9gias que podemos adotar nas nossas vidas e orientar os nossos pacientes jovens para que tenhamos bastante longevidade, al\u00e9m de apresentarem as principais recomenda\u00e7\u00f5es nutricionais para idosos, de acordo com as diretrizes nacionais e internacionais.<\/p>\n<p>Veja outros conte\u00fados produzidos em parceria com a Sodexo On-site:<\/p>\n<ul>\n<li><a href=\"https:\/\/nutritotal.com.br\/pro\/parceiros\/alergias-aumentam-o-risco-de-anemia-em-criancas\/\">Alergias aumentam o risco de anemia em crian\u00e7as<\/a><\/li>\n<li><a href=\"https:\/\/nutritotal.com.br\/pro\/material\/consistencia-das-dietas-hospitalares\/\">Manual pr\u00e1tico de consist\u00eancia das dietas hospitalares<\/a><\/li>\n<li><a href=\"https:\/\/nutritotal.com.br\/pro\/podcast\/importancia-do-acompanhamento-nutricional-para-pacientes-com-mieloma-multiplo\/\">Import\u00e2ncia do acompanhamento nutricional para pacientes com mieloma m\u00faltiplo<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Envelhecimento e Longevidade: atua\u00e7\u00e3o do Nutricionista\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/zGFK41TxkB0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esse caso cl\u00ednico de uma idosa de 97 \u00e9 um belo exemplo de longevidade e de como essa condi\u00e7\u00e3o se diferencia do envelhecimento comum. <\/p>\n","protected":false},"author":114981,"featured_media":57130,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2959],"tags":[3231,339,474],"divisao":[2185,3413],"categorias_parceiros":[3184],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Envelhecimento e Longevidade: atua\u00e7\u00e3o do Nutricionista<\/title>\n<meta name=\"description\" content=\"Esse caso cl\u00ednico de uma idosa de 97 \u00e9 um belo exemplo de longevidade e de como essa condi\u00e7\u00e3o se diferencia do envelhecimento comum.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nutritotal.com.br\/pro\/parceiros\/envelhecimento-longevidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Envelhecimento e Longevidade: atua\u00e7\u00e3o do Nutricionista\" \/>\n<meta property=\"og:description\" content=\"Esse caso cl\u00ednico de uma idosa de 97 \u00e9 um belo exemplo de longevidade e de como essa condi\u00e7\u00e3o se diferencia do envelhecimento comum.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nutritotal.com.br\/pro\/parceiros\/envelhecimento-longevidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Nutritotal PRO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nutritotalPRO\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-02T16:46:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2023\/03\/envelhecimento-longevidade-destacada.png\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/parceiros\/envelhecimento-longevidade\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/parceiros\/envelhecimento-longevidade\/\",\"name\":\"Envelhecimento e Longevidade: atua\u00e7\u00e3o do Nutricionista\",\"isPartOf\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/parceiros\/envelhecimento-longevidade\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/parceiros\/envelhecimento-longevidade\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2023\/03\/envelhecimento-longevidade-destacada.png\",\"datePublished\":\"2023-03-01T16:08:15+00:00\",\"dateModified\":\"2023-06-02T16:46:46+00:00\",\"description\":\"Esse caso cl\u00ednico de uma idosa de 97 \u00e9 um belo exemplo de longevidade e de como essa condi\u00e7\u00e3o se diferencia do envelhecimento comum.\",\"breadcrumb\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/parceiros\/envelhecimento-longevidade\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nutritotal.com.br\/pro\/parceiros\/envelhecimento-longevidade\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/parceiros\/envelhecimento-longevidade\/#primaryimage\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2023\/03\/envelhecimento-longevidade-destacada.png\",\"contentUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2023\/03\/envelhecimento-longevidade-destacada.png\",\"width\":580,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/parceiros\/envelhecimento-longevidade\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nutritotal.com.br\/pro\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paceiros\",\"item\":\"https:\/\/nutritotal.com.br\/pro\/parceiros\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Envelhecimento e Longevidade: atua\u00e7\u00e3o do Nutricionista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"name\":\"Nutritotal PRO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\",\"name\":\"Nutri Total\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"contentUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"width\":426,\"height\":426,\"caption\":\"Nutri Total\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/nutritotalPRO\/\",\"https:\/\/www.instagram.com\/nutritotalpro\/\",\"https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Envelhecimento e Longevidade: atua\u00e7\u00e3o do Nutricionista","description":"Esse caso cl\u00ednico de uma idosa de 97 \u00e9 um belo exemplo de longevidade e de como essa condi\u00e7\u00e3o se diferencia do envelhecimento comum.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nutritotal.com.br\/pro\/parceiros\/envelhecimento-longevidade\/","og_locale":"pt_BR","og_type":"article","og_title":"Envelhecimento e Longevidade: atua\u00e7\u00e3o do Nutricionista","og_description":"Esse caso cl\u00ednico de uma idosa de 97 \u00e9 um belo exemplo de longevidade e de como essa condi\u00e7\u00e3o se diferencia do envelhecimento comum.","og_url":"https:\/\/nutritotal.com.br\/pro\/parceiros\/envelhecimento-longevidade\/","og_site_name":"Nutritotal PRO","article_publisher":"https:\/\/www.facebook.com\/nutritotalPRO\/","article_modified_time":"2023-06-02T16:46:46+00:00","og_image":[{"width":580,"height":400,"url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2023\/03\/envelhecimento-longevidade-destacada.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nutritotal.com.br\/pro\/parceiros\/envelhecimento-longevidade\/","url":"https:\/\/nutritotal.com.br\/pro\/parceiros\/envelhecimento-longevidade\/","name":"Envelhecimento e Longevidade: atua\u00e7\u00e3o do Nutricionista","isPartOf":{"@id":"https:\/\/nutritotal.com.br\/pro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nutritotal.com.br\/pro\/parceiros\/envelhecimento-longevidade\/#primaryimage"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/parceiros\/envelhecimento-longevidade\/#primaryimage"},"thumbnailUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2023\/03\/envelhecimento-longevidade-destacada.png","datePublished":"2023-03-01T16:08:15+00:00","dateModified":"2023-06-02T16:46:46+00:00","description":"Esse caso cl\u00ednico de uma idosa de 97 \u00e9 um belo exemplo de longevidade e de como essa condi\u00e7\u00e3o se diferencia do envelhecimento comum.","breadcrumb":{"@id":"https:\/\/nutritotal.com.br\/pro\/parceiros\/envelhecimento-longevidade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nutritotal.com.br\/pro\/parceiros\/envelhecimento-longevidade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/parceiros\/envelhecimento-longevidade\/#primaryimage","url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2023\/03\/envelhecimento-longevidade-destacada.png","contentUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2023\/03\/envelhecimento-longevidade-destacada.png","width":580,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/nutritotal.com.br\/pro\/parceiros\/envelhecimento-longevidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nutritotal.com.br\/pro\/"},{"@type":"ListItem","position":2,"name":"Paceiros","item":"https:\/\/nutritotal.com.br\/pro\/parceiros\/"},{"@type":"ListItem","position":3,"name":"Envelhecimento e Longevidade: atua\u00e7\u00e3o do Nutricionista"}]},{"@type":"WebSite","@id":"https:\/\/nutritotal.com.br\/pro\/#website","url":"https:\/\/nutritotal.com.br\/pro\/","name":"Nutritotal PRO","description":"","publisher":{"@id":"https:\/\/nutritotal.com.br\/pro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nutritotal.com.br\/pro\/#organization","name":"Nutri Total","url":"https:\/\/nutritotal.com.br\/pro\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/","url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","contentUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","width":426,"height":426,"caption":"Nutri Total"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nutritotalPRO\/","https:\/\/www.instagram.com\/nutritotalpro\/","https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA"]}]}},"_links":{"self":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/parceiros\/57129"}],"collection":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/parceiros"}],"about":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/types\/parceiros"}],"author":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/users\/114981"}],"version-history":[{"count":1,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/parceiros\/57129\/revisions"}],"predecessor-version":[{"id":57131,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/parceiros\/57129\/revisions\/57131"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/media\/57130"}],"wp:attachment":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/media?parent=57129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/categories?post=57129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/tags?post=57129"},{"taxonomy":"divisao","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/divisao?post=57129"},{"taxonomy":"categorias_parceiros","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/categorias_parceiros?post=57129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}