
{"id":10075,"date":"2011-08-03T19:20:00","date_gmt":"2011-08-03T19:20:00","guid":{"rendered":"https:\/\/nutritotal.com.br\/pro?p=10075"},"modified":"2021-04-19T17:46:08","modified_gmt":"2021-04-19T20:46:08","slug":"o-que-a-sensibilidade-ao-glaoten","status":"publish","type":"post","link":"https:\/\/nutritotal.com.br\/pro\/o-que-a-sensibilidade-ao-glaoten\/","title":{"rendered":"O que \u00e9 sensibilidade ao gl\u00faten?"},"content":{"rendered":"<p>A sensibilidade ao gl\u00faten consiste em uma condi\u00e7\u00e3o cl\u00ednica em que os indiv\u00edduos apresentam alguns sinais e sintomas ap\u00f3s a ingest\u00e3o de alimentos que contenham gl\u00faten, como dor abdominal, fadiga, dores de cabe\u00e7a, dentre outros.<\/p>\n<p>Diferentemente da doen\u00e7a cel\u00edaca e da alergia ao trigo, a sensibilidade ao gl\u00faten n\u00e3o envolve mecanismos al\u00e9rgicos ou autoimunes, por isso seus sintomas s\u00e3o menos graves. Na sensibilidade ao gl\u00faten, os pacientes s\u00e3o incapazes de tolerar o gl\u00faten e desenvolvem uma rea\u00e7\u00e3o adversa que normalmente n\u00e3o leva a danos no intestino delgado. Al\u00e9m disso, os indiv\u00edduos podem apresentar melhora significativa com a exclus\u00e3o do gl\u00faten da dieta. O gl\u00faten est\u00e1 presente em alimentos como trigo, aveia, centeio, cevada e malte.<\/p>\n<p>Normalmente, o diagn\u00f3stico \u00e9 feito por exclus\u00e3o: com a retirada e reintrodu\u00e7\u00e3o monitorada dos alimentos que cont\u00eam gl\u00faten. Assim, primeiramente s\u00e3o descartadas as hip\u00f3teses de doen\u00e7a cel\u00edaca, alergia ao trigo, diabetes tipo 1, doen\u00e7as inflamat\u00f3rias intestinais e infec\u00e7\u00e3o por Helicobacter pylori. Posteriormente, relaciona-se que os sintomas foram desencadeados pela exposi\u00e7\u00e3o ao gl\u00faten e aliviados por sua exclus\u00e3o.<\/p>\n<p>O estudo de Sapone e colaboradores buscou compreender as semelhan\u00e7as e diferen\u00e7as entre a doen\u00e7a cel\u00edaca e a sensibilidade ao gl\u00faten. Os autores avaliaram a express\u00e3o de genes humanos associados com a fun\u00e7\u00e3o de barreira intestinal, bem como a imunidade inata e adaptativa nessas duas condi\u00e7\u00f5es cl\u00ednicas. Os pesquisadores observaram que a doen\u00e7a cel\u00edaca e a sensibilidade ao gl\u00faten s\u00e3o condi\u00e7\u00f5es cl\u00ednicas distintas causadas por diferentes respostas da mucosa intestinal ao gl\u00faten.<\/p>\n<p>Esta pesquisa mostrou tamb\u00e9m que a doen\u00e7a cel\u00edaca \u00e9 uma condi\u00e7\u00e3o mais complexa, em que ocorre intera\u00e7\u00e3o entre o aumento da permeabilidade intestinal, les\u00e3o da mucosa, fatores ambientais associados com exposi\u00e7\u00e3o ao gl\u00faten e predisposi\u00e7\u00e3o gen\u00e9tica. As les\u00f5es t\u00edpicas intestinais da doen\u00e7a cel\u00edaca s\u00e3o mediadas por vias efetoras da resposta imune inata e adaptativa. De maneira diferente, a sensibilidade ao gl\u00faten est\u00e1 associada com ativa\u00e7\u00e3o predominante da resposta imune inata, com aus\u00eancia de altera\u00e7\u00f5es detect\u00e1veis \u200b\u200bna fun\u00e7\u00e3o de barreira da mucosa intestinal.<\/p>\n<p>Leia mais:<\/p>\n<p><a href=\"http:\/\/www.nutritotal.com.br\/perguntas\/?acao=bu&amp;id=227&amp;categoria=9target=_blank\">O que \u00e9 doen\u00e7a cel\u00edaca?<\/a><\/p>\n<p><a href=\"http:\/\/www.nutritotal.com.br\/publicacoes\/?acao=bu&amp;id=1296&amp;categoria=1target=_blank\">Monografia: Dietoterapia na Doen\u00e7a Cel\u00edaca<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A sensibilidade ao gl\u00faten consiste em uma condi\u00e7\u00e3o cl\u00ednica em que os indiv\u00edduos apresentam alguns sinais e sintomas ap\u00f3s a ingest\u00e3o de alimentos que contenham gl\u00faten, como dor abdominal, fadiga, dores de cabe\u00e7a, dentre outros. Diferentemente da doen\u00e7a cel\u00edaca e da alergia ao trigo, a sensibilidade ao gl\u00faten n\u00e3o envolve mecanismos al\u00e9rgicos ou autoimunes, por [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"divisao":[2185,2186],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>O que \u00e9 sensibilidade ao gl\u00faten? - Nutritotal PRO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nutritotal.com.br\/pro\/o-que-a-sensibilidade-ao-glaoten\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que \u00e9 sensibilidade ao gl\u00faten? - Nutritotal PRO\" \/>\n<meta property=\"og:description\" content=\"A sensibilidade ao gl\u00faten consiste em uma condi\u00e7\u00e3o cl\u00ednica em que os indiv\u00edduos apresentam alguns sinais e sintomas ap\u00f3s a ingest\u00e3o de alimentos que contenham gl\u00faten, como dor abdominal, fadiga, dores de cabe\u00e7a, dentre outros. Diferentemente da doen\u00e7a cel\u00edaca e da alergia ao trigo, a sensibilidade ao gl\u00faten n\u00e3o envolve mecanismos al\u00e9rgicos ou autoimunes, por [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nutritotal.com.br\/pro\/o-que-a-sensibilidade-ao-glaoten\/\" \/>\n<meta property=\"og:site_name\" content=\"Nutritotal PRO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nutritotalPRO\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-08-03T19:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-19T20:46:08+00:00\" \/>\n<meta name=\"author\" content=\"Nutritotal Pro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nutritotal Pro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/o-que-a-sensibilidade-ao-glaoten\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/o-que-a-sensibilidade-ao-glaoten\/\"},\"author\":{\"name\":\"Nutritotal Pro\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb\"},\"headline\":\"O que \u00e9 sensibilidade ao gl\u00faten?\",\"datePublished\":\"2011-08-03T19:20:00+00:00\",\"dateModified\":\"2021-04-19T20:46:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/o-que-a-sensibilidade-ao-glaoten\/\"},\"wordCount\":420,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/nutritotal.com.br\/pro\/o-que-a-sensibilidade-ao-glaoten\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/o-que-a-sensibilidade-ao-glaoten\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/o-que-a-sensibilidade-ao-glaoten\/\",\"name\":\"O que \u00e9 sensibilidade ao gl\u00faten? - Nutritotal PRO\",\"isPartOf\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\"},\"datePublished\":\"2011-08-03T19:20:00+00:00\",\"dateModified\":\"2021-04-19T20:46:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/o-que-a-sensibilidade-ao-glaoten\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nutritotal.com.br\/pro\/o-que-a-sensibilidade-ao-glaoten\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/o-que-a-sensibilidade-ao-glaoten\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nutritotal.com.br\/pro\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O que \u00e9 sensibilidade ao gl\u00faten?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"name\":\"Nutritotal PRO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\",\"name\":\"Nutri Total\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"contentUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"width\":426,\"height\":426,\"caption\":\"Nutri Total\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/nutritotalPRO\/\",\"https:\/\/www.instagram.com\/nutritotalpro\/\",\"https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb\",\"name\":\"Nutritotal Pro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g\",\"caption\":\"Nutritotal Pro\"},\"url\":\"https:\/\/nutritotal.com.br\/pro\/author\/perguntaserespostasimportacao\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que \u00e9 sensibilidade ao gl\u00faten? - Nutritotal PRO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nutritotal.com.br\/pro\/o-que-a-sensibilidade-ao-glaoten\/","og_locale":"pt_BR","og_type":"article","og_title":"O que \u00e9 sensibilidade ao gl\u00faten? - Nutritotal PRO","og_description":"A sensibilidade ao gl\u00faten consiste em uma condi\u00e7\u00e3o cl\u00ednica em que os indiv\u00edduos apresentam alguns sinais e sintomas ap\u00f3s a ingest\u00e3o de alimentos que contenham gl\u00faten, como dor abdominal, fadiga, dores de cabe\u00e7a, dentre outros. Diferentemente da doen\u00e7a cel\u00edaca e da alergia ao trigo, a sensibilidade ao gl\u00faten n\u00e3o envolve mecanismos al\u00e9rgicos ou autoimunes, por [&hellip;]","og_url":"https:\/\/nutritotal.com.br\/pro\/o-que-a-sensibilidade-ao-glaoten\/","og_site_name":"Nutritotal PRO","article_publisher":"https:\/\/www.facebook.com\/nutritotalPRO\/","article_published_time":"2011-08-03T19:20:00+00:00","article_modified_time":"2021-04-19T20:46:08+00:00","author":"Nutritotal Pro","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Nutritotal Pro","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nutritotal.com.br\/pro\/o-que-a-sensibilidade-ao-glaoten\/#article","isPartOf":{"@id":"https:\/\/nutritotal.com.br\/pro\/o-que-a-sensibilidade-ao-glaoten\/"},"author":{"name":"Nutritotal Pro","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb"},"headline":"O que \u00e9 sensibilidade ao gl\u00faten?","datePublished":"2011-08-03T19:20:00+00:00","dateModified":"2021-04-19T20:46:08+00:00","mainEntityOfPage":{"@id":"https:\/\/nutritotal.com.br\/pro\/o-que-a-sensibilidade-ao-glaoten\/"},"wordCount":420,"commentCount":0,"publisher":{"@id":"https:\/\/nutritotal.com.br\/pro\/#organization"},"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nutritotal.com.br\/pro\/o-que-a-sensibilidade-ao-glaoten\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nutritotal.com.br\/pro\/o-que-a-sensibilidade-ao-glaoten\/","url":"https:\/\/nutritotal.com.br\/pro\/o-que-a-sensibilidade-ao-glaoten\/","name":"O que \u00e9 sensibilidade ao gl\u00faten? - Nutritotal PRO","isPartOf":{"@id":"https:\/\/nutritotal.com.br\/pro\/#website"},"datePublished":"2011-08-03T19:20:00+00:00","dateModified":"2021-04-19T20:46:08+00:00","breadcrumb":{"@id":"https:\/\/nutritotal.com.br\/pro\/o-que-a-sensibilidade-ao-glaoten\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nutritotal.com.br\/pro\/o-que-a-sensibilidade-ao-glaoten\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nutritotal.com.br\/pro\/o-que-a-sensibilidade-ao-glaoten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nutritotal.com.br\/pro\/"},{"@type":"ListItem","position":2,"name":"O que \u00e9 sensibilidade ao gl\u00faten?"}]},{"@type":"WebSite","@id":"https:\/\/nutritotal.com.br\/pro\/#website","url":"https:\/\/nutritotal.com.br\/pro\/","name":"Nutritotal PRO","description":"","publisher":{"@id":"https:\/\/nutritotal.com.br\/pro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nutritotal.com.br\/pro\/#organization","name":"Nutri Total","url":"https:\/\/nutritotal.com.br\/pro\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/","url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","contentUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","width":426,"height":426,"caption":"Nutri Total"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nutritotalPRO\/","https:\/\/www.instagram.com\/nutritotalpro\/","https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA"]},{"@type":"Person","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb","name":"Nutritotal Pro","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g","caption":"Nutritotal Pro"},"url":"https:\/\/nutritotal.com.br\/pro\/author\/perguntaserespostasimportacao\/"}]}},"views":935,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/10075"}],"collection":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/comments?post=10075"}],"version-history":[{"count":0,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/10075\/revisions"}],"wp:attachment":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/media?parent=10075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/categories?post=10075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/tags?post=10075"},{"taxonomy":"divisao","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/divisao?post=10075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}