
{"id":10481,"date":"2014-09-25T19:26:00","date_gmt":"2014-09-25T22:26:00","guid":{"rendered":"https:\/\/nutritotal.com.br\/pro?p=10481"},"modified":"2023-05-31T10:49:53","modified_gmt":"2023-05-31T13:49:53","slug":"quais-sa-o-os-ma-todos-dispona-veis-para-a-determinaa-a-o-do-gasto-energa-tico","status":"publish","type":"post","link":"https:\/\/nutritotal.com.br\/pro\/quais-sa-o-os-ma-todos-dispona-veis-para-a-determinaa-a-o-do-gasto-energa-tico\/","title":{"rendered":"Quais s\u00e3o os m\u00e9todos dispon\u00edveis para a determina\u00e7\u00e3o do gasto energ\u00e9tico?"},"content":{"rendered":"<div><span>Muitos m\u00e9todos s\u00e3o dispon\u00edveis para determinar o gasto energ\u00e9tico (GE), como a calorimetria direta ou indireta, a \u00e1gua duplamente marcada, ou atrav\u00e9s de f\u00f3rmulas estimativas. Por\u00e9m, ainda h\u00e1 controv\u00e9rsias de qual seria o mais preciso.<\/span><\/div>\n<div><span>\u00a0<\/span><\/div>\n<div><span>A calorimetria direta mede o metabolismo basal pela determina\u00e7\u00e3o da quantidade de calor produzida a partir da oxida\u00e7\u00e3o de substratos energ\u00e9ticos, al\u00e9m do vapor de \u00e1gua liberado pela respira\u00e7\u00e3o e pela pele. Esse m\u00e9todo tem precis\u00e3o de 99% e grande import\u00e2ncia em pesquisa. Na pratica cl\u00ednica \u00e9 pouco utilizada por requerer uma c\u00e2mara altamente sofisticada, de alto custo, e por precisar de isolamento total do paciente para o exame, que deve permanecer na c\u00e2mara por per\u00edodo igual ou superior a 24 horas, impedindo seu uso em paciente ventilado mecanicamente.<\/span><\/div>\n<div><span>\u00a0<\/span><\/div>\n<div><span>A calorimetria indireta \u00e9 um m\u00e9todo seguro, pr\u00e1tico, n\u00e3o invasivo, com a facilidade de que o equipamento utilizado \u00e9 port\u00e1til, podendo ser usado \u00e0 beira do leito. Essa t\u00e9cnica mensura o GE por meio da an\u00e1lise do volume de oxig\u00eanio consumido (VO2), do volume de di\u00f3xido de carbono produzido (VCO2) e, ainda, do quociente respirat\u00f3rio (QR = VO2\/VCO2), apontando assim a quantidade de energia necess\u00e1ria para a realiza\u00e7\u00e3o dos processos metab\u00f3licos. O calor\u00edmetro \u00e9 composto por uma mistura de coletor de gases que adapta no paciente um sistema de volume e concentra\u00e7\u00e3o de O2 e CO2. O paciente inspira o ar com composi\u00e7\u00e3o conhecida e, atrav\u00e9s de v\u00e1lvula unidirecional, colhem-se amostras de ar expirado para quantificar o volume e a concentra\u00e7\u00e3o de O2 e CO2. Conhecidos esses volumes, calcula-se o gasto energ\u00e9tico atrav\u00e9s da f\u00f3rmula de Weir [GE = [3,9 (VO2) + (VCO2) 1,44 \u2013 2,17 (UN)], sendo UN = nitrog\u00eanio urin\u00e1rio. Essa t\u00e9cnica n\u00e3o permite ao avaliado muita mobilidade e, por isso, \u00e9 utilizada prioritariamente para situa\u00e7\u00f5es de repouso. A determina\u00e7\u00e3o do gasto energ\u00e9tico basal por essa t\u00e9cnica necessita que a medida seja feita durante o per\u00edodo de sono do avaliado. Pela dificuldade de se medir o indiv\u00edduo nessa situa\u00e7\u00e3o, grande parte dos estudos na literatura utilizam a medida do gasto energ\u00e9tico de repouso, que \u00e9 feita geralmente pela manh\u00e3 com o indiv\u00edduo deitado, por\u00e9m acordado.<\/span><\/div>\n<div><span>\u00a0<\/span><\/div>\n<div><span>A \u00e1gua duplamente marcada informa o GE acumulado por um per\u00edodo superior a dois dias. Pode ser realizada em indiv\u00edduos saud\u00e1veis ou enfermos, nas diversas faixas et\u00e1rias. O indiv\u00edduo deve ingerir uma dose de \u00e1gua contendo is\u00f3topos est\u00e1veis de hidrog\u00eanio (H2) e oxig\u00eanio (O18). Os is\u00f3topos de H2 e de O18 misturam-se com a \u00e1gua corporal em aproximadamente 3 horas. Conforme a energia \u00e9 gasta pelo corpo, di\u00f3xido de carbono (CO2) e \u00e1gua s\u00e3o produzidos. O CO2 \u00e9 eliminado atrav\u00e9s dos pulm\u00f5es ao passo que a \u00e1gua \u00e9 eliminada pelos pulm\u00f5es, pele e urina. A taxa de perda de H2 e O18 \u00e9 determinada pela medida do decl\u00ednio na concentra\u00e7\u00e3o dos is\u00f3topos em algum fluido do corpo (usualmente a urina). A diferen\u00e7a entre a taxa de perda dos dois is\u00f3topos \u00e9 usada para estimar a taxa de produ\u00e7\u00e3o de CO2 e, por sua vez, o GE do indiv\u00edduo \u00e9 calculado utilizando-se a f\u00f3rmula de Weir.\u00a0<\/span><\/div>\n<div><span>\u00a0<\/span><\/div>\n<div><span>Quanto ao uso de f\u00f3rmulas, existem mais de 190 delas publicadas na literatura para estimar o gasto energ\u00e9tico, as quais utilizam as vari\u00e1veis: peso, altura, idade, sexo, e superf\u00edcie corporal. Na pr\u00e1tica cl\u00ednica, as f\u00f3rmulas mais utilizadas s\u00e3o as de Harris e Benedict, no entanto, estudos demonstram que o GE calculado frequentemente subestima o gasto energ\u00e9tico total.\u00a0<\/span><\/div>\n<div><span>\u00a0<\/span><\/div>\n<div><span>O m\u00e9todo de calorimetria indireta \u00e9 considerado padr\u00e3o ouro para a determina\u00e7\u00e3o do GE, mas infelizmente s\u00e3o poucos locais que disp\u00f5e do aparelho. Portanto, cabe ao profissional respons\u00e1vel pela terapia nutricional, o bom senso na escolha da melhor monitoriza\u00e7\u00e3o e op\u00e7\u00e3o para seus pacientes.\u00a0<\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Muitos m\u00e9todos s\u00e3o dispon\u00edveis para determinar o gasto energ\u00e9tico (GE), como a calorimetria direta ou indireta, a \u00e1gua duplamente marcada, ou atrav\u00e9s de f\u00f3rmulas estimativas. Por\u00e9m, ainda h\u00e1 controv\u00e9rsias de qual seria o mais preciso. \u00a0 A calorimetria direta mede o metabolismo basal pela determina\u00e7\u00e3o da quantidade de calor produzida a partir da oxida\u00e7\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"divisao":[3233,2185,2186,2187],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quais s\u00e3o os m\u00e9todos dispon\u00edveis para a determina\u00e7\u00e3o do gasto energ\u00e9tico? - Nutritotal PRO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nutritotal.com.br\/pro\/quais-sa-o-os-ma-todos-dispona-veis-para-a-determinaa-a-o-do-gasto-energa-tico\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quais s\u00e3o os m\u00e9todos dispon\u00edveis para a determina\u00e7\u00e3o do gasto energ\u00e9tico? - Nutritotal PRO\" \/>\n<meta property=\"og:description\" content=\"Muitos m\u00e9todos s\u00e3o dispon\u00edveis para determinar o gasto energ\u00e9tico (GE), como a calorimetria direta ou indireta, a \u00e1gua duplamente marcada, ou atrav\u00e9s de f\u00f3rmulas estimativas. Por\u00e9m, ainda h\u00e1 controv\u00e9rsias de qual seria o mais preciso. \u00a0 A calorimetria direta mede o metabolismo basal pela determina\u00e7\u00e3o da quantidade de calor produzida a partir da oxida\u00e7\u00e3o de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nutritotal.com.br\/pro\/quais-sa-o-os-ma-todos-dispona-veis-para-a-determinaa-a-o-do-gasto-energa-tico\/\" \/>\n<meta property=\"og:site_name\" content=\"Nutritotal PRO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nutritotalPRO\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-25T22:26:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-31T13:49:53+00:00\" \/>\n<meta name=\"author\" content=\"Nutritotal Pro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nutritotal Pro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/quais-sa-o-os-ma-todos-dispona-veis-para-a-determinaa-a-o-do-gasto-energa-tico\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/quais-sa-o-os-ma-todos-dispona-veis-para-a-determinaa-a-o-do-gasto-energa-tico\/\"},\"author\":{\"name\":\"Nutritotal Pro\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb\"},\"headline\":\"Quais s\u00e3o os m\u00e9todos dispon\u00edveis para a determina\u00e7\u00e3o do gasto energ\u00e9tico?\",\"datePublished\":\"2014-09-25T22:26:00+00:00\",\"dateModified\":\"2023-05-31T13:49:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/quais-sa-o-os-ma-todos-dispona-veis-para-a-determinaa-a-o-do-gasto-energa-tico\/\"},\"wordCount\":693,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/nutritotal.com.br\/pro\/quais-sa-o-os-ma-todos-dispona-veis-para-a-determinaa-a-o-do-gasto-energa-tico\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/quais-sa-o-os-ma-todos-dispona-veis-para-a-determinaa-a-o-do-gasto-energa-tico\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/quais-sa-o-os-ma-todos-dispona-veis-para-a-determinaa-a-o-do-gasto-energa-tico\/\",\"name\":\"Quais s\u00e3o os m\u00e9todos dispon\u00edveis para a determina\u00e7\u00e3o do gasto energ\u00e9tico? - Nutritotal PRO\",\"isPartOf\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\"},\"datePublished\":\"2014-09-25T22:26:00+00:00\",\"dateModified\":\"2023-05-31T13:49:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/quais-sa-o-os-ma-todos-dispona-veis-para-a-determinaa-a-o-do-gasto-energa-tico\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nutritotal.com.br\/pro\/quais-sa-o-os-ma-todos-dispona-veis-para-a-determinaa-a-o-do-gasto-energa-tico\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/quais-sa-o-os-ma-todos-dispona-veis-para-a-determinaa-a-o-do-gasto-energa-tico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nutritotal.com.br\/pro\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quais s\u00e3o os m\u00e9todos dispon\u00edveis para a determina\u00e7\u00e3o do gasto energ\u00e9tico?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"name\":\"Nutritotal PRO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\",\"name\":\"Nutri Total\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"contentUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"width\":426,\"height\":426,\"caption\":\"Nutri Total\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/nutritotalPRO\/\",\"https:\/\/www.instagram.com\/nutritotalpro\/\",\"https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb\",\"name\":\"Nutritotal Pro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g\",\"caption\":\"Nutritotal Pro\"},\"url\":\"https:\/\/nutritotal.com.br\/pro\/author\/perguntaserespostasimportacao\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quais s\u00e3o os m\u00e9todos dispon\u00edveis para a determina\u00e7\u00e3o do gasto energ\u00e9tico? - Nutritotal PRO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nutritotal.com.br\/pro\/quais-sa-o-os-ma-todos-dispona-veis-para-a-determinaa-a-o-do-gasto-energa-tico\/","og_locale":"pt_BR","og_type":"article","og_title":"Quais s\u00e3o os m\u00e9todos dispon\u00edveis para a determina\u00e7\u00e3o do gasto energ\u00e9tico? - Nutritotal PRO","og_description":"Muitos m\u00e9todos s\u00e3o dispon\u00edveis para determinar o gasto energ\u00e9tico (GE), como a calorimetria direta ou indireta, a \u00e1gua duplamente marcada, ou atrav\u00e9s de f\u00f3rmulas estimativas. Por\u00e9m, ainda h\u00e1 controv\u00e9rsias de qual seria o mais preciso. \u00a0 A calorimetria direta mede o metabolismo basal pela determina\u00e7\u00e3o da quantidade de calor produzida a partir da oxida\u00e7\u00e3o de [&hellip;]","og_url":"https:\/\/nutritotal.com.br\/pro\/quais-sa-o-os-ma-todos-dispona-veis-para-a-determinaa-a-o-do-gasto-energa-tico\/","og_site_name":"Nutritotal PRO","article_publisher":"https:\/\/www.facebook.com\/nutritotalPRO\/","article_published_time":"2014-09-25T22:26:00+00:00","article_modified_time":"2023-05-31T13:49:53+00:00","author":"Nutritotal Pro","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Nutritotal Pro","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nutritotal.com.br\/pro\/quais-sa-o-os-ma-todos-dispona-veis-para-a-determinaa-a-o-do-gasto-energa-tico\/#article","isPartOf":{"@id":"https:\/\/nutritotal.com.br\/pro\/quais-sa-o-os-ma-todos-dispona-veis-para-a-determinaa-a-o-do-gasto-energa-tico\/"},"author":{"name":"Nutritotal Pro","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb"},"headline":"Quais s\u00e3o os m\u00e9todos dispon\u00edveis para a determina\u00e7\u00e3o do gasto energ\u00e9tico?","datePublished":"2014-09-25T22:26:00+00:00","dateModified":"2023-05-31T13:49:53+00:00","mainEntityOfPage":{"@id":"https:\/\/nutritotal.com.br\/pro\/quais-sa-o-os-ma-todos-dispona-veis-para-a-determinaa-a-o-do-gasto-energa-tico\/"},"wordCount":693,"commentCount":0,"publisher":{"@id":"https:\/\/nutritotal.com.br\/pro\/#organization"},"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nutritotal.com.br\/pro\/quais-sa-o-os-ma-todos-dispona-veis-para-a-determinaa-a-o-do-gasto-energa-tico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nutritotal.com.br\/pro\/quais-sa-o-os-ma-todos-dispona-veis-para-a-determinaa-a-o-do-gasto-energa-tico\/","url":"https:\/\/nutritotal.com.br\/pro\/quais-sa-o-os-ma-todos-dispona-veis-para-a-determinaa-a-o-do-gasto-energa-tico\/","name":"Quais s\u00e3o os m\u00e9todos dispon\u00edveis para a determina\u00e7\u00e3o do gasto energ\u00e9tico? - Nutritotal PRO","isPartOf":{"@id":"https:\/\/nutritotal.com.br\/pro\/#website"},"datePublished":"2014-09-25T22:26:00+00:00","dateModified":"2023-05-31T13:49:53+00:00","breadcrumb":{"@id":"https:\/\/nutritotal.com.br\/pro\/quais-sa-o-os-ma-todos-dispona-veis-para-a-determinaa-a-o-do-gasto-energa-tico\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nutritotal.com.br\/pro\/quais-sa-o-os-ma-todos-dispona-veis-para-a-determinaa-a-o-do-gasto-energa-tico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nutritotal.com.br\/pro\/quais-sa-o-os-ma-todos-dispona-veis-para-a-determinaa-a-o-do-gasto-energa-tico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nutritotal.com.br\/pro\/"},{"@type":"ListItem","position":2,"name":"Quais s\u00e3o os m\u00e9todos dispon\u00edveis para a determina\u00e7\u00e3o do gasto energ\u00e9tico?"}]},{"@type":"WebSite","@id":"https:\/\/nutritotal.com.br\/pro\/#website","url":"https:\/\/nutritotal.com.br\/pro\/","name":"Nutritotal PRO","description":"","publisher":{"@id":"https:\/\/nutritotal.com.br\/pro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nutritotal.com.br\/pro\/#organization","name":"Nutri Total","url":"https:\/\/nutritotal.com.br\/pro\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/","url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","contentUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","width":426,"height":426,"caption":"Nutri Total"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nutritotalPRO\/","https:\/\/www.instagram.com\/nutritotalpro\/","https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA"]},{"@type":"Person","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb","name":"Nutritotal Pro","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g","caption":"Nutritotal Pro"},"url":"https:\/\/nutritotal.com.br\/pro\/author\/perguntaserespostasimportacao\/"}]}},"views":17520,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/10481"}],"collection":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/comments?post=10481"}],"version-history":[{"count":1,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/10481\/revisions"}],"predecessor-version":[{"id":58674,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/10481\/revisions\/58674"}],"wp:attachment":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/media?parent=10481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/categories?post=10481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/tags?post=10481"},{"taxonomy":"divisao","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/divisao?post=10481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}