
{"id":10495,"date":"2017-12-20T16:03:00","date_gmt":"2017-12-20T18:03:00","guid":{"rendered":"https:\/\/nutritotal.com.br\/pro?p=10495"},"modified":"2023-05-31T16:53:46","modified_gmt":"2023-05-31T19:53:46","slug":"como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral","status":"publish","type":"post","link":"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/","title":{"rendered":"Como deve ser a monitoramento laboratorial para pacientes em Nutri\u00e7\u00e3o Enteral e Parenteral?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive\" style=\"float: left;margin: 0 .5em 0 0\" role=\"presentation\" src=\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2017\/12\/exames20laboratoriais.jpg\" alt=\"\" width=\"266\" height=\"150\" \/>Pacientes em uso de Terapia Nutricional devem ter seus exameslaboratoriais constantemente monitorados.<\/p>\n<p>Para aqueles em uso de Terapia de Nutri\u00e7\u00e3o Enteral, o monitoramento deveincluir glicemia, s\u00f3dio, pot\u00e1ssio, fosfato e magn\u00e9sio diariamente. Fun\u00e7\u00e3o hep\u00e1ticae hemograma completo devem ser monitorados semanalmente e ap\u00f3s a estabiliza\u00e7\u00e3ohemodin\u00e2mica do paciente. Sempre que poss\u00edvel, deve-se monitorar os n\u00edveis deelementos tra\u00e7o e vitaminas.<\/p>\n<p>O monitoramento dos pacientes em Terapia de Nutri\u00e7\u00e3o Parenteral requerainda mais aten\u00e7\u00e3o, e vai depender da fase cl\u00ednica em que o paciente seencontra, como pode ser observado na tabela abaixo.<\/p>\n<p><b>Tabela.<\/b> Programa\u00e7\u00e3o para monitorar os valores laboratoriais durante PN<\/p>\n<table style=\"margin-left: 12.5pt;border-collapse: collapse;border: none\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 106.3pt;border-top: solid #4F81BD 1.0pt;border-left: solid #4F81BD 1.0pt;border-bottom: none;border-right: none;background: #4F81BD;padding: 0cm 5.4pt 0cm 5.4pt\" width=\"142\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\"><b>Exames Laboratoriais<\/b><\/p>\n<\/td>\n<td style=\"width: 104.45pt;border: none;border-top: solid #4F81BD 1.0pt;background: #4F81BD;padding: 0cm 5.4pt 0cm 5.4pt\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\"><b>Avalia\u00e7\u00e3o para in\u00edcio da PN<\/b><\/p>\n<\/td>\n<td style=\"width: 104.45pt;border: none;border-top: solid #4F81BD 1.0pt;background: #4F81BD;padding: 0cm 5.4pt 0cm 5.4pt\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\"><b>Exames laboratoriais na suspeita de s\u00edndrome de realimenta\u00e7\u00e3o<\/b><\/p>\n<\/td>\n<td style=\"width: 104.5pt;border-top: solid #4F81BD 1.0pt;border-left: none;border-bottom: none;border-right: solid #4F81BD 1.0pt;background: #4F81BD;padding: 0cm 5.4pt 0cm 5.4pt\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\"><b>Exames laboratoriais quando a PN est\u00e1 est\u00e1vel<\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 106.3pt;border: solid #4F81BD 1.0pt;border-right: none;background: #C6D9F1;padding: 0cm 5.4pt 0cm 5.4pt\" width=\"142\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\"><b>Quando?<\/b><\/p>\n<\/td>\n<td style=\"width: 104.45pt;border-top: solid #4F81BD 1.0pt;border-left: none;border-bottom: solid #4F81BD 1.0pt;border-right: none;background: #C6D9F1;padding: 0cm 5.4pt 0cm 5.4pt\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">Dia 0: antes de come\u00e7ar PN<\/p>\n<\/td>\n<td style=\"width: 104.45pt;border-top: solid #4F81BD 1.0pt;border-left: none;border-bottom: solid #4F81BD 1.0pt;border-right: none;background: #C6D9F1;padding: 0cm 5.4pt 0cm 5.4pt\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">Dia 0 at\u00e9 4-10 dias<\/p>\n<\/td>\n<td style=\"width: 104.5pt;border: solid #4F81BD 1.0pt;border-left: none;background: #C6D9F1;padding: 0cm 5.4pt 0cm 5.4pt\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">Uma vez por semana (dia fixo)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 106.3pt;border: none;border-left: solid #4F81BD 1.0pt;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"142\">\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><b>PCR<\/b><\/p>\n<\/td>\n<td style=\"width: 104.45pt;border: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<td style=\"width: 104.45pt;border: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">\n<\/td>\n<td style=\"width: 104.5pt;border: none;border-right: solid #4F81BD 1.0pt;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 106.3pt;border: solid #4F81BD 1.0pt;border-right: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"142\">\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><b>S\u00f3dio<\/b><\/p>\n<\/td>\n<td style=\"width: 104.45pt;border-top: solid #4F81BD 1.0pt;border-left: none;border-bottom: solid #4F81BD 1.0pt;border-right: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<td style=\"width: 104.45pt;border-top: solid #4F81BD 1.0pt;border-left: none;border-bottom: solid #4F81BD 1.0pt;border-right: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<td style=\"width: 104.5pt;border: solid #4F81BD 1.0pt;border-left: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 106.3pt;border: none;border-left: solid #4F81BD 1.0pt;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"142\">\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><b>Pot\u00e1ssio<\/b><\/p>\n<\/td>\n<td style=\"width: 104.45pt;border: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<td style=\"width: 104.45pt;border: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<td style=\"width: 104.5pt;border: none;border-right: solid #4F81BD 1.0pt;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 106.3pt;border: solid #4F81BD 1.0pt;border-right: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"142\">\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><b>Cloro<\/b><\/p>\n<\/td>\n<td style=\"width: 104.45pt;border-top: solid #4F81BD 1.0pt;border-left: none;border-bottom: solid #4F81BD 1.0pt;border-right: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<td style=\"width: 104.45pt;border-top: solid #4F81BD 1.0pt;border-left: none;border-bottom: solid #4F81BD 1.0pt;border-right: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">\n<\/td>\n<td style=\"width: 104.5pt;border: solid #4F81BD 1.0pt;border-left: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 106.3pt;border: none;border-left: solid #4F81BD 1.0pt;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"142\">\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><b>C\u00e1lcio <\/b><\/p>\n<\/td>\n<td style=\"width: 104.45pt;border: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<td style=\"width: 104.45pt;border: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<td style=\"width: 104.5pt;border: none;border-right: solid #4F81BD 1.0pt;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 106.3pt;border: solid #4F81BD 1.0pt;border-right: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"142\">\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><b>Magn\u00e9sio<\/b><\/p>\n<\/td>\n<td style=\"width: 104.45pt;border-top: solid #4F81BD 1.0pt;border-left: none;border-bottom: solid #4F81BD 1.0pt;border-right: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<td style=\"width: 104.45pt;border-top: solid #4F81BD 1.0pt;border-left: none;border-bottom: solid #4F81BD 1.0pt;border-right: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<td style=\"width: 104.5pt;border: solid #4F81BD 1.0pt;border-left: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 106.3pt;border: none;border-left: solid #4F81BD 1.0pt;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"142\">\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><b>Fosfato<\/b><\/p>\n<\/td>\n<td style=\"width: 104.45pt;border: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<td style=\"width: 104.45pt;border: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<td style=\"width: 104.5pt;border: none;border-right: solid #4F81BD 1.0pt;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 106.3pt;border: solid #4F81BD 1.0pt;border-right: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"142\">\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><b>Creatina<\/b><\/p>\n<\/td>\n<td style=\"width: 104.45pt;border-top: solid #4F81BD 1.0pt;border-left: none;border-bottom: solid #4F81BD 1.0pt;border-right: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<td style=\"width: 104.45pt;border-top: solid #4F81BD 1.0pt;border-left: none;border-bottom: solid #4F81BD 1.0pt;border-right: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<td style=\"width: 104.5pt;border: solid #4F81BD 1.0pt;border-left: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 106.3pt;border: none;border-left: solid #4F81BD 1.0pt;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"142\">\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><b>Albumina<\/b><\/p>\n<\/td>\n<td style=\"width: 104.45pt;border: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<td style=\"width: 104.45pt;border: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<td style=\"width: 104.5pt;border: none;border-right: solid #4F81BD 1.0pt;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 106.3pt;border: solid #4F81BD 1.0pt;border-right: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"142\">\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><b>Glicose<\/b><\/p>\n<\/td>\n<td style=\"width: 104.45pt;border-top: solid #4F81BD 1.0pt;border-left: none;border-bottom: solid #4F81BD 1.0pt;border-right: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<td style=\"width: 104.45pt;border-top: solid #4F81BD 1.0pt;border-left: none;border-bottom: solid #4F81BD 1.0pt;border-right: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<td style=\"width: 104.5pt;border: solid #4F81BD 1.0pt;border-left: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 106.3pt;border: none;border-left: solid #4F81BD 1.0pt;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"142\">\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><b>Bilirrubina<\/b><\/p>\n<\/td>\n<td style=\"width: 104.45pt;border: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<td style=\"width: 104.45pt;border: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">\n<\/td>\n<td style=\"width: 104.5pt;border: none;border-right: solid #4F81BD 1.0pt;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 106.3pt;border: solid #4F81BD 1.0pt;border-right: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"142\">\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><b>Fosfatase Alcalina<\/b><\/p>\n<\/td>\n<td style=\"width: 104.45pt;border-top: solid #4F81BD 1.0pt;border-left: none;border-bottom: solid #4F81BD 1.0pt;border-right: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<td style=\"width: 104.45pt;border-top: solid #4F81BD 1.0pt;border-left: none;border-bottom: solid #4F81BD 1.0pt;border-right: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">\n<\/td>\n<td style=\"width: 104.5pt;border: solid #4F81BD 1.0pt;border-left: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 106.3pt;border: none;border-left: solid #4F81BD 1.0pt;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"142\">\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><b>ALT<\/b><\/p>\n<\/td>\n<td style=\"width: 104.45pt;border: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<td style=\"width: 104.45pt;border: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">\n<\/td>\n<td style=\"width: 104.5pt;border: none;border-right: solid #4F81BD 1.0pt;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 106.3pt;border: solid #4F81BD 1.0pt;border-right: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"142\">\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><b>Triglic\u00e9rides <\/b><\/p>\n<\/td>\n<td style=\"width: 104.45pt;border-top: solid #4F81BD 1.0pt;border-left: none;border-bottom: solid #4F81BD 1.0pt;border-right: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<td style=\"width: 104.45pt;border-top: solid #4F81BD 1.0pt;border-left: none;border-bottom: solid #4F81BD 1.0pt;border-right: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">\n<\/td>\n<td style=\"width: 104.5pt;border: solid #4F81BD 1.0pt;border-left: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 106.3pt;border-top: none;border-left: solid #4F81BD 1.0pt;border-bottom: solid #4F81BD 1.0pt;border-right: none;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"142\">\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><b>Tempo de protrombina<\/b><\/p>\n<\/td>\n<td style=\"width: 104.45pt;border: none;border-bottom: solid #4F81BD 1.0pt;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">X<\/p>\n<\/td>\n<td style=\"width: 104.45pt;border: none;border-bottom: solid #4F81BD 1.0pt;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">\n<\/td>\n<td style=\"width: 104.5pt;border-top: none;border-left: none;border-bottom: solid #4F81BD 1.0pt;border-right: solid #4F81BD 1.0pt;padding: 0cm 5.4pt 0cm 5.4pt\" valign=\"top\" width=\"139\">\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\" align=\"center\">\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><b><i>\u00a0 Fonte:<\/i><\/b> adaptado de ESPEN, 2017.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pacientes em uso de Terapia Nutricional devem ter seus exameslaboratoriais constantemente monitorados. Para aqueles em uso de Terapia de Nutri\u00e7\u00e3o Enteral, o monitoramento deveincluir glicemia, s\u00f3dio, pot\u00e1ssio, fosfato e magn\u00e9sio diariamente. Fun\u00e7\u00e3o hep\u00e1ticae hemograma completo devem ser monitorados semanalmente e ap\u00f3s a estabiliza\u00e7\u00e3ohemodin\u00e2mica do paciente. Sempre que poss\u00edvel, deve-se monitorar os n\u00edveis deelementos tra\u00e7o e [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":10494,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[576,577],"tags":[194,98],"divisao":[3233,2185,2192,3327],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Como deve ser a monitoramento laboratorial para pacientes em Nutri\u00e7\u00e3o Enteral e Parenteral? - Nutritotal PRO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como deve ser a monitoramento laboratorial para pacientes em Nutri\u00e7\u00e3o Enteral e Parenteral? - Nutritotal PRO\" \/>\n<meta property=\"og:description\" content=\"Pacientes em uso de Terapia Nutricional devem ter seus exameslaboratoriais constantemente monitorados. Para aqueles em uso de Terapia de Nutri\u00e7\u00e3o Enteral, o monitoramento deveincluir glicemia, s\u00f3dio, pot\u00e1ssio, fosfato e magn\u00e9sio diariamente. Fun\u00e7\u00e3o hep\u00e1ticae hemograma completo devem ser monitorados semanalmente e ap\u00f3s a estabiliza\u00e7\u00e3ohemodin\u00e2mica do paciente. Sempre que poss\u00edvel, deve-se monitorar os n\u00edveis deelementos tra\u00e7o e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/\" \/>\n<meta property=\"og:site_name\" content=\"Nutritotal PRO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nutritotalPRO\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-20T18:03:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-31T19:53:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2017\/12\/exames20laboratoriais.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"169\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nutritotal Pro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nutritotal Pro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/\"},\"author\":{\"name\":\"Nutritotal Pro\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb\"},\"headline\":\"Como deve ser a monitoramento laboratorial para pacientes em Nutri\u00e7\u00e3o Enteral e Parenteral?\",\"datePublished\":\"2017-12-20T18:03:00+00:00\",\"dateModified\":\"2023-05-31T19:53:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/\"},\"wordCount\":232,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2017\/12\/exames20laboratoriais.jpg\",\"keywords\":[\"nutri\u00e7\u00e3o enteral\",\"Nutri\u00e7\u00e3o parenteral\"],\"articleSection\":[\"Nutri\u00e7\u00e3o Enteral\",\"Nutri\u00e7\u00e3o Parenteral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/\",\"name\":\"Como deve ser a monitoramento laboratorial para pacientes em Nutri\u00e7\u00e3o Enteral e Parenteral? - Nutritotal PRO\",\"isPartOf\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2017\/12\/exames20laboratoriais.jpg\",\"datePublished\":\"2017-12-20T18:03:00+00:00\",\"dateModified\":\"2023-05-31T19:53:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/#primaryimage\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2017\/12\/exames20laboratoriais.jpg\",\"contentUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2017\/12\/exames20laboratoriais.jpg\",\"width\":300,\"height\":169},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nutritotal.com.br\/pro\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como deve ser a monitoramento laboratorial para pacientes em Nutri\u00e7\u00e3o Enteral e Parenteral?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"name\":\"Nutritotal PRO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\",\"name\":\"Nutri Total\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"contentUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"width\":426,\"height\":426,\"caption\":\"Nutri Total\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/nutritotalPRO\/\",\"https:\/\/www.instagram.com\/nutritotalpro\/\",\"https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb\",\"name\":\"Nutritotal Pro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g\",\"caption\":\"Nutritotal Pro\"},\"url\":\"https:\/\/nutritotal.com.br\/pro\/author\/perguntaserespostasimportacao\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como deve ser a monitoramento laboratorial para pacientes em Nutri\u00e7\u00e3o Enteral e Parenteral? - Nutritotal PRO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/","og_locale":"pt_BR","og_type":"article","og_title":"Como deve ser a monitoramento laboratorial para pacientes em Nutri\u00e7\u00e3o Enteral e Parenteral? - Nutritotal PRO","og_description":"Pacientes em uso de Terapia Nutricional devem ter seus exameslaboratoriais constantemente monitorados. Para aqueles em uso de Terapia de Nutri\u00e7\u00e3o Enteral, o monitoramento deveincluir glicemia, s\u00f3dio, pot\u00e1ssio, fosfato e magn\u00e9sio diariamente. Fun\u00e7\u00e3o hep\u00e1ticae hemograma completo devem ser monitorados semanalmente e ap\u00f3s a estabiliza\u00e7\u00e3ohemodin\u00e2mica do paciente. Sempre que poss\u00edvel, deve-se monitorar os n\u00edveis deelementos tra\u00e7o e [&hellip;]","og_url":"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/","og_site_name":"Nutritotal PRO","article_publisher":"https:\/\/www.facebook.com\/nutritotalPRO\/","article_published_time":"2017-12-20T18:03:00+00:00","article_modified_time":"2023-05-31T19:53:46+00:00","og_image":[{"width":300,"height":169,"url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2017\/12\/exames20laboratoriais.jpg","type":"image\/jpeg"}],"author":"Nutritotal Pro","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Nutritotal Pro","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/#article","isPartOf":{"@id":"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/"},"author":{"name":"Nutritotal Pro","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb"},"headline":"Como deve ser a monitoramento laboratorial para pacientes em Nutri\u00e7\u00e3o Enteral e Parenteral?","datePublished":"2017-12-20T18:03:00+00:00","dateModified":"2023-05-31T19:53:46+00:00","mainEntityOfPage":{"@id":"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/"},"wordCount":232,"commentCount":0,"publisher":{"@id":"https:\/\/nutritotal.com.br\/pro\/#organization"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/#primaryimage"},"thumbnailUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2017\/12\/exames20laboratoriais.jpg","keywords":["nutri\u00e7\u00e3o enteral","Nutri\u00e7\u00e3o parenteral"],"articleSection":["Nutri\u00e7\u00e3o Enteral","Nutri\u00e7\u00e3o Parenteral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/","url":"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/","name":"Como deve ser a monitoramento laboratorial para pacientes em Nutri\u00e7\u00e3o Enteral e Parenteral? - Nutritotal PRO","isPartOf":{"@id":"https:\/\/nutritotal.com.br\/pro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/#primaryimage"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/#primaryimage"},"thumbnailUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2017\/12\/exames20laboratoriais.jpg","datePublished":"2017-12-20T18:03:00+00:00","dateModified":"2023-05-31T19:53:46+00:00","breadcrumb":{"@id":"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/#primaryimage","url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2017\/12\/exames20laboratoriais.jpg","contentUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2017\/12\/exames20laboratoriais.jpg","width":300,"height":169},{"@type":"BreadcrumbList","@id":"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-a-monitoramento-laboratorial-para-pacientes-em-nutria-a-o-enteral-e-parenteral\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nutritotal.com.br\/pro\/"},{"@type":"ListItem","position":2,"name":"Como deve ser a monitoramento laboratorial para pacientes em Nutri\u00e7\u00e3o Enteral e Parenteral?"}]},{"@type":"WebSite","@id":"https:\/\/nutritotal.com.br\/pro\/#website","url":"https:\/\/nutritotal.com.br\/pro\/","name":"Nutritotal PRO","description":"","publisher":{"@id":"https:\/\/nutritotal.com.br\/pro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nutritotal.com.br\/pro\/#organization","name":"Nutri Total","url":"https:\/\/nutritotal.com.br\/pro\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/","url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","contentUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","width":426,"height":426,"caption":"Nutri Total"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nutritotalPRO\/","https:\/\/www.instagram.com\/nutritotalpro\/","https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA"]},{"@type":"Person","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb","name":"Nutritotal Pro","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g","caption":"Nutritotal Pro"},"url":"https:\/\/nutritotal.com.br\/pro\/author\/perguntaserespostasimportacao\/"}]}},"views":5170,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/10495"}],"collection":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/comments?post=10495"}],"version-history":[{"count":1,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/10495\/revisions"}],"predecessor-version":[{"id":58669,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/10495\/revisions\/58669"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/media\/10494"}],"wp:attachment":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/media?parent=10495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/categories?post=10495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/tags?post=10495"},{"taxonomy":"divisao","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/divisao?post=10495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}