
{"id":10711,"date":"2016-05-27T19:44:00","date_gmt":"2016-05-27T22:44:00","guid":{"rendered":"https:\/\/nutritotal.com.br\/pro?p=10711"},"modified":"2023-05-31T15:20:42","modified_gmt":"2023-05-31T18:20:42","slug":"o-que-a-e-quais-os-benefa-cios-das-pancs","status":"publish","type":"post","link":"https:\/\/nutritotal.com.br\/pro\/o-que-a-e-quais-os-benefa-cios-das-pancs\/","title":{"rendered":"O que \u00e9 e quais os benef\u00edcios das PANCs?"},"content":{"rendered":"<div><span>PANC \u00e9 acr\u00f4nimo para plantas aliment\u00edcias n\u00e3o convencionais. S\u00e3o plantas de desenvolvimento espont\u00e2neo e facilmente encontradas em jardins, hortas, quintais e at\u00e9 mesmo em cal\u00e7adas de rua. S\u00e3o consideradas daninhas ou \u201cmato\u201d e s\u00e3o pouco utilizadas na alimenta\u00e7\u00e3o por falta de conhecimento e\/ou costume. Estudos revelam que pancs possuem teores de minerais, fibras, antioxidantes e prote\u00ednas significativamente maiores quando comparadas com plantas domesticadas.<\/span><\/div>\n<div><span>\u00a0<\/span><\/div>\n<div><span>As pancs abrangem desde plantas nativas e pouco usuais at\u00e9 ex\u00f3ticas ou silvestres com uso aliment\u00edcio direto (na forma de fruto ou verdura) e indireto (amido, f\u00e9cula ou \u00f3leo). Em geral, n\u00e3o fazem parte do card\u00e1pio di\u00e1rio da maior parte das pessoas e n\u00e3o costumam ser encontradas em mercados convencionais. Elas n\u00e3o s\u00e3o transg\u00eanicas e, na maior parte dos casos, s\u00e3o org\u00e2nicas.<\/span><\/div>\n<div><span>\u00a0<\/span><\/div>\n<div><span>Da Amaz\u00f4nia ao Rio Grande do Sul, as pancs crescem espontaneamente em qualquer ambiente. Sua alta resist\u00eancia faz com que sejam encontradas em quase todos os lugares, pois s\u00e3o nativas de cada regi\u00e3o.<\/span><\/div>\n<div><span>\u00a0<\/span><\/div>\n<div><span>Uma das mais conhecidas entre as n\u00e3o-convencionais, a <b>ora-pro-n\u00f3bis<\/b>, tamb\u00e9m chamada como carne-de-pobre, possui alto teor de prote\u00edna. \u00c9 encontrada em abund\u00e2ncia especialmente no Sudeste, mas est\u00e1 presente tamb\u00e9m em outras regi\u00f5es. Trepadeira, desenvolve-se em v\u00e1rios tipos de solo e de clima, \u00e9 de f\u00e1cil cultivo e tem alto valor nutricional. \u00c9 rica em vitaminas do complexo B, A e C, fibras e f\u00f3sforo. As folhas s\u00e3o sua parte comest\u00edvel, podendo ser consumidas secas ou frescas, cruas ou cozidas, e at\u00e9 acrescentada a massas de p\u00e3es.<\/span><\/div>\n<div><span>\u00a0<\/span><\/div>\n<div><span>A <b>bertalha<\/b> tamb\u00e9m \u00e9 trepadeira com folhas e caules verdes, carnosos e suculentos, com apar\u00eancia similar \u00e0 do espinafre. \u00c9 rica em vitamina A, al\u00e9m de oferecer outros nutrientes como vitamina C, c\u00e1lcio e ferro. As folhas e os ramos novos devem ser consumidos logo ap\u00f3s a colheita, refogados ou em substitui\u00e7\u00e3o ao espinafre e \u00e0 couve, ou em omeletes, quiches e tortas. Crua, pode ser ingerida junto a saladas verdes.<\/span><\/div>\n<div><span>\u00a0<\/span><\/div>\n<div><span>A <b>serralha<\/b> \u00e9 fonte de vitaminas A, D e E. Desenvolve-se em quase todo o mundo, podendo servir de insumo para a prepara\u00e7\u00e3o de saladas e de receitas cozidas. Seu sabor \u00e9 amargo e lembra o do espinafre.<\/span><\/div>\n<div><span>\u00a0<\/span><\/div>\n<div><span>A <b>taioba<\/b> j\u00e1 foi apreciada na culin\u00e1ria mineira, mas acabaram sendo esquecidas ou substitu\u00eddas com o passar do tempo. \u00c9 rica em vitaminas do complexo B, A, C, e em minerais como c\u00e1lcio e f\u00f3sforo. A abund\u00e2ncia de ferro faz com que a sabedoria popular lhe atribua a cura da anemia. Taioba refogada \u00e9 muito semelhante \u00e0 couve, mas n\u00e3o pode ser consumida crua devido ao alto teor de cristais de oxalato de c\u00e1lcio.<\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>PANC \u00e9 acr\u00f4nimo para plantas aliment\u00edcias n\u00e3o convencionais. S\u00e3o plantas de desenvolvimento espont\u00e2neo e facilmente encontradas em jardins, hortas, quintais e at\u00e9 mesmo em cal\u00e7adas de rua. S\u00e3o consideradas daninhas ou \u201cmato\u201d e s\u00e3o pouco utilizadas na alimenta\u00e7\u00e3o por falta de conhecimento e\/ou costume. Estudos revelam que pancs possuem teores de minerais, fibras, antioxidantes e [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"divisao":[2189,3393,2186],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>O que \u00e9 e quais os benef\u00edcios das PANCs? - Nutritotal PRO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nutritotal.com.br\/pro\/o-que-a-e-quais-os-benefa-cios-das-pancs\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que \u00e9 e quais os benef\u00edcios das PANCs? - Nutritotal PRO\" \/>\n<meta property=\"og:description\" content=\"PANC \u00e9 acr\u00f4nimo para plantas aliment\u00edcias n\u00e3o convencionais. S\u00e3o plantas de desenvolvimento espont\u00e2neo e facilmente encontradas em jardins, hortas, quintais e at\u00e9 mesmo em cal\u00e7adas de rua. S\u00e3o consideradas daninhas ou \u201cmato\u201d e s\u00e3o pouco utilizadas na alimenta\u00e7\u00e3o por falta de conhecimento e\/ou costume. Estudos revelam que pancs possuem teores de minerais, fibras, antioxidantes e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nutritotal.com.br\/pro\/o-que-a-e-quais-os-benefa-cios-das-pancs\/\" \/>\n<meta property=\"og:site_name\" content=\"Nutritotal PRO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nutritotalPRO\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-27T22:44:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-31T18:20:42+00:00\" \/>\n<meta name=\"author\" content=\"Nutritotal Pro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nutritotal Pro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/o-que-a-e-quais-os-benefa-cios-das-pancs\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/o-que-a-e-quais-os-benefa-cios-das-pancs\/\"},\"author\":{\"name\":\"Nutritotal Pro\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb\"},\"headline\":\"O que \u00e9 e quais os benef\u00edcios das PANCs?\",\"datePublished\":\"2016-05-27T22:44:00+00:00\",\"dateModified\":\"2023-05-31T18:20:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/o-que-a-e-quais-os-benefa-cios-das-pancs\/\"},\"wordCount\":477,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/nutritotal.com.br\/pro\/o-que-a-e-quais-os-benefa-cios-das-pancs\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/o-que-a-e-quais-os-benefa-cios-das-pancs\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/o-que-a-e-quais-os-benefa-cios-das-pancs\/\",\"name\":\"O que \u00e9 e quais os benef\u00edcios das PANCs? - Nutritotal PRO\",\"isPartOf\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\"},\"datePublished\":\"2016-05-27T22:44:00+00:00\",\"dateModified\":\"2023-05-31T18:20:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/o-que-a-e-quais-os-benefa-cios-das-pancs\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nutritotal.com.br\/pro\/o-que-a-e-quais-os-benefa-cios-das-pancs\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/o-que-a-e-quais-os-benefa-cios-das-pancs\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nutritotal.com.br\/pro\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O que \u00e9 e quais os benef\u00edcios das PANCs?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"name\":\"Nutritotal PRO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\",\"name\":\"Nutri Total\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"contentUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"width\":426,\"height\":426,\"caption\":\"Nutri Total\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/nutritotalPRO\/\",\"https:\/\/www.instagram.com\/nutritotalpro\/\",\"https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb\",\"name\":\"Nutritotal Pro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g\",\"caption\":\"Nutritotal Pro\"},\"url\":\"https:\/\/nutritotal.com.br\/pro\/author\/perguntaserespostasimportacao\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que \u00e9 e quais os benef\u00edcios das PANCs? - Nutritotal PRO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nutritotal.com.br\/pro\/o-que-a-e-quais-os-benefa-cios-das-pancs\/","og_locale":"pt_BR","og_type":"article","og_title":"O que \u00e9 e quais os benef\u00edcios das PANCs? - Nutritotal PRO","og_description":"PANC \u00e9 acr\u00f4nimo para plantas aliment\u00edcias n\u00e3o convencionais. S\u00e3o plantas de desenvolvimento espont\u00e2neo e facilmente encontradas em jardins, hortas, quintais e at\u00e9 mesmo em cal\u00e7adas de rua. S\u00e3o consideradas daninhas ou \u201cmato\u201d e s\u00e3o pouco utilizadas na alimenta\u00e7\u00e3o por falta de conhecimento e\/ou costume. Estudos revelam que pancs possuem teores de minerais, fibras, antioxidantes e [&hellip;]","og_url":"https:\/\/nutritotal.com.br\/pro\/o-que-a-e-quais-os-benefa-cios-das-pancs\/","og_site_name":"Nutritotal PRO","article_publisher":"https:\/\/www.facebook.com\/nutritotalPRO\/","article_published_time":"2016-05-27T22:44:00+00:00","article_modified_time":"2023-05-31T18:20:42+00:00","author":"Nutritotal Pro","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Nutritotal Pro","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nutritotal.com.br\/pro\/o-que-a-e-quais-os-benefa-cios-das-pancs\/#article","isPartOf":{"@id":"https:\/\/nutritotal.com.br\/pro\/o-que-a-e-quais-os-benefa-cios-das-pancs\/"},"author":{"name":"Nutritotal Pro","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb"},"headline":"O que \u00e9 e quais os benef\u00edcios das PANCs?","datePublished":"2016-05-27T22:44:00+00:00","dateModified":"2023-05-31T18:20:42+00:00","mainEntityOfPage":{"@id":"https:\/\/nutritotal.com.br\/pro\/o-que-a-e-quais-os-benefa-cios-das-pancs\/"},"wordCount":477,"commentCount":0,"publisher":{"@id":"https:\/\/nutritotal.com.br\/pro\/#organization"},"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nutritotal.com.br\/pro\/o-que-a-e-quais-os-benefa-cios-das-pancs\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nutritotal.com.br\/pro\/o-que-a-e-quais-os-benefa-cios-das-pancs\/","url":"https:\/\/nutritotal.com.br\/pro\/o-que-a-e-quais-os-benefa-cios-das-pancs\/","name":"O que \u00e9 e quais os benef\u00edcios das PANCs? - Nutritotal PRO","isPartOf":{"@id":"https:\/\/nutritotal.com.br\/pro\/#website"},"datePublished":"2016-05-27T22:44:00+00:00","dateModified":"2023-05-31T18:20:42+00:00","breadcrumb":{"@id":"https:\/\/nutritotal.com.br\/pro\/o-que-a-e-quais-os-benefa-cios-das-pancs\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nutritotal.com.br\/pro\/o-que-a-e-quais-os-benefa-cios-das-pancs\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nutritotal.com.br\/pro\/o-que-a-e-quais-os-benefa-cios-das-pancs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nutritotal.com.br\/pro\/"},{"@type":"ListItem","position":2,"name":"O que \u00e9 e quais os benef\u00edcios das PANCs?"}]},{"@type":"WebSite","@id":"https:\/\/nutritotal.com.br\/pro\/#website","url":"https:\/\/nutritotal.com.br\/pro\/","name":"Nutritotal PRO","description":"","publisher":{"@id":"https:\/\/nutritotal.com.br\/pro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nutritotal.com.br\/pro\/#organization","name":"Nutri Total","url":"https:\/\/nutritotal.com.br\/pro\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/","url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","contentUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","width":426,"height":426,"caption":"Nutri Total"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nutritotalPRO\/","https:\/\/www.instagram.com\/nutritotalpro\/","https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA"]},{"@type":"Person","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb","name":"Nutritotal Pro","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g","caption":"Nutritotal Pro"},"url":"https:\/\/nutritotal.com.br\/pro\/author\/perguntaserespostasimportacao\/"}]}},"views":3128,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/10711"}],"collection":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/comments?post=10711"}],"version-history":[{"count":1,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/10711\/revisions"}],"predecessor-version":[{"id":59670,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/10711\/revisions\/59670"}],"wp:attachment":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/media?parent=10711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/categories?post=10711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/tags?post=10711"},{"taxonomy":"divisao","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/divisao?post=10711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}