
{"id":10719,"date":"2022-05-30T09:00:00","date_gmt":"2022-05-30T12:00:00","guid":{"rendered":"https:\/\/nutritotal.com.br\/pro?p=10719"},"modified":"2023-05-31T15:14:45","modified_gmt":"2023-05-31T18:14:45","slug":"o-que-significa-fodmap","status":"publish","type":"post","link":"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/","title":{"rendered":"O que \u00e9 FODMAP?"},"content":{"rendered":"<p>O termo <strong>\u201cFODMAP\u201d<\/strong> se refere \u00e0 uma sigla em ingl\u00eas, que significa: <strong>oligossacar\u00eddeos, dissacar\u00eddeos, monossacar\u00eddeos e poli\u00f3is ferment\u00e1veis.<\/strong> Assim, agrupa tipos espec\u00edficos de carboidratos de cadeia curta que s\u00e3o lentamente absorvidos ou n\u00e3o digeridos no intestino delgado.<\/p>\n<div id=\"attachment_54929\" style=\"width: 1150px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-54929\" class=\"wp-image-54929 size-full\" src=\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2015\/07\/FODMAP_site.png\" alt=\"fodmap\" width=\"1140\" height=\"460\" srcset=\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2015\/07\/FODMAP_site.png 1140w, https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2015\/07\/FODMAP_site-300x121.png 300w, https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2015\/07\/FODMAP_site-1024x413.png 1024w, https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2015\/07\/FODMAP_site-768x310.png 768w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" \/><p id=\"caption-attachment-54929\" class=\"wp-caption-text\">Fonte: Shutterstock<\/p><\/div>\n<p>Os poli\u00f3is (\u201c\u00e1lcoois de a\u00e7\u00facar\u201d), apesar de n\u00e3o serem carboidratos propriamente ditos, possuem sabor adocicado e s\u00e3o utilizadas na ind\u00fastria como ado\u00e7antes artificiais.<\/p>\n<p><strong>Qual o mecanismo de a\u00e7\u00e3o dos FODMAP\u2019s no organismo?<\/strong><\/p>\n<p>Quando fermentados pelos microrganismos que habitam o intestino grosso, os FODMAPs levam \u00e0 uma <strong>maior produ\u00e7\u00e3o de gases<\/strong>, como hidrog\u00eanio, metano e di\u00f3xido de carbono.<\/p>\n<p>Al\u00e9m disso, tamb\u00e9m apresentam grande capacidade de atrair \u00e1gua no trato gastrintestinal, atrav\u00e9s de um <strong>efeito osm\u00f3tico<\/strong> que gera a <strong>distens\u00e3o luminal<\/strong>.<\/p>\n<p>O consumo de FODMAPs tamb\u00e9m eleva a produ\u00e7\u00e3o de \u00e1cidos graxos de cadeia curta (AGCCs), como propianato, butirato e acetato, que geralmente exibem muitos efeitos ben\u00e9ficos. No entanto, a produ\u00e7\u00e3o excessiva <strong>pode aumentar a sensibilidade visceral<\/strong> e favorecer o aparecimento de contra\u00e7\u00f5es col\u00f4nicas.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>FODMAPs nos alimentos<\/strong><\/p>\n<p>Na tabela abaixo, est\u00e3o exemplificados alimentos com altos teores de FODMAPs, al\u00e9m de alternativas com baixos n\u00edveis desses carboidratos.<\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"132\"><\/td>\n<td width=\"208\"><strong>Alimentos com altos teores de FODMAPs<\/strong><\/td>\n<td width=\"226\"><strong>Alimentos com baixos teores de FODMAPs<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"132\"><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Frutas<\/strong><\/p>\n<p>&nbsp;<\/td>\n<td width=\"208\">Abacate, amora, ameixa, caqui, cereja, damasco, figo, ma\u00e7\u00e3, manga, melancia, nectarina, pera, p\u00eassego, sucos de fruta<\/td>\n<td width=\"226\">Abacaxi, banana, carambola, coco, framboesa, kiwi, laranja, lim\u00e3o, mam\u00e3o, maracuj\u00e1, mel\u00e3o, mirtilo, morango, tangerina, uva<\/td>\n<\/tr>\n<tr>\n<td width=\"132\"><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Legumes e vegetais<\/strong><\/p>\n<p>&nbsp;<\/td>\n<td width=\"208\">&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Aspargo, alcachofra, alho, beterraba, cebola, chic\u00f3ria, cogumelo, couve-flor, ervilha, milho, quiabo, vagem<\/p>\n<p>&nbsp;<\/td>\n<td width=\"226\">Abobrinha, ab\u00f3bora, acelga, alface, alho-por\u00f3, azeitona, batata, berinjela, broto de alfafa, broto de feij\u00e3o, cebolinha (parte verde), cenoura, couve, erva-doce, espinafre, feij\u00e3o-verde, gengibre, mandioca, nabo, pepino, pimenta, piment\u00e3o, tomate<\/td>\n<\/tr>\n<tr>\n<td width=\"132\"><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Gr\u00e3os, sementes e cereais<\/strong><\/p>\n<p>&nbsp;<\/td>\n<td width=\"208\">&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Centeio, cevada, cuscuz, feij\u00e3o, soja, trigo<\/p>\n<p>&nbsp;<\/td>\n<td width=\"226\">Aveia, arroz, chia, gergelim, gr\u00e3o de bico enlatado, lentilhas enlatadas, milho, pain\u00e7o, p\u00e3o de milho, produtos sem gl\u00faten (p\u00e3o, farinhas, massas), polenta, quinoa, sementes de ab\u00f3bora, semente de girassol, tapioca, tempeh, tofu<\/p>\n<p>&nbsp;<\/td>\n<\/tr>\n<tr>\n<td width=\"132\"><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Queijos e l\u00e1cteos<\/strong><\/p>\n<p>&nbsp;<\/td>\n<td width=\"208\">Cream chesse, coalhada, iogurte, leite condensado, leite (vaca, cabra, ovelha), nata, pudim, queijo cottage, queijo fresco, ricota, sorvete<\/p>\n<p>&nbsp;<\/td>\n<td width=\"226\">Brie, camembert, cheddar, feta, manteiga, leite e iogurte sem lactose, mu\u00e7arela, parmes\u00e3o, queijo de trigo, queijo su\u00ed\u00e7o<\/p>\n<p>&nbsp;<\/td>\n<\/tr>\n<tr>\n<td width=\"132\"><strong>\u00a0<\/strong><\/p>\n<p><strong>Castanhas e nozes<\/strong><\/p>\n<p>&nbsp;<\/td>\n<td width=\"208\">&nbsp;<\/p>\n<p>Castanha de caju, pistache<\/p>\n<p>&nbsp;<\/td>\n<td width=\"226\">Amendoim, macad\u00e2mia, manteiga de amendoim, nozes, pinh\u00e3o<\/p>\n<p>&nbsp;<\/td>\n<\/tr>\n<tr>\n<td width=\"132\"><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Condimentos e ado\u00e7antes<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/td>\n<td width=\"208\">&nbsp;<\/p>\n<p>Alho, cebola, condimentos com trigo, frutose, ketchup, maionese, manitol, massa de tomate, mel, molho japon\u00eas, mostarda, sorbitol, xarope de milho rico em frutose, xilitol<\/p>\n<p>&nbsp;<\/td>\n<td width=\"226\">A\u00e7\u00facar comum, aspartame, est\u00e9via, glicose, mela\u00e7o, molho de ostra, molho de peixe, molho de soja sem gl\u00faten, n\u00e9ctar, \u00f3leos, suco de lim\u00e3o, vinagre (de champanhe, vinho tinto ou vinho branco), xarope de bordo, de frutose dourada e de milho dourado<\/p>\n<p>&nbsp;<\/td>\n<\/tr>\n<tr>\n<td width=\"132\"><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Temperos e ervas<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/td>\n<td width=\"208\">&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Alho e cebola em p\u00f3<\/p>\n<p>&nbsp;<\/td>\n<td width=\"226\">A\u00e7afr\u00e3o, alecrim, coentro, gengibre, hortel\u00e3, louro, manjeric\u00e3o, or\u00e9gano, p\u00e1prica, pimenta, pimenta caiena, pimenta vermelha em p\u00f3, sal, salsa, semente de mostarda, tomilho<\/p>\n<p>&nbsp;<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>Vale ressaltar que a composi\u00e7\u00e3o dos FODMAPs \u00e9 afetada por t\u00e9cnicas de processamentos de alimentos. Processos que envolvem aquecimento e \u00e1gua podem reduzir os teores de FODMAPs sol\u00faveis em \u00e1gua (como frutanos e GOS).<\/p>\n<p>As por\u00e7\u00f5es tamb\u00e9m devem ser consideradas, pois uma ingest\u00e3o excessiva de alimentos considerado \u201cpobres\u201d em FODMAPs pode aumentar o seu conte\u00fado na dieta.<\/p>\n<p>Ademais, os produtos sem gl\u00faten costumam ter baixo teor de FODMAPs, exceto se contiverem mel ou ado\u00e7antes a base de frutose ou poli\u00f3is.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Como \u00e9 a dieta Low FODMAPs?<\/strong><\/p>\n<p>A dieta baixa em FODMAP foi criada na Austr\u00e1lia em 1999 para tratar pacientes com <a href=\"https:\/\/nutritotal.com.br\/pro\/fodmaps-e-gluten-quais-sao-os-efeitos-sobre-os-sintomas-de-sii\/\"><strong>S\u00edndrome do Intestino Irrit\u00e1vel<\/strong><\/a> <strong>(SII)<\/strong>. Ela inclui a redu\u00e7\u00e3o da ingest\u00e3o alimentar dos 5 principais subgrupos de carboidratos:<\/p>\n<ul>\n<li><strong>Frutose com excesso de glicose;<\/strong><\/li>\n<li><strong>Lactose;<\/strong><\/li>\n<li><strong>Poli\u00f3is de a\u00e7\u00facar<\/strong> (como sorbitol e manitol);<\/li>\n<li><strong>Frutanos;<\/strong><\/li>\n<li><strong>Galactooligossacar\u00eddeos (GOS).<\/strong><\/li>\n<\/ul>\n<p>O objetivo da dieta baixa em FODMAP \u00e9 <strong>ajudar os pacientes a controlar seus sintomas<\/strong> e, posteriormente, identificar os desencadeadores alimentares espec\u00edficos. A dieta consiste num processo de tr\u00eas etapas:<\/p>\n<ul>\n<li><strong>Elimina\u00e7\u00e3o (fase inicial)<\/strong> \u2013 Os pacientes devem ser educados sobre formas de reduzir os alimentos ricos em FODMAP na dieta, geralmente por um per\u00edodo de 2 a 8 semanas. O objetivo \u00e9 melhorar os sintomas.<\/li>\n<li><strong>Determina\u00e7\u00e3o das sensibilidades (fase de nova provoca\u00e7\u00e3o)<\/strong> \u2013 Introdu\u00e7\u00e3o gradual de FODMAPs na dieta para determinar o tipo e quantidade que podem ser tolerados antes de sentir sintomas. O objetivo \u00e9 identificar os alimentos desencadeadores espec\u00edficos para o indiv\u00edduo.<\/li>\n<li><strong>Personaliza\u00e7\u00e3o (fase de manuten\u00e7\u00e3o) <\/strong>&#8211; Reintrodu\u00e7\u00e3o m\u00e1xima de FODMAPs na dieta conforme tolerado, mantendo um bom controle dos sintomas. Alimentos que s\u00e3o moderadamente tolerados podem ser reintroduzidos ocasionalmente, enquanto alimentos que s\u00e3o mal tolerados devem continuar sendo evitados.<\/li>\n<\/ul>\n<p>Com essa abordagem, baseada em restri\u00e7\u00f5es diet\u00e9ticas personalizadas demonstradas pela toler\u00e2ncia do paciente, \u00e9 mais prov\u00e1vel que sejam compensados os efeitos adversos da dieta (inadequa\u00e7\u00e3o nutricional, constipa\u00e7\u00e3o, redu\u00e7\u00e3o da fibra alimentar, etc).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Redu\u00e7\u00e3o dos FODMAPs no tratamento de doen\u00e7as<\/strong><\/p>\n<p>Como visto, a redu\u00e7\u00e3o de FODMAPs \u00e9 considerada uma abordagem diet\u00e9tica eficaz em adultos com <a href=\"https:\/\/nutritotal.com.br\/pro\/fodmaps-e-gluten-quais-sao-os-efeitos-sobre-os-sintomas-de-sii\/\">S\u00edndrome do Intestino Irrit\u00e1vel<\/a> (SII), principalmente quando os sintomas persistem apesar das mudan\u00e7as de estilo de vida e outros aconselhamentos diet\u00e9ticos. Essa estrat\u00e9gia promove um al\u00edvio significativo dos sintomas em compara\u00e7\u00e3o \u00e0 outras dietas.<\/p>\n<p>Alguns estudos sugerem ainda que a <strong>redu\u00e7\u00e3o de FODMAPs na dieta pode beneficiar outras condi\u00e7\u00f5es<\/strong>, como: doen\u00e7a cel\u00edaca, <a href=\"https:\/\/nutritotal.com.br\/pro\/ingestao-de-gluten-e-sindrome-do-intestino-irritavel\/\">sensibilidade o gl\u00faten n\u00e3o cel\u00edaca<\/a>, endometriose, <a href=\"https:\/\/nutritotal.com.br\/pro\/dieta-materna-pobre-em-fodmaps-melhora-ca-lica-infantil\/\">c\u00f3lica infantil<\/a>, dispepsia funcional, <a href=\"https:\/\/nutritotal.com.br\/pro\/dieta-pobre-em-fodmaps-pode-trazer-benefa-cios-para-pacientes-com-fibromialgia\/\">fibromialgia<\/a>, esclerodermia, s\u00edndrome da fadiga cr\u00f4nica, <a href=\"https:\/\/nutritotal.com.br\/pro\/recomendacoes-nutricionais-na-doenca-de-crohn\/\">doen\u00e7a de Crohn<\/a> e colite ulcerativa. Contudo, mais pesquisas ainda s\u00e3o necess\u00e1rias.<\/p>\n<p>Por fim, a orienta\u00e7\u00e3o de um m\u00e9dico e de um nutricionista \u00e9 essencial para o diagn\u00f3stico e o tratamento correto.<\/p>\n<p>&nbsp;<\/p>\n<h3><a href=\"https:\/\/nutritotal.com.br\/publico-geral\/material\/receita-low-fodmap-rolinho-de-camarao-oriental\/\" target=\"_blank\" rel=\"noopener\">Clique aqui<\/a> para conferir uma receita com baixo teor de FODMAPs.<\/h3>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Refer\u00eancias<\/strong>:<\/p>\n<p>BELLINI, Massimo et al. <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/32784614\/#:~:text=A%20Low-FODMAP%20Diet%20for%20Irritable%20Bowel%20Syndrome%3A%20Some,a%20possible%20therapy%20for%20irritable%20bowel%20syndrome%20%28IBS%29.\">A Low-FODMAP Diet for Irritable Bowel Syndrome: Some Answers to the Doubts from a Long-Term Follow-Up<\/a>.\u00a0<strong>Nutrients<\/strong>, v. 12, n. 8, p. 2360, 2020.<\/p>\n<p>BELLINI, Massimo et al. <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/31947991\/#:~:text=Low%20FODMAP%20Diet%3A%20Evidence%2C%20Doubts%2C%20and%20Hopes%20Food,which%20can%20be%20found%20in%20many%20common%20foods.\">Low FODMAP Diet: Evidence, Doubts, and Hopes<\/a>.\u00a0<strong>Nutrients<\/strong>, v. 12, n. 1, p. 148, 2020.<\/p>\n<p>Hospital Bras\u00edlia. <a href=\"https:\/\/hospitalbrasilia.com.br\/pt\/pacientes-e-visitantes-site\/Documents\/NEDIC\/CARTILHA%205%20DIETA%20COM%20RESTRIC%CC%A7A%CC%83O%20DE%20FODMAP_DUAS%20DOBRAS.pdf\" class=\"broken_link\">Cartilha: Dieta com Restri\u00e7\u00e3o de FODMAP<\/a>. N\u00facleo Especializado em Doen\u00e7as Intestinais Complexas (NEDIC).<\/p>\n<p>MAKHARIA, Govind et al. <a href=\"https:\/\/www.worldgastroenterology.org\/guidelines\/diet-and-the-gut\/diet-and-the-gut-portuguese\">Dieta e intestino<\/a>. World Gastroenterology Organisation, 2018.<\/p>\n<p>PENSABENE, Licia et al. <a href=\"https:\/\/www.scielo.br\/j\/jped\/a\/x67Hrj8Fh8YdffnM8FYVjpc\/\" class=\"broken_link\">Low FODMAPs diet for functional abdominal pain disorders in children: critical review of current knowledge<\/a>.\u00a0<strong>Jornal de pediatria<\/strong>, v. 95, p. 642-656, 2019.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O termo \u201cFODMAP\u201d se refere \u00e0 uma sigla em ingl\u00eas, que significa: oligossacar\u00eddeos, dissacar\u00eddeos, monossacar\u00eddeos e poli\u00f3is ferment\u00e1veis. Assim, agrupa tipos espec\u00edficos de carboidratos de cadeia curta que s\u00e3o lentamente absorvidos ou n\u00e3o digeridos no intestino delgado. Os poli\u00f3is (\u201c\u00e1lcoois de a\u00e7\u00facar\u201d), apesar de n\u00e3o serem carboidratos propriamente ditos, possuem sabor adocicado e s\u00e3o utilizadas [&hellip;]<\/p>\n","protected":false},"author":114981,"featured_media":54930,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[404,782],"divisao":[3393,2185,2186],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>O que \u00e9 FODMAP? - Nutritotal PRO<\/title>\n<meta name=\"description\" content=\"O termo \u201cFODMAP\u201d \u00e9 frequentemente citado na m\u00eddia e em estudos cient\u00edficos. Mas voc\u00ea sabe o que ele realmente significa? Descubra!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que \u00e9 FODMAP? - Nutritotal PRO\" \/>\n<meta property=\"og:description\" content=\"O termo \u201cFODMAP\u201d \u00e9 frequentemente citado na m\u00eddia e em estudos cient\u00edficos. Mas voc\u00ea sabe o que ele realmente significa? Descubra!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/\" \/>\n<meta property=\"og:site_name\" content=\"Nutritotal PRO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nutritotalPRO\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/nutritotalPRO\/?ref=pages_you_manage&amp;_rdc=1&amp;_rdr\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-30T12:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-31T18:14:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2015\/07\/FODMAP_destacada.png\" \/>\n\t<meta property=\"og:image:width\" content=\"582\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Nutritotal PRO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Nutritotal PRO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Nutritotal PRO\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/ebc724f6275a533739e9d1ad603f21a2\"},\"headline\":\"O que \u00e9 FODMAP?\",\"datePublished\":\"2022-05-30T12:00:00+00:00\",\"dateModified\":\"2023-05-31T18:14:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/\"},\"wordCount\":1161,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2015\/07\/FODMAP_destacada.png\",\"keywords\":[\"carboidratos\",\"S\u00edndrome do Intestino Irrit\u00e1vel\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/\",\"name\":\"O que \u00e9 FODMAP? - Nutritotal PRO\",\"isPartOf\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2015\/07\/FODMAP_destacada.png\",\"datePublished\":\"2022-05-30T12:00:00+00:00\",\"dateModified\":\"2023-05-31T18:14:45+00:00\",\"description\":\"O termo \u201cFODMAP\u201d \u00e9 frequentemente citado na m\u00eddia e em estudos cient\u00edficos. Mas voc\u00ea sabe o que ele realmente significa? Descubra!\",\"breadcrumb\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/#primaryimage\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2015\/07\/FODMAP_destacada.png\",\"contentUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2015\/07\/FODMAP_destacada.png\",\"width\":582,\"height\":400,\"caption\":\"fodmap\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nutritotal.com.br\/pro\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O que \u00e9 FODMAP?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"name\":\"Nutritotal PRO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\",\"name\":\"Nutri Total\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"contentUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"width\":426,\"height\":426,\"caption\":\"Nutri Total\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/nutritotalPRO\/\",\"https:\/\/www.instagram.com\/nutritotalpro\/\",\"https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/ebc724f6275a533739e9d1ad603f21a2\",\"name\":\"Reda\u00e7\u00e3o Nutritotal PRO\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0b28a44567fd9e96213e21d1d40eeb15?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0b28a44567fd9e96213e21d1d40eeb15?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o Nutritotal PRO\"},\"description\":\"A Reda\u00e7\u00e3o Nutritotal PRO \u00e9 formada por nutricionistas, m\u00e9dicos e estudantes de nutri\u00e7\u00e3o que t\u00eam a preocupa\u00e7\u00e3o de produzir conte\u00fados atuais, baseados em evid\u00eancia cient\u00edficas, sempre com o objetivo de facilitar a pr\u00e1tica cl\u00ednica de profissionais da \u00e1rea da sa\u00fade.\",\"sameAs\":[\"https:\/\/www.facebook.com\/nutritotalPRO\/?ref=pages_you_manage&_rdc=1&_rdr\",\"https:\/\/www.instagram.com\/nutritotalpro\/?utm_medium=copy_link\",\"https:\/\/www.linkedin.com\/company\/nutritotal-pro\/?viewAsMember=true\",\"https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA\"],\"url\":\"https:\/\/nutritotal.com.br\/pro\/author\/nutritotal\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que \u00e9 FODMAP? - Nutritotal PRO","description":"O termo \u201cFODMAP\u201d \u00e9 frequentemente citado na m\u00eddia e em estudos cient\u00edficos. Mas voc\u00ea sabe o que ele realmente significa? Descubra!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/","og_locale":"pt_BR","og_type":"article","og_title":"O que \u00e9 FODMAP? - Nutritotal PRO","og_description":"O termo \u201cFODMAP\u201d \u00e9 frequentemente citado na m\u00eddia e em estudos cient\u00edficos. Mas voc\u00ea sabe o que ele realmente significa? Descubra!","og_url":"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/","og_site_name":"Nutritotal PRO","article_publisher":"https:\/\/www.facebook.com\/nutritotalPRO\/","article_author":"https:\/\/www.facebook.com\/nutritotalPRO\/?ref=pages_you_manage&_rdc=1&_rdr","article_published_time":"2022-05-30T12:00:00+00:00","article_modified_time":"2023-05-31T18:14:45+00:00","og_image":[{"width":582,"height":400,"url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2015\/07\/FODMAP_destacada.png","type":"image\/png"}],"author":"Reda\u00e7\u00e3o Nutritotal PRO","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Nutritotal PRO","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/#article","isPartOf":{"@id":"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/"},"author":{"name":"Reda\u00e7\u00e3o Nutritotal PRO","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/ebc724f6275a533739e9d1ad603f21a2"},"headline":"O que \u00e9 FODMAP?","datePublished":"2022-05-30T12:00:00+00:00","dateModified":"2023-05-31T18:14:45+00:00","mainEntityOfPage":{"@id":"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/"},"wordCount":1161,"commentCount":0,"publisher":{"@id":"https:\/\/nutritotal.com.br\/pro\/#organization"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/#primaryimage"},"thumbnailUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2015\/07\/FODMAP_destacada.png","keywords":["carboidratos","S\u00edndrome do Intestino Irrit\u00e1vel"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/","url":"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/","name":"O que \u00e9 FODMAP? - Nutritotal PRO","isPartOf":{"@id":"https:\/\/nutritotal.com.br\/pro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/#primaryimage"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/#primaryimage"},"thumbnailUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2015\/07\/FODMAP_destacada.png","datePublished":"2022-05-30T12:00:00+00:00","dateModified":"2023-05-31T18:14:45+00:00","description":"O termo \u201cFODMAP\u201d \u00e9 frequentemente citado na m\u00eddia e em estudos cient\u00edficos. Mas voc\u00ea sabe o que ele realmente significa? Descubra!","breadcrumb":{"@id":"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/#primaryimage","url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2015\/07\/FODMAP_destacada.png","contentUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2015\/07\/FODMAP_destacada.png","width":582,"height":400,"caption":"fodmap"},{"@type":"BreadcrumbList","@id":"https:\/\/nutritotal.com.br\/pro\/o-que-significa-fodmap\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nutritotal.com.br\/pro\/"},{"@type":"ListItem","position":2,"name":"O que \u00e9 FODMAP?"}]},{"@type":"WebSite","@id":"https:\/\/nutritotal.com.br\/pro\/#website","url":"https:\/\/nutritotal.com.br\/pro\/","name":"Nutritotal PRO","description":"","publisher":{"@id":"https:\/\/nutritotal.com.br\/pro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nutritotal.com.br\/pro\/#organization","name":"Nutri Total","url":"https:\/\/nutritotal.com.br\/pro\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/","url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","contentUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","width":426,"height":426,"caption":"Nutri Total"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nutritotalPRO\/","https:\/\/www.instagram.com\/nutritotalpro\/","https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA"]},{"@type":"Person","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/ebc724f6275a533739e9d1ad603f21a2","name":"Reda\u00e7\u00e3o Nutritotal PRO","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0b28a44567fd9e96213e21d1d40eeb15?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0b28a44567fd9e96213e21d1d40eeb15?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o Nutritotal PRO"},"description":"A Reda\u00e7\u00e3o Nutritotal PRO \u00e9 formada por nutricionistas, m\u00e9dicos e estudantes de nutri\u00e7\u00e3o que t\u00eam a preocupa\u00e7\u00e3o de produzir conte\u00fados atuais, baseados em evid\u00eancia cient\u00edficas, sempre com o objetivo de facilitar a pr\u00e1tica cl\u00ednica de profissionais da \u00e1rea da sa\u00fade.","sameAs":["https:\/\/www.facebook.com\/nutritotalPRO\/?ref=pages_you_manage&_rdc=1&_rdr","https:\/\/www.instagram.com\/nutritotalpro\/?utm_medium=copy_link","https:\/\/www.linkedin.com\/company\/nutritotal-pro\/?viewAsMember=true","https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA"],"url":"https:\/\/nutritotal.com.br\/pro\/author\/nutritotal\/"}]}},"views":158726,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/10719"}],"collection":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/users\/114981"}],"replies":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/comments?post=10719"}],"version-history":[{"count":1,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/10719\/revisions"}],"predecessor-version":[{"id":58095,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/10719\/revisions\/58095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/media\/54930"}],"wp:attachment":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/media?parent=10719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/categories?post=10719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/tags?post=10719"},{"taxonomy":"divisao","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/divisao?post=10719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}