
{"id":10727,"date":"2016-01-22T21:29:00","date_gmt":"2016-01-22T23:29:00","guid":{"rendered":"https:\/\/nutritotal.com.br\/pro?p=10727"},"modified":"2023-05-31T15:21:18","modified_gmt":"2023-05-31T18:21:18","slug":"qual-a-diferena-a-entre-alimentos-minimamente-processados-processados-e-ultra-processados","status":"publish","type":"post","link":"https:\/\/nutritotal.com.br\/pro\/qual-a-diferena-a-entre-alimentos-minimamente-processados-processados-e-ultra-processados\/","title":{"rendered":"Qual a diferen\u00e7a entre alimentos minimamente processados, processados e ultra processados?"},"content":{"rendered":"<div>\n<div><span>Segundo estudos sobre aquisi\u00e7\u00e3o domiciliar de alimentos utilizando dados de pesquisas de or\u00e7amentos familiares foi demonstrado que, em m\u00e9dia, alimentos ultra processados possuem maior densidade energ\u00e9tica, maior teor de a\u00e7\u00facar livre e menor teor de fibra que os alimentos <i>in natura<\/i> ou aqueles minimamente processados, mesmo quando se considera a combina\u00e7\u00e3o desses alimentos com ingredientes culin\u00e1rios como sal, a\u00e7\u00facar e gorduras.<\/span><\/div>\n<div><span>\u00a0<\/span><\/div>\n<div><span>De acordo com o Guia Alimentar para a Popula\u00e7\u00e3o Brasileira, existem quatro categorias de alimentos definidas de acordo com o tipo de processamento empregado na sua produ\u00e7\u00e3o.<\/span><\/div>\n<div><span>\u00a0<\/span><\/div>\n<div><span>A primeira re\u00fane alimentos <i>in natura<\/i> ou minimamente processados. Alimentos <i>in natura<\/i> s\u00e3o aqueles obtidos diretamente de plantas ou de animais e adquiridos para consumo sem que tenham sofrido qualquer altera\u00e7\u00e3o ap\u00f3s deixarem a natureza.<\/span><\/div>\n<div><span>\u00a0<\/span><\/div>\n<div><span>A aquisi\u00e7\u00e3o de alimentos <i>in natura <\/i>\u00e9 limitada a algumas variedades como frutas, legumes, verduras, ra\u00edzes, tub\u00e9rculos e ovos. E, ainda assim, \u00e9 comum que mesmo esses alimentos sofram alguma altera\u00e7\u00e3o antes de serem adquiridos, como limpeza, remo\u00e7\u00e3o de partes n\u00e3o comest\u00edveis e refrigera\u00e7\u00e3o. Limpeza, remo\u00e7\u00e3o de partes n\u00e3o comest\u00edveis, secagem, embalagem, pasteuriza\u00e7\u00e3o, resfriamento, congelamento, moagem e fermenta\u00e7\u00e3o s\u00e3o exemplos de processos m\u00ednimos que transformam alimentos<i> in natura<\/i> em minimamente processados. No processamento m\u00ednimo n\u00e3o h\u00e1 adi\u00e7\u00e3o de sal, a\u00e7\u00facar, \u00f3leos, gorduras ou outras subst\u00e2ncias ao alimento.\u00a0<\/span><\/div>\n<div><span>\u00a0<\/span><\/div>\n<div><span>A segunda categoria corresponde a produtos extra\u00eddos de alimentos<i> in natura<\/i> ou diretamente da natureza e usados pelas pessoas para temperar e cozinhar alimentos e criar prepara\u00e7\u00f5es culin\u00e1rias. Exemplos desses produtos s\u00e3o: \u00f3leos, gorduras, a\u00e7\u00facar e sal. Esses alimentos ainda s\u00e3o considerados minimamente processados.<\/span><\/div>\n<div><span>\u00a0<\/span><\/div>\n<div><span>A terceira categoria corresponde a produtos fabricados essencialmente com a adi\u00e7\u00e3o de sal ou a\u00e7\u00facar a um alimento <i>in natura <\/i>ou minimamente processado, como legumes em conserva, frutas em calda, queijos e p\u00e3es. Esses s\u00e3o os alimentos processados.<\/span><\/div>\n<div><span>\u00a0<\/span><\/div>\n<div><span>A quarta categoria, \u00e9 a de alimentos ultra processados, que s\u00e3o formula\u00e7\u00f5es industriais prontas para consumo e feitas inteiramente ou majoritariamente de subst\u00e2ncias extra\u00eddas de alimentos (\u00f3leos, gorduras, a\u00e7\u00facar, prote\u00ednas), derivadas de constituintes de alimentos (gorduras hidrogenadas, amido modificado) ou sintetizadas em laborat\u00f3rio com base em mat\u00e9rias org\u00e2nicas (corantes, aromatizantes, real\u00e7adores de sabor e outros aditivos usados para alterar propriedades sensoriais). Alguns exemplos incluem refrigerantes, biscoitos recheados, salgadinhos de pacote e macarr\u00e3o instant\u00e2neo.<\/span><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Segundo estudos sobre aquisi\u00e7\u00e3o domiciliar de alimentos utilizando dados de pesquisas de or\u00e7amentos familiares foi demonstrado que, em m\u00e9dia, alimentos ultra processados possuem maior densidade energ\u00e9tica, maior teor de a\u00e7\u00facar livre e menor teor de fibra que os alimentos in natura ou aqueles minimamente processados, mesmo quando se considera a combina\u00e7\u00e3o desses alimentos com ingredientes [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"divisao":[3393,2186,2194],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qual a diferen\u00e7a entre alimentos minimamente processados, processados e ultra processados? - Nutritotal PRO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nutritotal.com.br\/pro\/qual-a-diferena-a-entre-alimentos-minimamente-processados-processados-e-ultra-processados\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qual a diferen\u00e7a entre alimentos minimamente processados, processados e ultra processados? - Nutritotal PRO\" \/>\n<meta property=\"og:description\" content=\"Segundo estudos sobre aquisi\u00e7\u00e3o domiciliar de alimentos utilizando dados de pesquisas de or\u00e7amentos familiares foi demonstrado que, em m\u00e9dia, alimentos ultra processados possuem maior densidade energ\u00e9tica, maior teor de a\u00e7\u00facar livre e menor teor de fibra que os alimentos in natura ou aqueles minimamente processados, mesmo quando se considera a combina\u00e7\u00e3o desses alimentos com ingredientes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nutritotal.com.br\/pro\/qual-a-diferena-a-entre-alimentos-minimamente-processados-processados-e-ultra-processados\/\" \/>\n<meta property=\"og:site_name\" content=\"Nutritotal PRO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nutritotalPRO\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-22T23:29:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-31T18:21:18+00:00\" \/>\n<meta name=\"author\" content=\"Nutritotal Pro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nutritotal Pro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/qual-a-diferena-a-entre-alimentos-minimamente-processados-processados-e-ultra-processados\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/qual-a-diferena-a-entre-alimentos-minimamente-processados-processados-e-ultra-processados\/\"},\"author\":{\"name\":\"Nutritotal Pro\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb\"},\"headline\":\"Qual a diferen\u00e7a entre alimentos minimamente processados, processados e ultra processados?\",\"datePublished\":\"2016-01-22T23:29:00+00:00\",\"dateModified\":\"2023-05-31T18:21:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/qual-a-diferena-a-entre-alimentos-minimamente-processados-processados-e-ultra-processados\/\"},\"wordCount\":430,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/nutritotal.com.br\/pro\/qual-a-diferena-a-entre-alimentos-minimamente-processados-processados-e-ultra-processados\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/qual-a-diferena-a-entre-alimentos-minimamente-processados-processados-e-ultra-processados\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/qual-a-diferena-a-entre-alimentos-minimamente-processados-processados-e-ultra-processados\/\",\"name\":\"Qual a diferen\u00e7a entre alimentos minimamente processados, processados e ultra processados? - Nutritotal PRO\",\"isPartOf\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\"},\"datePublished\":\"2016-01-22T23:29:00+00:00\",\"dateModified\":\"2023-05-31T18:21:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/qual-a-diferena-a-entre-alimentos-minimamente-processados-processados-e-ultra-processados\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nutritotal.com.br\/pro\/qual-a-diferena-a-entre-alimentos-minimamente-processados-processados-e-ultra-processados\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/qual-a-diferena-a-entre-alimentos-minimamente-processados-processados-e-ultra-processados\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nutritotal.com.br\/pro\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qual a diferen\u00e7a entre alimentos minimamente processados, processados e ultra processados?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"name\":\"Nutritotal PRO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\",\"name\":\"Nutri Total\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"contentUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"width\":426,\"height\":426,\"caption\":\"Nutri Total\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/nutritotalPRO\/\",\"https:\/\/www.instagram.com\/nutritotalpro\/\",\"https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb\",\"name\":\"Nutritotal Pro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g\",\"caption\":\"Nutritotal Pro\"},\"url\":\"https:\/\/nutritotal.com.br\/pro\/author\/perguntaserespostasimportacao\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qual a diferen\u00e7a entre alimentos minimamente processados, processados e ultra processados? - Nutritotal PRO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nutritotal.com.br\/pro\/qual-a-diferena-a-entre-alimentos-minimamente-processados-processados-e-ultra-processados\/","og_locale":"pt_BR","og_type":"article","og_title":"Qual a diferen\u00e7a entre alimentos minimamente processados, processados e ultra processados? - Nutritotal PRO","og_description":"Segundo estudos sobre aquisi\u00e7\u00e3o domiciliar de alimentos utilizando dados de pesquisas de or\u00e7amentos familiares foi demonstrado que, em m\u00e9dia, alimentos ultra processados possuem maior densidade energ\u00e9tica, maior teor de a\u00e7\u00facar livre e menor teor de fibra que os alimentos in natura ou aqueles minimamente processados, mesmo quando se considera a combina\u00e7\u00e3o desses alimentos com ingredientes [&hellip;]","og_url":"https:\/\/nutritotal.com.br\/pro\/qual-a-diferena-a-entre-alimentos-minimamente-processados-processados-e-ultra-processados\/","og_site_name":"Nutritotal PRO","article_publisher":"https:\/\/www.facebook.com\/nutritotalPRO\/","article_published_time":"2016-01-22T23:29:00+00:00","article_modified_time":"2023-05-31T18:21:18+00:00","author":"Nutritotal Pro","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Nutritotal Pro","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nutritotal.com.br\/pro\/qual-a-diferena-a-entre-alimentos-minimamente-processados-processados-e-ultra-processados\/#article","isPartOf":{"@id":"https:\/\/nutritotal.com.br\/pro\/qual-a-diferena-a-entre-alimentos-minimamente-processados-processados-e-ultra-processados\/"},"author":{"name":"Nutritotal Pro","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb"},"headline":"Qual a diferen\u00e7a entre alimentos minimamente processados, processados e ultra processados?","datePublished":"2016-01-22T23:29:00+00:00","dateModified":"2023-05-31T18:21:18+00:00","mainEntityOfPage":{"@id":"https:\/\/nutritotal.com.br\/pro\/qual-a-diferena-a-entre-alimentos-minimamente-processados-processados-e-ultra-processados\/"},"wordCount":430,"commentCount":0,"publisher":{"@id":"https:\/\/nutritotal.com.br\/pro\/#organization"},"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nutritotal.com.br\/pro\/qual-a-diferena-a-entre-alimentos-minimamente-processados-processados-e-ultra-processados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nutritotal.com.br\/pro\/qual-a-diferena-a-entre-alimentos-minimamente-processados-processados-e-ultra-processados\/","url":"https:\/\/nutritotal.com.br\/pro\/qual-a-diferena-a-entre-alimentos-minimamente-processados-processados-e-ultra-processados\/","name":"Qual a diferen\u00e7a entre alimentos minimamente processados, processados e ultra processados? - Nutritotal PRO","isPartOf":{"@id":"https:\/\/nutritotal.com.br\/pro\/#website"},"datePublished":"2016-01-22T23:29:00+00:00","dateModified":"2023-05-31T18:21:18+00:00","breadcrumb":{"@id":"https:\/\/nutritotal.com.br\/pro\/qual-a-diferena-a-entre-alimentos-minimamente-processados-processados-e-ultra-processados\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nutritotal.com.br\/pro\/qual-a-diferena-a-entre-alimentos-minimamente-processados-processados-e-ultra-processados\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nutritotal.com.br\/pro\/qual-a-diferena-a-entre-alimentos-minimamente-processados-processados-e-ultra-processados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nutritotal.com.br\/pro\/"},{"@type":"ListItem","position":2,"name":"Qual a diferen\u00e7a entre alimentos minimamente processados, processados e ultra processados?"}]},{"@type":"WebSite","@id":"https:\/\/nutritotal.com.br\/pro\/#website","url":"https:\/\/nutritotal.com.br\/pro\/","name":"Nutritotal PRO","description":"","publisher":{"@id":"https:\/\/nutritotal.com.br\/pro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nutritotal.com.br\/pro\/#organization","name":"Nutri Total","url":"https:\/\/nutritotal.com.br\/pro\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/","url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","contentUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","width":426,"height":426,"caption":"Nutri Total"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nutritotalPRO\/","https:\/\/www.instagram.com\/nutritotalpro\/","https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA"]},{"@type":"Person","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb","name":"Nutritotal Pro","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g","caption":"Nutritotal Pro"},"url":"https:\/\/nutritotal.com.br\/pro\/author\/perguntaserespostasimportacao\/"}]}},"views":3554,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/10727"}],"collection":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/comments?post=10727"}],"version-history":[{"count":1,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/10727\/revisions"}],"predecessor-version":[{"id":59674,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/10727\/revisions\/59674"}],"wp:attachment":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/media?parent=10727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/categories?post=10727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/tags?post=10727"},{"taxonomy":"divisao","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/divisao?post=10727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}