
{"id":11129,"date":"2012-04-13T21:20:00","date_gmt":"2012-04-14T00:20:00","guid":{"rendered":"https:\/\/nutritotal.com.br\/pro?p=11129"},"modified":"2023-05-04T09:05:37","modified_gmt":"2023-05-04T12:05:37","slug":"qual-a-importa-ncia-da-ingesta-o-de-lipa-dios-para-a-saaode-do-bebaa-durante-a-gravidez-e-lactaa-a-o","status":"publish","type":"post","link":"https:\/\/nutritotal.com.br\/pro\/qual-a-importa-ncia-da-ingesta-o-de-lipa-dios-para-a-saaode-do-bebaa-durante-a-gravidez-e-lactaa-a-o\/","title":{"rendered":"Qual a import\u00e2ncia da ingest\u00e3o de lip\u00eddios para a sa\u00fade do beb\u00ea durante a gravidez e lacta\u00e7\u00e3o?"},"content":{"rendered":"<p>Diversas evid\u00eancias cient\u00edficas apontam que a ingest\u00e3o de lip\u00eddios durante a gravidez e lacta\u00e7\u00e3o afeta os resultados de crescimento e desenvolvimento do beb\u00ea. Esse interesse se concentra sobre o consumo de \u00e1cidos graxos essenciais, os \u00e1cidos graxos poli-insaturados (AGPI), nos quais potencialmente t\u00eam efeitos importantes sobre a sa\u00fade, crescimento e desenvolvimento em longo prazo.<\/p>\n<p>Os AGPIs influenciam o perfil de \u00e1cidos graxos presentes nas membranas celulares, contribuem para a forma\u00e7\u00e3o de estruturas \u00fatero-placent\u00e1ria, bem como participam do desenvolvimento do sistema nervoso central e forma\u00e7\u00e3o da retina e, com isso, relacionam-se com a capacidade de aprendizagem e acuidade visual.<\/p>\n<p>Estudos sugerem que a ingest\u00e3o de AGPIs est\u00e1 relacionada com preven\u00e7\u00e3o de doen\u00e7as cardiovasculares, c\u00e2ncer de c\u00f3lon, doen\u00e7as imunol\u00f3gicas, al\u00e9m de favorecer o desenvolvimento cerebral e da retina. Esses efeitos s\u00e3o atribu\u00eddos principalmente ao \u00e1cido docosahexaenoico (DHA), um membro da fam\u00edlia dos \u00e1cidos graxos \u00f4mega-3.<\/p>\n<p>A ingest\u00e3o diet\u00e9tica de lip\u00eddios durante a gravidez e lacta\u00e7\u00e3o, deve ser a mesma que a recomendada para a popula\u00e7\u00e3o em geral, ou seja, entre 15 a 30% do total do valor energ\u00e9tico total (VET), sendo menos de 10% na forma de gordura saturada. No entanto, a recomenda\u00e7\u00e3o para ingest\u00e3o de DHA \u00e9 diferenciada e o consumo por mulheres durante a gravidez e lacta\u00e7\u00e3o deve ser no m\u00ednimo 200 mg\/dia. O consumo de at\u00e9 1 g\/dia de DHA ou 2,7 g\/dia de \u00f4mega-3 total tem sido usado em estudos cl\u00ednicos randomizados, sem ocorr\u00eancia de efeitos adversos significativos.<\/p>\n<p>A ingest\u00e3o m\u00ednima de DHA pode ser alcan\u00e7ada pela ingest\u00e3o de duas por\u00e7\u00f5es de peixe por semana. As fontes vegetais de \u00f4mega-3 n\u00e3o s\u00e3o suficientes para suprir as necessidades de DHA, pois a convers\u00e3o de \u00e1cido alfa-linol\u00eanico (ALA), principal \u00e1cido graxo \u00f4mega-3 presente nas fontes vegetais, em DHA \u00e9 muito baixa, cerca de 9%. Al\u00e9m disso, o ALA \u00e9 muito menos eficaz no desenvolvimento cerebral do que o DHA.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diversas evid\u00eancias cient\u00edficas apontam que a ingest\u00e3o de lip\u00eddios durante a gravidez e lacta\u00e7\u00e3o afeta os resultados de crescimento e desenvolvimento do beb\u00ea. Esse interesse se concentra sobre o consumo de \u00e1cidos graxos essenciais, os \u00e1cidos graxos poli-insaturados (AGPI), nos quais potencialmente t\u00eam efeitos importantes sobre a sa\u00fade, crescimento e desenvolvimento em longo prazo. Os [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"divisao":[2186,3208,3195,3328,3232],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qual a import\u00e2ncia da ingest\u00e3o de lip\u00eddios para a sa\u00fade do beb\u00ea durante a gravidez e lacta\u00e7\u00e3o? - Nutritotal PRO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nutritotal.com.br\/pro\/qual-a-importa-ncia-da-ingesta-o-de-lipa-dios-para-a-saaode-do-bebaa-durante-a-gravidez-e-lactaa-a-o\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qual a import\u00e2ncia da ingest\u00e3o de lip\u00eddios para a sa\u00fade do beb\u00ea durante a gravidez e lacta\u00e7\u00e3o? - Nutritotal PRO\" \/>\n<meta property=\"og:description\" content=\"Diversas evid\u00eancias cient\u00edficas apontam que a ingest\u00e3o de lip\u00eddios durante a gravidez e lacta\u00e7\u00e3o afeta os resultados de crescimento e desenvolvimento do beb\u00ea. Esse interesse se concentra sobre o consumo de \u00e1cidos graxos essenciais, os \u00e1cidos graxos poli-insaturados (AGPI), nos quais potencialmente t\u00eam efeitos importantes sobre a sa\u00fade, crescimento e desenvolvimento em longo prazo. Os [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nutritotal.com.br\/pro\/qual-a-importa-ncia-da-ingesta-o-de-lipa-dios-para-a-saaode-do-bebaa-durante-a-gravidez-e-lactaa-a-o\/\" \/>\n<meta property=\"og:site_name\" content=\"Nutritotal PRO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nutritotalPRO\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-04-14T00:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-04T12:05:37+00:00\" \/>\n<meta name=\"author\" content=\"Nutritotal Pro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nutritotal Pro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/qual-a-importa-ncia-da-ingesta-o-de-lipa-dios-para-a-saaode-do-bebaa-durante-a-gravidez-e-lactaa-a-o\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/qual-a-importa-ncia-da-ingesta-o-de-lipa-dios-para-a-saaode-do-bebaa-durante-a-gravidez-e-lactaa-a-o\/\"},\"author\":{\"name\":\"Nutritotal Pro\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb\"},\"headline\":\"Qual a import\u00e2ncia da ingest\u00e3o de lip\u00eddios para a sa\u00fade do beb\u00ea durante a gravidez e lacta\u00e7\u00e3o?\",\"datePublished\":\"2012-04-14T00:20:00+00:00\",\"dateModified\":\"2023-05-04T12:05:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/qual-a-importa-ncia-da-ingesta-o-de-lipa-dios-para-a-saaode-do-bebaa-durante-a-gravidez-e-lactaa-a-o\/\"},\"wordCount\":368,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/nutritotal.com.br\/pro\/qual-a-importa-ncia-da-ingesta-o-de-lipa-dios-para-a-saaode-do-bebaa-durante-a-gravidez-e-lactaa-a-o\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/qual-a-importa-ncia-da-ingesta-o-de-lipa-dios-para-a-saaode-do-bebaa-durante-a-gravidez-e-lactaa-a-o\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/qual-a-importa-ncia-da-ingesta-o-de-lipa-dios-para-a-saaode-do-bebaa-durante-a-gravidez-e-lactaa-a-o\/\",\"name\":\"Qual a import\u00e2ncia da ingest\u00e3o de lip\u00eddios para a sa\u00fade do beb\u00ea durante a gravidez e lacta\u00e7\u00e3o? - Nutritotal PRO\",\"isPartOf\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\"},\"datePublished\":\"2012-04-14T00:20:00+00:00\",\"dateModified\":\"2023-05-04T12:05:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/qual-a-importa-ncia-da-ingesta-o-de-lipa-dios-para-a-saaode-do-bebaa-durante-a-gravidez-e-lactaa-a-o\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nutritotal.com.br\/pro\/qual-a-importa-ncia-da-ingesta-o-de-lipa-dios-para-a-saaode-do-bebaa-durante-a-gravidez-e-lactaa-a-o\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/qual-a-importa-ncia-da-ingesta-o-de-lipa-dios-para-a-saaode-do-bebaa-durante-a-gravidez-e-lactaa-a-o\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nutritotal.com.br\/pro\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qual a import\u00e2ncia da ingest\u00e3o de lip\u00eddios para a sa\u00fade do beb\u00ea durante a gravidez e lacta\u00e7\u00e3o?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"name\":\"Nutritotal PRO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\",\"name\":\"Nutri Total\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"contentUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"width\":426,\"height\":426,\"caption\":\"Nutri Total\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/nutritotalPRO\/\",\"https:\/\/www.instagram.com\/nutritotalpro\/\",\"https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb\",\"name\":\"Nutritotal Pro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g\",\"caption\":\"Nutritotal Pro\"},\"url\":\"https:\/\/nutritotal.com.br\/pro\/author\/perguntaserespostasimportacao\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qual a import\u00e2ncia da ingest\u00e3o de lip\u00eddios para a sa\u00fade do beb\u00ea durante a gravidez e lacta\u00e7\u00e3o? - Nutritotal PRO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nutritotal.com.br\/pro\/qual-a-importa-ncia-da-ingesta-o-de-lipa-dios-para-a-saaode-do-bebaa-durante-a-gravidez-e-lactaa-a-o\/","og_locale":"pt_BR","og_type":"article","og_title":"Qual a import\u00e2ncia da ingest\u00e3o de lip\u00eddios para a sa\u00fade do beb\u00ea durante a gravidez e lacta\u00e7\u00e3o? - Nutritotal PRO","og_description":"Diversas evid\u00eancias cient\u00edficas apontam que a ingest\u00e3o de lip\u00eddios durante a gravidez e lacta\u00e7\u00e3o afeta os resultados de crescimento e desenvolvimento do beb\u00ea. Esse interesse se concentra sobre o consumo de \u00e1cidos graxos essenciais, os \u00e1cidos graxos poli-insaturados (AGPI), nos quais potencialmente t\u00eam efeitos importantes sobre a sa\u00fade, crescimento e desenvolvimento em longo prazo. Os [&hellip;]","og_url":"https:\/\/nutritotal.com.br\/pro\/qual-a-importa-ncia-da-ingesta-o-de-lipa-dios-para-a-saaode-do-bebaa-durante-a-gravidez-e-lactaa-a-o\/","og_site_name":"Nutritotal PRO","article_publisher":"https:\/\/www.facebook.com\/nutritotalPRO\/","article_published_time":"2012-04-14T00:20:00+00:00","article_modified_time":"2023-05-04T12:05:37+00:00","author":"Nutritotal Pro","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Nutritotal Pro","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nutritotal.com.br\/pro\/qual-a-importa-ncia-da-ingesta-o-de-lipa-dios-para-a-saaode-do-bebaa-durante-a-gravidez-e-lactaa-a-o\/#article","isPartOf":{"@id":"https:\/\/nutritotal.com.br\/pro\/qual-a-importa-ncia-da-ingesta-o-de-lipa-dios-para-a-saaode-do-bebaa-durante-a-gravidez-e-lactaa-a-o\/"},"author":{"name":"Nutritotal Pro","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb"},"headline":"Qual a import\u00e2ncia da ingest\u00e3o de lip\u00eddios para a sa\u00fade do beb\u00ea durante a gravidez e lacta\u00e7\u00e3o?","datePublished":"2012-04-14T00:20:00+00:00","dateModified":"2023-05-04T12:05:37+00:00","mainEntityOfPage":{"@id":"https:\/\/nutritotal.com.br\/pro\/qual-a-importa-ncia-da-ingesta-o-de-lipa-dios-para-a-saaode-do-bebaa-durante-a-gravidez-e-lactaa-a-o\/"},"wordCount":368,"commentCount":0,"publisher":{"@id":"https:\/\/nutritotal.com.br\/pro\/#organization"},"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nutritotal.com.br\/pro\/qual-a-importa-ncia-da-ingesta-o-de-lipa-dios-para-a-saaode-do-bebaa-durante-a-gravidez-e-lactaa-a-o\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nutritotal.com.br\/pro\/qual-a-importa-ncia-da-ingesta-o-de-lipa-dios-para-a-saaode-do-bebaa-durante-a-gravidez-e-lactaa-a-o\/","url":"https:\/\/nutritotal.com.br\/pro\/qual-a-importa-ncia-da-ingesta-o-de-lipa-dios-para-a-saaode-do-bebaa-durante-a-gravidez-e-lactaa-a-o\/","name":"Qual a import\u00e2ncia da ingest\u00e3o de lip\u00eddios para a sa\u00fade do beb\u00ea durante a gravidez e lacta\u00e7\u00e3o? - Nutritotal PRO","isPartOf":{"@id":"https:\/\/nutritotal.com.br\/pro\/#website"},"datePublished":"2012-04-14T00:20:00+00:00","dateModified":"2023-05-04T12:05:37+00:00","breadcrumb":{"@id":"https:\/\/nutritotal.com.br\/pro\/qual-a-importa-ncia-da-ingesta-o-de-lipa-dios-para-a-saaode-do-bebaa-durante-a-gravidez-e-lactaa-a-o\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nutritotal.com.br\/pro\/qual-a-importa-ncia-da-ingesta-o-de-lipa-dios-para-a-saaode-do-bebaa-durante-a-gravidez-e-lactaa-a-o\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nutritotal.com.br\/pro\/qual-a-importa-ncia-da-ingesta-o-de-lipa-dios-para-a-saaode-do-bebaa-durante-a-gravidez-e-lactaa-a-o\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nutritotal.com.br\/pro\/"},{"@type":"ListItem","position":2,"name":"Qual a import\u00e2ncia da ingest\u00e3o de lip\u00eddios para a sa\u00fade do beb\u00ea durante a gravidez e lacta\u00e7\u00e3o?"}]},{"@type":"WebSite","@id":"https:\/\/nutritotal.com.br\/pro\/#website","url":"https:\/\/nutritotal.com.br\/pro\/","name":"Nutritotal PRO","description":"","publisher":{"@id":"https:\/\/nutritotal.com.br\/pro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nutritotal.com.br\/pro\/#organization","name":"Nutri Total","url":"https:\/\/nutritotal.com.br\/pro\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/","url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","contentUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","width":426,"height":426,"caption":"Nutri Total"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nutritotalPRO\/","https:\/\/www.instagram.com\/nutritotalpro\/","https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA"]},{"@type":"Person","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb","name":"Nutritotal Pro","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g","caption":"Nutritotal Pro"},"url":"https:\/\/nutritotal.com.br\/pro\/author\/perguntaserespostasimportacao\/"}]}},"views":2317,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/11129"}],"collection":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/comments?post=11129"}],"version-history":[{"count":1,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/11129\/revisions"}],"predecessor-version":[{"id":58267,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/11129\/revisions\/58267"}],"wp:attachment":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/media?parent=11129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/categories?post=11129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/tags?post=11129"},{"taxonomy":"divisao","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/divisao?post=11129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}