
{"id":11647,"date":"2016-10-06T21:30:00","date_gmt":"2016-10-07T00:30:00","guid":{"rendered":"https:\/\/nutritotal.com.br\/pro?p=11647"},"modified":"2023-05-31T13:52:43","modified_gmt":"2023-05-31T16:52:43","slug":"qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2","status":"publish","type":"post","link":"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/","title":{"rendered":"Qual a indica\u00e7\u00e3o de probi\u00f3ticos na s\u00edndrome de super crescimento bacteriano intestinal?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-55807 size-full\" src=\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2016\/10\/crescimento-bact-novo-site-1.jpg\" alt=\"\" width=\"1140\" height=\"500\" srcset=\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2016\/10\/crescimento-bact-novo-site-1.jpg 1140w, https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2016\/10\/crescimento-bact-novo-site-1-300x132.jpg 300w, https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2016\/10\/crescimento-bact-novo-site-1-1024x449.jpg 1024w, https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2016\/10\/crescimento-bact-novo-site-1-768x337.jpg 768w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" \/><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; margin: 0cm 0cm 0pt;\">A condi\u00e7\u00e3o de super crescimento bacteriano no intestino delgado, do ingl\u00eas, small intestinal bacterial overgrowth (SIBO), ocorre quando bact\u00e9rias colonizadoras do c\u00f3lon aumentam a sua prolifera\u00e7\u00e3o e colonizam o intestino delgado de maneira anormal.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; margin: 0cm 0cm 0pt;\">Essa s\u00edndrome pode ser encontrada em pacientes com fal\u00eancia e disfun\u00e7\u00f5es intestinais, incluindo s\u00edndrome do intestino curto, dist\u00farbios de motilidade e doen\u00e7as inflamat\u00f3rias intestinais. A consequ\u00eancia mais grave da SIBO \u00e9 a sepse sist\u00eamica devido a aumento na transloca\u00e7\u00e3o bacteriana. O tratamento da SIBO inclui uso de antibi\u00f3ticos e terapia nutricional adequada.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; margin: 0cm 0cm 0pt;\">Estudo piloto, prospectivo e aleat\u00f3rio avaliou as diferen\u00e7as no tratamento com antibi\u00f3ticos metronidazol ou uma mistura de probi\u00f3ticos em pacientes com distens\u00e3o abdominal (crit\u00e9rios de Roma III) e diagn\u00f3stico de SIBO. Vinte e cinco pacientes receberam metronidazol (500mg duas vezes por dia) e 25 pacientes receberam por cinco dias a mistura de probi\u00f3ticos contendo: <i>Lactobacillus casei <\/i>(3.3 x 107 UFC), <i>Lactobacillus plantarum <\/i>(3.3 x 107 UFC), <i>Streptococcus faecalis <\/i>(3.3 x 107 UFC) e <i>Bifidobacterium brevis <\/i>(1.0 x 106 UFC). Os sintomas referidos pelos pacientes melhoraram significativamente no grupo probi\u00f3ticos em rela\u00e7\u00e3o ao grupo metronidazol (82% vs 52%; p = 0,036). Os autores sugerem o uso potencial de probi\u00f3ticos no tratamento dos sintomas de pacientes com SIBO.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; margin: 0cm 0cm 0pt;\">No entanto, apesar dos estudos preliminares apontarem a\u00e7\u00f5es ben\u00e9ficas de probi\u00f3ticos, em SIBO, particularmente no refor\u00e7o da barreira intestinal, inibi\u00e7\u00e3o de bact\u00e9rias patog\u00eanicas e est\u00edmulo de a\u00e7\u00e3o imuno-moduladora, ainda s\u00e3o poucos os estudos em pacientes com SIBO e novas investiga\u00e7\u00f5es devem ser realizadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A condi\u00e7\u00e3o de super crescimento bacteriano no intestino delgado, do ingl\u00eas, small intestinal bacterial overgrowth (SIBO), ocorre quando bact\u00e9rias colonizadoras do c\u00f3lon aumentam a sua prolifera\u00e7\u00e3o e colonizam o intestino delgado de maneira anormal. Essa s\u00edndrome pode ser encontrada em pacientes com fal\u00eancia e disfun\u00e7\u00f5es intestinais, incluindo s\u00edndrome do intestino curto, dist\u00farbios de motilidade e [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":42701,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1399],"tags":[641],"divisao":[2185,2186,2193],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qual a indica\u00e7\u00e3o de probi\u00f3ticos na s\u00edndrome de super crescimento bacteriano intestinal? - Nutritotal PRO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qual a indica\u00e7\u00e3o de probi\u00f3ticos na s\u00edndrome de super crescimento bacteriano intestinal? - Nutritotal PRO\" \/>\n<meta property=\"og:description\" content=\"A condi\u00e7\u00e3o de super crescimento bacteriano no intestino delgado, do ingl\u00eas, small intestinal bacterial overgrowth (SIBO), ocorre quando bact\u00e9rias colonizadoras do c\u00f3lon aumentam a sua prolifera\u00e7\u00e3o e colonizam o intestino delgado de maneira anormal. Essa s\u00edndrome pode ser encontrada em pacientes com fal\u00eancia e disfun\u00e7\u00f5es intestinais, incluindo s\u00edndrome do intestino curto, dist\u00farbios de motilidade e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Nutritotal PRO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nutritotalPRO\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-07T00:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-31T16:52:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2016\/10\/crescimento-bact-destacada-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"257\" \/>\n\t<meta property=\"og:image:height\" content=\"165\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nutritotal Pro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nutritotal Pro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/\"},\"author\":{\"name\":\"Nutritotal Pro\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb\"},\"headline\":\"Qual a indica\u00e7\u00e3o de probi\u00f3ticos na s\u00edndrome de super crescimento bacteriano intestinal?\",\"datePublished\":\"2016-10-07T00:30:00+00:00\",\"dateModified\":\"2023-05-31T16:52:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/\"},\"wordCount\":284,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2016\/10\/crescimento-bact-destacada-1.png\",\"keywords\":[\"probi\u00f3ticos\"],\"articleSection\":[\"Probi\u00f3ticos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/\",\"name\":\"Qual a indica\u00e7\u00e3o de probi\u00f3ticos na s\u00edndrome de super crescimento bacteriano intestinal? - Nutritotal PRO\",\"isPartOf\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2016\/10\/crescimento-bact-destacada-1.png\",\"datePublished\":\"2016-10-07T00:30:00+00:00\",\"dateModified\":\"2023-05-31T16:52:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/#primaryimage\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2016\/10\/crescimento-bact-destacada-1.png\",\"contentUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2016\/10\/crescimento-bact-destacada-1.png\",\"width\":257,\"height\":165},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nutritotal.com.br\/pro\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qual a indica\u00e7\u00e3o de probi\u00f3ticos na s\u00edndrome de super crescimento bacteriano intestinal?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"name\":\"Nutritotal PRO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\",\"name\":\"Nutri Total\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"contentUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"width\":426,\"height\":426,\"caption\":\"Nutri Total\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/nutritotalPRO\/\",\"https:\/\/www.instagram.com\/nutritotalpro\/\",\"https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb\",\"name\":\"Nutritotal Pro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g\",\"caption\":\"Nutritotal Pro\"},\"url\":\"https:\/\/nutritotal.com.br\/pro\/author\/perguntaserespostasimportacao\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qual a indica\u00e7\u00e3o de probi\u00f3ticos na s\u00edndrome de super crescimento bacteriano intestinal? - Nutritotal PRO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Qual a indica\u00e7\u00e3o de probi\u00f3ticos na s\u00edndrome de super crescimento bacteriano intestinal? - Nutritotal PRO","og_description":"A condi\u00e7\u00e3o de super crescimento bacteriano no intestino delgado, do ingl\u00eas, small intestinal bacterial overgrowth (SIBO), ocorre quando bact\u00e9rias colonizadoras do c\u00f3lon aumentam a sua prolifera\u00e7\u00e3o e colonizam o intestino delgado de maneira anormal. Essa s\u00edndrome pode ser encontrada em pacientes com fal\u00eancia e disfun\u00e7\u00f5es intestinais, incluindo s\u00edndrome do intestino curto, dist\u00farbios de motilidade e [&hellip;]","og_url":"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/","og_site_name":"Nutritotal PRO","article_publisher":"https:\/\/www.facebook.com\/nutritotalPRO\/","article_published_time":"2016-10-07T00:30:00+00:00","article_modified_time":"2023-05-31T16:52:43+00:00","og_image":[{"width":257,"height":165,"url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2016\/10\/crescimento-bact-destacada-1.png","type":"image\/png"}],"author":"Nutritotal Pro","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Nutritotal Pro","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/#article","isPartOf":{"@id":"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/"},"author":{"name":"Nutritotal Pro","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb"},"headline":"Qual a indica\u00e7\u00e3o de probi\u00f3ticos na s\u00edndrome de super crescimento bacteriano intestinal?","datePublished":"2016-10-07T00:30:00+00:00","dateModified":"2023-05-31T16:52:43+00:00","mainEntityOfPage":{"@id":"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/"},"wordCount":284,"commentCount":0,"publisher":{"@id":"https:\/\/nutritotal.com.br\/pro\/#organization"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/#primaryimage"},"thumbnailUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2016\/10\/crescimento-bact-destacada-1.png","keywords":["probi\u00f3ticos"],"articleSection":["Probi\u00f3ticos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/","url":"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/","name":"Qual a indica\u00e7\u00e3o de probi\u00f3ticos na s\u00edndrome de super crescimento bacteriano intestinal? - Nutritotal PRO","isPartOf":{"@id":"https:\/\/nutritotal.com.br\/pro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/#primaryimage"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/#primaryimage"},"thumbnailUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2016\/10\/crescimento-bact-destacada-1.png","datePublished":"2016-10-07T00:30:00+00:00","dateModified":"2023-05-31T16:52:43+00:00","breadcrumb":{"@id":"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/#primaryimage","url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2016\/10\/crescimento-bact-destacada-1.png","contentUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2016\/10\/crescimento-bact-destacada-1.png","width":257,"height":165},{"@type":"BreadcrumbList","@id":"https:\/\/nutritotal.com.br\/pro\/qual-a-indicaa-a-o-de-probia-ticos-na-sa-ndrome-de-super-crescimento-bacteriano-intestinal-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nutritotal.com.br\/pro\/"},{"@type":"ListItem","position":2,"name":"Qual a indica\u00e7\u00e3o de probi\u00f3ticos na s\u00edndrome de super crescimento bacteriano intestinal?"}]},{"@type":"WebSite","@id":"https:\/\/nutritotal.com.br\/pro\/#website","url":"https:\/\/nutritotal.com.br\/pro\/","name":"Nutritotal PRO","description":"","publisher":{"@id":"https:\/\/nutritotal.com.br\/pro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nutritotal.com.br\/pro\/#organization","name":"Nutri Total","url":"https:\/\/nutritotal.com.br\/pro\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/","url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","contentUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","width":426,"height":426,"caption":"Nutri Total"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nutritotalPRO\/","https:\/\/www.instagram.com\/nutritotalpro\/","https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA"]},{"@type":"Person","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/d3263f44ee30149db636a6624efe3cfb","name":"Nutritotal Pro","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d6401bcf0a081502ab525e04b5c6b29?s=96&d=mm&r=g","caption":"Nutritotal Pro"},"url":"https:\/\/nutritotal.com.br\/pro\/author\/perguntaserespostasimportacao\/"}]}},"views":2759,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/11647"}],"collection":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/comments?post=11647"}],"version-history":[{"count":1,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/11647\/revisions"}],"predecessor-version":[{"id":59208,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/11647\/revisions\/59208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/media\/42701"}],"wp:attachment":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/media?parent=11647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/categories?post=11647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/tags?post=11647"},{"taxonomy":"divisao","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/divisao?post=11647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}