
{"id":36090,"date":"2019-02-12T17:23:03","date_gmt":"2019-02-12T19:23:03","guid":{"rendered":"https:\/\/nutritotal.com.br\/pro\/?p=36090"},"modified":"2021-04-23T15:33:05","modified_gmt":"2021-04-23T18:33:05","slug":"fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso","status":"publish","type":"post","link":"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/","title":{"rendered":"Fatores Gen\u00e9ticos influenciam resposta \u00e0 dieta e tratamento medicamentoso"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-36091\" src=\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/02\/lipideos_novosite.jpg\" alt=\"\" width=\"1139\" height=\"501\" srcset=\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/02\/lipideos_novosite.jpg 1139w, https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/02\/lipideos_novosite-300x132.jpg 300w, https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/02\/lipideos_novosite-1024x450.jpg 1024w, https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/02\/lipideos_novosite-768x338.jpg 768w\" sizes=\"(max-width: 1139px) 100vw, 1139px\" \/><\/p>\n<p><span class=\"tlid-translation\">Estudo avaliou os efeitos de variantes gen\u00e9ticas raras sobre resposta lip\u00eddica diante \u00e0 refei\u00e7\u00e3o rica em gordura (RRG) e \u00e0 terapia com fenofibrato (FFB). Para isso, 810 indiv\u00edduos realizaram interven\u00e7\u00e3o com RRG, sendo que 797 receberam diariamente tratamento com 160mg de FFB durante tr\u00eas semanas. Para avaliar os efeitos da interven\u00e7\u00e3o, foram mensurados HDL, LDL, TG. Amostras sangu\u00edneas foram coletadas antes e ap\u00f3s o uso de FFB em tr\u00eas medidas: jejum (imediatamente antes da refei\u00e7\u00e3o), aproximadamente 3,5h ap\u00f3s a refei\u00e7\u00e3o e aproximadamente 6h ap\u00f3s a refei\u00e7\u00e3o. Amostras de DNA foram coletadas de sangue perif\u00e9rico.<\/span><\/p>\n<p><span class=\"tlid-translation\">Os autores encontraram que os n\u00edveis de LDL e TG reduziram significativamente ap\u00f3s o tratamento com FFB (p\u22640,05), e os n\u00edveis de HDL mantiveram-se semelhantes. Os n\u00edveis de TG aumentaram significativamente durante as primeiras 3,5h e diminu\u00edram significativamente de 3,5h para 6h ap\u00f3s as refei\u00e7\u00f5es com alto teor de gordura (P\u22640,05). Tamb\u00e9m verificaram que raras variantes codificadoras em ITGA7, SIPA1L2 e CEP72 foram significativamente associadas, respectivamente, \u00e0 resposta do LDL ao FFB (P = 1.24), ao aumento p\u00f3s-prandial de triglic\u00e9rides (AUI) (P = 2.31) e \u00e0 resposta p\u00f3s-prandial do triglicer\u00eddeo ao FFB (P = 1.88).<\/span><\/p>\n<p><span class=\"tlid-translation\">Com estes dados, os autores concluiram que variantes raras em tr\u00eas genes, ITGA7, SIPA1L2 e CEP72, est\u00e3o associadas \u00e0 resposta lip\u00eddica ap\u00f3s refei\u00e7\u00e3o rica em gordura e \/ ou ao tratamento com FFB. Esses resultados e discuss\u00f5es futuras sobre mecanismos moleculares subjacentes podem fornecer informa\u00e7\u00f5es sobre risco de doen\u00e7as e ajudar a estabelecer metas de tratamento.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estudo avaliou efeitos de variantes gen\u00e9ticas raras sobre resposta lip\u00eddica diante \u00e0 refei\u00e7\u00e3o rica em gordura e terapia com fenofibrato em 810 indiv\u00edduos<\/p>\n","protected":false},"author":15,"featured_media":36092,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[178,188],"divisao":[2186],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fatores Gen\u00e9ticos influenciam resposta \u00e0 dieta e tratamento medicamentoso - Nutritotal PRO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fatores Gen\u00e9ticos influenciam resposta \u00e0 dieta e tratamento medicamentoso - Nutritotal PRO\" \/>\n<meta property=\"og:description\" content=\"Estudo avaliou efeitos de variantes gen\u00e9ticas raras sobre resposta lip\u00eddica diante \u00e0 refei\u00e7\u00e3o rica em gordura e terapia com fenofibrato em 810 indiv\u00edduos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/\" \/>\n<meta property=\"og:site_name\" content=\"Nutritotal PRO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nutritotalPRO\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-12T19:23:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-23T18:33:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/02\/lipideos_destacada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"255\" \/>\n\t<meta property=\"og:image:height\" content=\"165\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michelle Grillo Barone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michelle Grillo Barone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/\"},\"author\":{\"name\":\"Michelle Grillo Barone\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/2edd7f2716a6ced17f76103a7b2875c4\"},\"headline\":\"Fatores Gen\u00e9ticos influenciam resposta \u00e0 dieta e tratamento medicamentoso\",\"datePublished\":\"2019-02-12T19:23:03+00:00\",\"dateModified\":\"2021-04-23T18:33:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/\"},\"wordCount\":278,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/02\/lipideos_destacada.jpg\",\"keywords\":[\"dieta\",\"lip\u00eddeos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/\",\"name\":\"Fatores Gen\u00e9ticos influenciam resposta \u00e0 dieta e tratamento medicamentoso - Nutritotal PRO\",\"isPartOf\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/02\/lipideos_destacada.jpg\",\"datePublished\":\"2019-02-12T19:23:03+00:00\",\"dateModified\":\"2021-04-23T18:33:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/#primaryimage\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/02\/lipideos_destacada.jpg\",\"contentUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/02\/lipideos_destacada.jpg\",\"width\":255,\"height\":165},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nutritotal.com.br\/pro\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fatores Gen\u00e9ticos influenciam resposta \u00e0 dieta e tratamento medicamentoso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"name\":\"Nutritotal PRO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\",\"name\":\"Nutri Total\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"contentUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"width\":426,\"height\":426,\"caption\":\"Nutri Total\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/nutritotalPRO\/\",\"https:\/\/www.instagram.com\/nutritotalpro\/\",\"https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/2edd7f2716a6ced17f76103a7b2875c4\",\"name\":\"Michelle Grillo Barone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f7c991ea71e5869f1ccfbb383a603a4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f7c991ea71e5869f1ccfbb383a603a4?s=96&d=mm&r=g\",\"caption\":\"Michelle Grillo Barone\"},\"description\":\"Nutricionista. Especialista em Nutri\u00e7\u00e3o Enteral e Parenteral pela BRASPEN. Especializa\u00e7\u00e3o em Fitoterapia pela Ganep. Especializa\u00e7\u00e3o em Nutri\u00e7\u00e3o Cl\u00ednica pelo Centro Universit\u00e1rio S\u00e3o Camilo. Coordenadora de projetos e inova\u00e7\u00e3o do Ganep Educa\u00e7\u00e3o e Nutritotal\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/author\/michelle\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fatores Gen\u00e9ticos influenciam resposta \u00e0 dieta e tratamento medicamentoso - Nutritotal PRO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/","og_locale":"pt_BR","og_type":"article","og_title":"Fatores Gen\u00e9ticos influenciam resposta \u00e0 dieta e tratamento medicamentoso - Nutritotal PRO","og_description":"Estudo avaliou efeitos de variantes gen\u00e9ticas raras sobre resposta lip\u00eddica diante \u00e0 refei\u00e7\u00e3o rica em gordura e terapia com fenofibrato em 810 indiv\u00edduos","og_url":"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/","og_site_name":"Nutritotal PRO","article_publisher":"https:\/\/www.facebook.com\/nutritotalPRO\/","article_published_time":"2019-02-12T19:23:03+00:00","article_modified_time":"2021-04-23T18:33:05+00:00","og_image":[{"width":255,"height":165,"url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/02\/lipideos_destacada.jpg","type":"image\/jpeg"}],"author":"Michelle Grillo Barone","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Michelle Grillo Barone","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/#article","isPartOf":{"@id":"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/"},"author":{"name":"Michelle Grillo Barone","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/2edd7f2716a6ced17f76103a7b2875c4"},"headline":"Fatores Gen\u00e9ticos influenciam resposta \u00e0 dieta e tratamento medicamentoso","datePublished":"2019-02-12T19:23:03+00:00","dateModified":"2021-04-23T18:33:05+00:00","mainEntityOfPage":{"@id":"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/"},"wordCount":278,"commentCount":0,"publisher":{"@id":"https:\/\/nutritotal.com.br\/pro\/#organization"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/#primaryimage"},"thumbnailUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/02\/lipideos_destacada.jpg","keywords":["dieta","lip\u00eddeos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/","url":"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/","name":"Fatores Gen\u00e9ticos influenciam resposta \u00e0 dieta e tratamento medicamentoso - Nutritotal PRO","isPartOf":{"@id":"https:\/\/nutritotal.com.br\/pro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/#primaryimage"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/#primaryimage"},"thumbnailUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/02\/lipideos_destacada.jpg","datePublished":"2019-02-12T19:23:03+00:00","dateModified":"2021-04-23T18:33:05+00:00","breadcrumb":{"@id":"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/#primaryimage","url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/02\/lipideos_destacada.jpg","contentUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/02\/lipideos_destacada.jpg","width":255,"height":165},{"@type":"BreadcrumbList","@id":"https:\/\/nutritotal.com.br\/pro\/fatores-geneticos-influenciam-resposta-a-dieta-e-tratamento-medicamentoso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nutritotal.com.br\/pro\/"},{"@type":"ListItem","position":2,"name":"Fatores Gen\u00e9ticos influenciam resposta \u00e0 dieta e tratamento medicamentoso"}]},{"@type":"WebSite","@id":"https:\/\/nutritotal.com.br\/pro\/#website","url":"https:\/\/nutritotal.com.br\/pro\/","name":"Nutritotal PRO","description":"","publisher":{"@id":"https:\/\/nutritotal.com.br\/pro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nutritotal.com.br\/pro\/#organization","name":"Nutri Total","url":"https:\/\/nutritotal.com.br\/pro\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/","url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","contentUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","width":426,"height":426,"caption":"Nutri Total"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nutritotalPRO\/","https:\/\/www.instagram.com\/nutritotalpro\/","https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA"]},{"@type":"Person","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/2edd7f2716a6ced17f76103a7b2875c4","name":"Michelle Grillo Barone","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f7c991ea71e5869f1ccfbb383a603a4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f7c991ea71e5869f1ccfbb383a603a4?s=96&d=mm&r=g","caption":"Michelle Grillo Barone"},"description":"Nutricionista. Especialista em Nutri\u00e7\u00e3o Enteral e Parenteral pela BRASPEN. Especializa\u00e7\u00e3o em Fitoterapia pela Ganep. Especializa\u00e7\u00e3o em Nutri\u00e7\u00e3o Cl\u00ednica pelo Centro Universit\u00e1rio S\u00e3o Camilo. Coordenadora de projetos e inova\u00e7\u00e3o do Ganep Educa\u00e7\u00e3o e Nutritotal","url":"https:\/\/nutritotal.com.br\/pro\/author\/michelle\/"}]}},"views":790,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/36090"}],"collection":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/comments?post=36090"}],"version-history":[{"count":0,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/36090\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/media\/36092"}],"wp:attachment":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/media?parent=36090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/categories?post=36090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/tags?post=36090"},{"taxonomy":"divisao","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/divisao?post=36090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}