
{"id":39499,"date":"2019-04-15T11:22:17","date_gmt":"2019-04-15T14:22:17","guid":{"rendered":"https:\/\/nutritotal.com.br\/pro\/?p=39499"},"modified":"2023-04-04T15:44:04","modified_gmt":"2023-04-04T18:44:04","slug":"quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno","status":"publish","type":"post","link":"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/","title":{"rendered":"Quais s\u00e3o os fatores que influenciam o microbioma do leite materno?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-39500\" src=\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/04\/Nota-2-Microbioma-leite-materno-NovoSite.jpg\" alt=\"\" width=\"1140\" height=\"498\" srcset=\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/04\/Nota-2-Microbioma-leite-materno-NovoSite.jpg 1140w, https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/04\/Nota-2-Microbioma-leite-materno-NovoSite-300x131.jpg 300w, https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/04\/Nota-2-Microbioma-leite-materno-NovoSite-1024x447.jpg 1024w, https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/04\/Nota-2-Microbioma-leite-materno-NovoSite-768x335.jpg 768w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" \/><\/p>\n<p>Estudo caracterizou o microbioma do leite materno de 80 lactantes saud\u00e1veis em quatro diferentes pa\u00edses (Espanha, Finlandia, Africa do Sul e China) a fim de investigar a potencial influencia geogr\u00e1fica e do tipo de parto nesta composi\u00e7\u00e3o, e explorar a fra\u00e7\u00e3o f\u00fangica.<\/p>\n<p>Foram coletadas amostras de leite materno, e dados como idade, peso e IMC pr\u00e9 gestacional. \u00a0O microbioma foi avaliado por extra\u00e7\u00e3o de DNA e sequenciamento por Illumina da regi\u00e3o ITS1 e sequenciamento gen\u00e9tico a partir da t\u00e9cnica 16S rRNA.<\/p>\n<p>A idade materna m\u00e9dia foi de 33,52 anos e o IMC pr\u00e9 gestacional m\u00e9dio foi de 24kg\/m\u00b2. Das 20 amostras coletadas em cada pa\u00eds, foram detectados n\u00edveis de fungos em 16 amostras espanholas, 14 africanas, 9 chinesas e 7 finlandesas, sem diferen\u00e7a quantitativa entre os pa\u00edses e entre os tipos de parto. Foram identificados dois filos f\u00fangicos dominantes: Basidiomycota (58.65%) e Ascomycota (41.03%), sendo que as mulheres africanas apresentaram valores maiores de Ascomycota e menores de Basidiomycota que mulheres de outros pa\u00edses (p&lt;0,05). \u00a0A an\u00e1lise em n\u00edvel de g\u00eanero mostrou domin\u00e2ncia de <em>Malassezia<\/em> (40.6%) e <em>Davidiella<\/em> (9.0%), independentemente do local ou tipo de parto.<\/p>\n<p>De maneira geral, a localiza\u00e7\u00e3o geogr\u00e1fica (p=0,005) e tipo de parto (p=0,023) influenciaram a composi\u00e7\u00e3o de fungos do leite materno. Com rela\u00e7\u00e3o ao tipo de parto, a concentra\u00e7\u00e3o de Cryptococcus foi significativamente maior em amostras de leite de mulheres que tiveram parto normal, em compara\u00e7\u00e3o com aquelas que tiveram parto ces\u00e1rea (p = 0,028). Foi observada maior concentra\u00e7\u00e3o de <em>Candida smithsonii <\/em>nas chinesas que tiveram parto normal; <em>Sistotrema sp.<\/em> em espanholas que tiveram parto ces\u00e1rea; <em>Ascomycota sp<\/em> que tiveram parto normal e <em>Malasezzia restricta<\/em> que tiveram parto ces\u00e1rea na Finl\u00e2ndia; e <em>Malassezia restricta <\/em>e<em> Davidiella tassiana<\/em> nas africanas que tiveram parto ces\u00e1rea \u00a0(todos p&lt;0,05).<\/p>\n<p>Bact\u00e9rias e fungos presentes nas amostras de leite materno mostraram intera\u00e7\u00f5es complexas intra e interdom\u00ednios, com diferentes associa\u00e7\u00f5es dependendo da localiza\u00e7\u00e3o geogr\u00e1fica e tipo de parto.<\/p>\n<p>Esses resultados apoiam a exist\u00eancia de um microbioma do leite materno, sendo esse influenciado por fatores demogr\u00e1ficos e pelo tipo de parto. A presen\u00e7a de c\u00e9lulas f\u00fangicas \u200b\u200bsugere uma potencial influ\u00eancia do leite materno no desenvolvimento da micobiota do beb\u00ea, mas novos estudos s\u00e3o necess\u00e1rios para avaliar a potencial transfer\u00eancia de fungos do leite materno para o micobiota intestinal infantil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estudo analisou o micobioma  do leite materno de 80 mulheres de diferentes pa\u00edses, e explorou a presen\u00e7a de fra\u00e7\u00e3o f\u00fangica, a rela\u00e7\u00e3o entre fungos e bact\u00e9rias, e a associa\u00e7\u00e3o entre os microrganismos, fatores demogr\u00e1ficos e tipo de parto<\/p>\n","protected":false},"author":112425,"featured_media":39501,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[382,864,865,866],"divisao":[2185,2186,3208,3195],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quais s\u00e3o os fatores que influenciam o microbioma do leite materno? - Nutritotal PRO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quais s\u00e3o os fatores que influenciam o microbioma do leite materno?\" \/>\n<meta property=\"og:description\" content=\"Estudo avaliou amostras de leite materno de 80 lactantes saud\u00e1veis em quatro diferentes pa\u00edses para investigar o potencial de influencia geogr\u00e1fica e do tipo de parto na composi\u00e7\u00e3o do microbioma do leite. De maneira geral, os dois fatores influenciaram a composi\u00e7\u00e3o do microbioma. Foram detectados n\u00edveis de fungos em 16 amostras espanholas, 14 africanas, 9 chinesas e 7 finlandesas, e foram observadas intera\u00e7\u00f5es entre bact\u00e9rias e fungos. A presen\u00e7a de c\u00e9lulas f\u00fangicas sugere uma potencial influ\u00eancia do leite materno no desenvolvimento da micobiota do beb\u00ea. Veja a not\u00edcia completa no portal do Nutritotal Pro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/\" \/>\n<meta property=\"og:site_name\" content=\"Nutritotal PRO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nutritotalPRO\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-15T14:22:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-04T18:44:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/04\/Nota-2-Microbioma-leite-materno-Destacada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"257\" \/>\n\t<meta property=\"og:image:height\" content=\"165\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nutritotal PRO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nutritotal PRO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/\"},\"author\":{\"name\":\"Nutritotal PRO\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/c168b0202c0b3946a1d52e7de7a04126\"},\"headline\":\"Quais s\u00e3o os fatores que influenciam o microbioma do leite materno?\",\"datePublished\":\"2019-04-15T14:22:17+00:00\",\"dateModified\":\"2023-04-04T18:44:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/\"},\"wordCount\":426,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/04\/Nota-2-Microbioma-leite-materno-Destacada.jpg\",\"keywords\":[\"aleitamento materno\",\"leite materno\",\"microbioma\",\"microbioma intestinal\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/\",\"name\":\"Quais s\u00e3o os fatores que influenciam o microbioma do leite materno? - Nutritotal PRO\",\"isPartOf\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/04\/Nota-2-Microbioma-leite-materno-Destacada.jpg\",\"datePublished\":\"2019-04-15T14:22:17+00:00\",\"dateModified\":\"2023-04-04T18:44:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/#primaryimage\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/04\/Nota-2-Microbioma-leite-materno-Destacada.jpg\",\"contentUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/04\/Nota-2-Microbioma-leite-materno-Destacada.jpg\",\"width\":257,\"height\":165},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nutritotal.com.br\/pro\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quais s\u00e3o os fatores que influenciam o microbioma do leite materno?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"name\":\"Nutritotal PRO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\",\"name\":\"Nutri Total\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"contentUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"width\":426,\"height\":426,\"caption\":\"Nutri Total\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/nutritotalPRO\/\",\"https:\/\/www.instagram.com\/nutritotalpro\/\",\"https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/c168b0202c0b3946a1d52e7de7a04126\",\"name\":\"Nutritotal PRO\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dcd1ba43aaf81b0086ef87608bacee68?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dcd1ba43aaf81b0086ef87608bacee68?s=96&d=mm&r=g\",\"caption\":\"Nutritotal PRO\"},\"url\":\"https:\/\/nutritotal.com.br\/pro\/author\/nicole\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quais s\u00e3o os fatores que influenciam o microbioma do leite materno? - Nutritotal PRO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/","og_locale":"pt_BR","og_type":"article","og_title":"Quais s\u00e3o os fatores que influenciam o microbioma do leite materno?","og_description":"Estudo avaliou amostras de leite materno de 80 lactantes saud\u00e1veis em quatro diferentes pa\u00edses para investigar o potencial de influencia geogr\u00e1fica e do tipo de parto na composi\u00e7\u00e3o do microbioma do leite. De maneira geral, os dois fatores influenciaram a composi\u00e7\u00e3o do microbioma. Foram detectados n\u00edveis de fungos em 16 amostras espanholas, 14 africanas, 9 chinesas e 7 finlandesas, e foram observadas intera\u00e7\u00f5es entre bact\u00e9rias e fungos. A presen\u00e7a de c\u00e9lulas f\u00fangicas sugere uma potencial influ\u00eancia do leite materno no desenvolvimento da micobiota do beb\u00ea. Veja a not\u00edcia completa no portal do Nutritotal Pro.","og_url":"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/","og_site_name":"Nutritotal PRO","article_publisher":"https:\/\/www.facebook.com\/nutritotalPRO\/","article_published_time":"2019-04-15T14:22:17+00:00","article_modified_time":"2023-04-04T18:44:04+00:00","og_image":[{"width":257,"height":165,"url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/04\/Nota-2-Microbioma-leite-materno-Destacada.jpg","type":"image\/jpeg"}],"author":"Nutritotal PRO","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Nutritotal PRO","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/#article","isPartOf":{"@id":"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/"},"author":{"name":"Nutritotal PRO","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/c168b0202c0b3946a1d52e7de7a04126"},"headline":"Quais s\u00e3o os fatores que influenciam o microbioma do leite materno?","datePublished":"2019-04-15T14:22:17+00:00","dateModified":"2023-04-04T18:44:04+00:00","mainEntityOfPage":{"@id":"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/"},"wordCount":426,"commentCount":0,"publisher":{"@id":"https:\/\/nutritotal.com.br\/pro\/#organization"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/#primaryimage"},"thumbnailUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/04\/Nota-2-Microbioma-leite-materno-Destacada.jpg","keywords":["aleitamento materno","leite materno","microbioma","microbioma intestinal"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/","url":"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/","name":"Quais s\u00e3o os fatores que influenciam o microbioma do leite materno? - Nutritotal PRO","isPartOf":{"@id":"https:\/\/nutritotal.com.br\/pro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/#primaryimage"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/#primaryimage"},"thumbnailUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/04\/Nota-2-Microbioma-leite-materno-Destacada.jpg","datePublished":"2019-04-15T14:22:17+00:00","dateModified":"2023-04-04T18:44:04+00:00","breadcrumb":{"@id":"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/#primaryimage","url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/04\/Nota-2-Microbioma-leite-materno-Destacada.jpg","contentUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2019\/04\/Nota-2-Microbioma-leite-materno-Destacada.jpg","width":257,"height":165},{"@type":"BreadcrumbList","@id":"https:\/\/nutritotal.com.br\/pro\/quais-sao-os-fatores-que-influenciam-o-microbioma-do-leite-materno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nutritotal.com.br\/pro\/"},{"@type":"ListItem","position":2,"name":"Quais s\u00e3o os fatores que influenciam o microbioma do leite materno?"}]},{"@type":"WebSite","@id":"https:\/\/nutritotal.com.br\/pro\/#website","url":"https:\/\/nutritotal.com.br\/pro\/","name":"Nutritotal PRO","description":"","publisher":{"@id":"https:\/\/nutritotal.com.br\/pro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nutritotal.com.br\/pro\/#organization","name":"Nutri Total","url":"https:\/\/nutritotal.com.br\/pro\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/","url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","contentUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","width":426,"height":426,"caption":"Nutri Total"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nutritotalPRO\/","https:\/\/www.instagram.com\/nutritotalpro\/","https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA"]},{"@type":"Person","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/c168b0202c0b3946a1d52e7de7a04126","name":"Nutritotal PRO","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dcd1ba43aaf81b0086ef87608bacee68?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dcd1ba43aaf81b0086ef87608bacee68?s=96&d=mm&r=g","caption":"Nutritotal PRO"},"url":"https:\/\/nutritotal.com.br\/pro\/author\/nicole\/"}]}},"views":1025,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/39499"}],"collection":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/users\/112425"}],"replies":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/comments?post=39499"}],"version-history":[{"count":1,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/39499\/revisions"}],"predecessor-version":[{"id":57858,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/39499\/revisions\/57858"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/media\/39501"}],"wp:attachment":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/media?parent=39499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/categories?post=39499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/tags?post=39499"},{"taxonomy":"divisao","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/divisao?post=39499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}