
{"id":53981,"date":"2022-04-11T10:22:44","date_gmt":"2022-04-11T13:22:44","guid":{"rendered":"https:\/\/nutritotal.com.br\/pro\/?p=53981"},"modified":"2023-06-02T09:18:53","modified_gmt":"2023-06-02T12:18:53","slug":"protocolos-no-manejo-da-nutricao-enteral","status":"publish","type":"post","link":"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/","title":{"rendered":"Protocolos no manejo da Nutri\u00e7\u00e3o Enteral"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_75 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Conte\u00fado<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabela de conte\u00fado\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/#Quais_sao_os_criterios_de_indicacao_da_nutricao_enteral\" >Quais s\u00e3o os crit\u00e9rios de indica\u00e7\u00e3o da nutri\u00e7\u00e3o enteral?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/#Como_e_determinada_a_via_de_acesso_para_recebimento_da_nutricao_enteral\" >Como \u00e9 determinada a via de acesso para recebimento da nutri\u00e7\u00e3o enteral?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/#Pacientes_em_uso_de_nutricao_enteral_precisam_receber_agua\" >Pacientes em uso de nutri\u00e7\u00e3o enteral precisam receber \u00e1gua?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/#Como_deve_ser_o_cuidado_diario_com_a_sonda_de_nutricao_enteral\" >Como deve ser o cuidado di\u00e1rio com a sonda de nutri\u00e7\u00e3o enteral?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/#Patrocinio\" >Patroc\u00ednio:<\/a><\/li><\/ul><\/nav><\/div>\n<p>A nutri\u00e7\u00e3o enteral \u00e9 uma estrat\u00e9gia para garantir a oferta de nutrientes a pacientes que, por diversas raz\u00f5es, n\u00e3o conseguem ou n\u00e3o podem se alimentar pela via oral. Estes passam a receber macro e micronutrientes atrav\u00e9s de solu\u00e7\u00f5es que chegam direto ao est\u00f4mago ou intestino.<\/p>\n<p>A desnutri\u00e7\u00e3o hospitalar \u00e9 uma realidade observada a muitos anos, que resulta em maior risco de complica\u00e7\u00f5es, como les\u00f5es por press\u00e3o e infec\u00e7\u00f5es, al\u00e9m de aumento no tempo de interna\u00e7\u00e3o e dos custos hospitalares.<\/p>\n<p>Desta forma, profissionais devem priorizar a preven\u00e7\u00e3o da desnutri\u00e7\u00e3o atrav\u00e9s da oferta de terapia nutricional adequada, incluindo o uso de protocolos pr\u00e9-estabelecidos que garantem o sucesso da nutri\u00e7\u00e3o enteral.<\/p>\n<p><strong> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-53982 size-full\" src=\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/04\/Protocolos-no-Manejo-da-Nutricao-Enteral_site.png\" alt=\"manejo da Nutri\u00e7\u00e3o Enteral\" width=\"1140\" height=\"460\" srcset=\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/04\/Protocolos-no-Manejo-da-Nutricao-Enteral_site.png 1140w, https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/04\/Protocolos-no-Manejo-da-Nutricao-Enteral_site-300x121.png 300w, https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/04\/Protocolos-no-Manejo-da-Nutricao-Enteral_site-1024x413.png 1024w, https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/04\/Protocolos-no-Manejo-da-Nutricao-Enteral_site-768x310.png 768w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" \/><\/strong><\/p>\n<h3><span class=\"ez-toc-section\" id=\"Quais_sao_os_criterios_de_indicacao_da_nutricao_enteral\"><\/span><strong>Quais s\u00e3o os crit\u00e9rios de indica\u00e7\u00e3o da nutri\u00e7\u00e3o enteral? <\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>A nutri\u00e7\u00e3o enteral deve ser indicada na presen\u00e7a de trato gastrointestinal funcionante e impossibilidade de alimenta\u00e7\u00e3o pela via oral ou quando o consumo de alimentos via oral \u00e9 inferior a 60% das necessidades nutricionais do paciente, sendo obrigat\u00f3ria a presen\u00e7a de estabilidade hemodin\u00e2mica para in\u00edcio da terapia.<\/p>\n<p>&nbsp;<\/p>\n<p>Veja com o realizar a <a href=\"https:\/\/nutritotal.com.br\/pro\/tv-nutritotal\/e-na-pratica-como-faz-episodio-3-prescricao-de-dieta-enteral-o-que-voce-precisa-saber\/\"><strong>Prescri\u00e7\u00e3o de dieta enteral<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Como_e_determinada_a_via_de_acesso_para_recebimento_da_nutricao_enteral\"><\/span><strong>Como \u00e9 determinada a via de acesso para recebimento da nutri\u00e7\u00e3o enteral?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>A escolha pelo tipo de acesso pelo qual ser\u00e1 feita a oferta de nutrientes depender\u00e1 de v\u00e1rios fatores e dever\u00e1 levar em considera\u00e7\u00e3o a avalia\u00e7\u00e3o de toda equipe multiprofissional.<\/p>\n<p>Em primeiro lugar, deve-se avaliar a condi\u00e7\u00e3o cl\u00ednica do paciente, bem como a integridade de \u00f3rg\u00e3os necess\u00e1rios a passagem da sonda. Fatores neurol\u00f3gicos tamb\u00e9m devem ser avaliados, visto que em algumas condi\u00e7\u00f5es, pacientes podem puxar sondas nasog\u00e1stricas ou nasoenterais.<\/p>\n<p>O tempo de previsto para uso da sonda tamb\u00e9m deve ser considerado. Normalmente, indica-se a sonda nasog\u00e1strica ou nasoenteral quando for utilizada por per\u00edodo inferior a 4 semanas, sendo conhecidas como sondas de curta perman\u00eancia.<\/p>\n<p>Caso o uso da nutri\u00e7\u00e3o enteral seja superior a 4 semanas, indica-se a utiliza\u00e7\u00e3o de sondas de longa perman\u00eancia, ou seja, atrav\u00e9s das <a href=\"https:\/\/nutritotal.com.br\/pro\/material\/ostomia-o-que-e-e-quais-sao-os-cuidados\/\">ostomias<\/a>.<\/p>\n<p>Vale destacar que, independentemente do tipo de acesso, h\u00e1 alguns cuidados que devem ser tomados para evitar complica\u00e7\u00f5es e garantir o sucesso da terapia nutricional.<\/p>\n<p>&nbsp;<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Pacientes_em_uso_de_nutricao_enteral_precisam_receber_agua\"><\/span><strong>Pacientes em uso de nutri\u00e7\u00e3o enteral precisam receber \u00e1gua? <\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Sim! Deve ser realizado o c\u00e1lculo das necessidades h\u00eddricas do paciente, considerando especifica\u00e7\u00f5es para cada faixa et\u00e1ria, e para <a href=\"https:\/\/nutritotal.com.br\/pro\/como-dever-ser-feito-o-calculo-de-oferta-hidrica-para-pacientes-em-tne\/\">oferta de \u00e1gua<\/a> deve-se considerar: o teor de \u00e1gua da f\u00f3rmula utilizada, total de \u00e1gua que ser\u00e1 utilizado para lavagem da sonda, bem como administra\u00e7\u00e3o de soro.<\/p>\n<p>Assista ao v\u00eddeo <a href=\"https:\/\/nutritotal.com.br\/pro\/tv-nutritotal\/nutricao-enteral-bomba-de-infusao\/\"><strong>\u201cNutri\u00e7\u00e3o Enteral, Bomba de Infus\u00e3o e Hidrata\u00e7\u00e3o: Existe rela\u00e7\u00e3o?\u201d<\/strong><\/a> e conhe\u00e7a estrat\u00e9gias para minimizar complica\u00e7\u00f5es em pacientes que utilizam nutri\u00e7\u00e3o enteral e pr\u00e1ticas seguras para infus\u00e3o de dieta.<\/p>\n<p>&nbsp;<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Como_deve_ser_o_cuidado_diario_com_a_sonda_de_nutricao_enteral\"><\/span><strong>Como deve ser o cuidado di\u00e1rio com a sonda de nutri\u00e7\u00e3o enteral?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>O paciente em uso de nutri\u00e7\u00e3o enteral est\u00e1 sujeito a complica\u00e7\u00f5es caso n\u00e3o seja realizado o manejo adequado.<\/p>\n<p>Essas complica\u00e7\u00f5es podem ser, por exemplo, de origem mec\u00e2nica, como deslocamento, remo\u00e7\u00e3o ou <a href=\"https:\/\/nutritotal.com.br\/pro\/como-deve-ser-tratada-uma-sonda-nasoenteral-obstrua-da\/\">obstru\u00e7\u00e3o da sonda<\/a>; de origem gastrointestinal, como a ocorr\u00eancia de n\u00e1useas, v\u00f4mitos, distens\u00e3o abdominal, diarreia, constipa\u00e7\u00e3o intestinal; de car\u00e1ter pulmonar, como aspira\u00e7\u00e3o e pneumonia; ou metab\u00f3lica, em que se observa altera\u00e7\u00e3o hep\u00e1tica, dos n\u00edveis de hidrata\u00e7\u00e3o, da glicemia ou de eletr\u00f3litos.<\/p>\n<p>Para minimizar o risco de complica\u00e7\u00f5es, alguns cuidados devem ser tomados:<\/p>\n<p>&#8211; Todo material a ser utilizado, bem como a embalagem da dieta deve ser visualmente avaliado quanto a sua integridade e viabilidade para uso antes da administra\u00e7\u00e3o da dieta;<\/p>\n<p>&#8211; A dieta deve ser armazenada de maneira correta, de acordo com as especifica\u00e7\u00f5es da embalagem. Verificar o prazo de validade da dieta ap\u00f3s a instala\u00e7\u00e3o e, no caso de dieta artesanal, cuidados de higiene e manipula\u00e7\u00e3o devem ser rigorosamente seguidos durante todas as etapas de manipula\u00e7\u00e3o.<\/p>\n<p>&#8211; A lavagem da sonda deve ocorrer sempre que houver pausa na administra\u00e7\u00e3o da dieta, antes e ap\u00f3s a administra\u00e7\u00e3o de medicamentos.<\/p>\n<p>No quadro abaixo, voc\u00ea pode verificar algumas poss\u00edveis complica\u00e7\u00f5es e como devem ser conduzidas:<\/p>\n<p>&nbsp;<\/p>\n<table width=\"680\">\n<tbody>\n<tr>\n<td width=\"113\"><strong>COMPLICA\u00c7\u00c3O<\/strong><\/td>\n<td width=\"189\"><strong>CAUSA<\/strong><\/td>\n<td width=\"189\"><strong>SINAL<\/strong><\/td>\n<td width=\"189\"><strong>O QUE FAZER?<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"113\">Sa\u00edda ou migra\u00e7\u00e3o acidental da sonda<\/td>\n<td width=\"189\">&#8211; Paciente muito agitado ou com altera\u00e7\u00f5es neurol\u00f3gicas<\/p>\n<p>&nbsp;<\/td>\n<td width=\"189\">&#8211; Sa\u00edda da fixa\u00e7\u00e3o da sonda<\/p>\n<p>&#8211; Marca\u00e7\u00e3o da sonda fora do lugar<\/td>\n<td width=\"189\">&#8211; Acionar m\u00e9dico ou enfermeiro para que realize uma nova passagem da sonda<\/td>\n<\/tr>\n<tr>\n<td width=\"113\">Obstru\u00e7\u00e3o da sonda<\/p>\n<p>&nbsp;<\/td>\n<td width=\"189\">&#8211; Dietas com densidade cal\u00f3rica de 2,0kcal\/ml, com alta viscosidade e com gotejamento lento<\/p>\n<p>-Utiliza\u00e7\u00e3o de fibras nas dietas<\/p>\n<p>-Lavagem incorreta da sonda ap\u00f3s a infus\u00e3o de dieta ou medicamentos<\/p>\n<p>-Dobramento e no\u0301 na sonda<\/p>\n<p>&nbsp;<\/td>\n<td width=\"189\">-Ressecamento de sonda e vazamento de dieta<\/p>\n<p>&#8211; Dificuldade para infundir dieta e \u00e1gua<\/p>\n<p>&#8211; Sinaliza\u00e7\u00e3o sonora da bomba de infus\u00e3o<\/td>\n<td width=\"189\">-Avaliar velocidade de infus\u00e3o da dieta<\/p>\n<p>&#8211; Realizar a limpeza adequada da sonda, atrav\u00e9s da infus\u00e3o de \u00e1gua a cada 4 horas<\/p>\n<p>&#8211; Comunicar a equipe e verificar a possibilidade de tentar a desobstru\u00e7\u00e3o utilizando \u00e1gua sob press\u00e3o, \u00e1gua morna, pastilha de vitamina C ou solu\u00e7\u00e3o de bicarbonato<\/td>\n<\/tr>\n<tr>\n<td width=\"113\">Na\u0301useas e vo\u0302mitos<\/p>\n<p>&nbsp;<\/td>\n<td width=\"189\">&#8211; Infus\u00e3o r\u00e1pida da dieta<\/p>\n<p>&#8211; Presen\u00e7a de altera\u00e7\u00f5es no funcionamento do est\u00f4mago e\/ou intestino<\/p>\n<p>&nbsp;<\/td>\n<td width=\"189\">&#8211; Presen\u00e7a de empachamento e distens\u00e3o abdominal<\/p>\n<p>&#8211; Presen\u00e7a de refluxo gastroesofa\u0301gico<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/td>\n<td width=\"189\">&#8211; Comunicar equipe para avalia\u00e7\u00e3o de posicionamento da sonda,<\/p>\n<p>&#8211; Manter cabeceira elevada;<\/p>\n<p>&#8211; Administrar a dieta de forma mais lenta (uso de bomba de infus\u00e3o pode contribuir para o controle)<\/p>\n<p>&#8211; Reduzir volume de dieta<\/td>\n<\/tr>\n<tr>\n<td width=\"113\">Co\u0301licas, empachamento, flatule\u0302ncia<\/p>\n<p>&nbsp;<\/td>\n<td width=\"189\">&#8211; Oferta de grandes volumes de dieta<\/p>\n<p>&#8211; Infus\u00e3o r\u00e1pida da dieta<\/p>\n<p>&#8211; Infus\u00e3o de dietas que n\u00e3o est\u00e3o em temperatura ambiente<\/p>\n<p>&nbsp;<\/td>\n<td width=\"189\">&#8211; Paciente agitado e demonstrando sinais de dor<\/p>\n<p>&#8211; Distens\u00e3o abdominal<\/td>\n<td width=\"189\">&#8211; Manter cabeceiras elevadas<\/p>\n<p>&#8211; Administrar a dieta de forma mais lenta<\/p>\n<p>&#8211; Reduzir volume de dieta<\/p>\n<p>&#8211; N\u00e3o administrar dietas geladas<\/p>\n<p>&nbsp;<\/td>\n<\/tr>\n<tr>\n<td width=\"113\">Diarreia<\/p>\n<p>&nbsp;<\/td>\n<td width=\"189\">&#8211; Infusa\u0303o ra\u0301pida da fo\u0301rmula<\/p>\n<p>&#8211; Infus\u00e3o de dietas que n\u00e3o est\u00e3o em temperatura ambiente<\/p>\n<p>&#8211; Dieta contaminada por manipula\u00e7\u00e3o incorreta<\/p>\n<p>&#8211; Uso de certas medica\u00e7\u00f5es<\/p>\n<p>&nbsp;<\/td>\n<td width=\"189\">&#8211; Presen\u00e7a de 3 ou mais evacua\u00e7\u00f5es l\u00edquidas ao dia<\/td>\n<td width=\"189\">&#8211; Realizar hidrata\u00e7\u00e3o adequada e verificar necessidade de aumentar oferta de l\u00edquidos<\/p>\n<p>&#8211; Comunicar equipe de sa\u00fade<\/p>\n<p>&#8211; Reduzir volume de dieta oferecido<\/p>\n<p>&#8211; Associar fibras<\/p>\n<p>&#8211; Verificar a necessidade de alterar m\u00e9todo de infus\u00e3o<\/p>\n<p>&#8211; Avaliar medicamentos em uso<\/p>\n<p>&#8211; Infundir dieta em temperatura ambiente<\/p>\n<p>&#8211; Refor\u00e7ar medidas de higiene<\/p>\n<p>&#8211; Discutir com os profissionais a necessidade de altera\u00e7\u00e3o da dieta<\/td>\n<\/tr>\n<tr>\n<td width=\"113\">Obstipac\u0327a\u0303o \/ constipa\u00e7\u00e3o<\/td>\n<td width=\"189\">&#8211; Movimenta\u00e7\u00e3o reduzida do paciente (indiv\u00edduos acamados)<\/p>\n<p>&#8211; Oferta inadequada de l\u00edquidos<\/p>\n<p>&#8211; N\u00e3o oferta de fibras<\/p>\n<p>&#8211; Uso de algumas medica\u00e7\u00f5es<\/p>\n<p>&nbsp;<\/td>\n<td width=\"189\">Aus\u00eancia de evacua\u00e7\u00e3o por 2 ou mais dias seguidos<\/td>\n<td width=\"189\">&#8211; Verificar com a equipe a possibilidade de aumentar a oferta de l\u00edquidos<\/p>\n<p>&#8211; Verificar a possibilidade da utiliza\u00e7\u00e3o de fibras e probi\u00f3ticos<\/p>\n<p>&#8211; Quando poss\u00edvel e se poss\u00edvel estimular movimenta\u00e7\u00e3o do paciente<\/p>\n<p>&#8211; Verificar necessidade de uso de medicamentos laxativos, caso a complica\u00e7\u00e3o n\u00e3o seja solucionada<\/td>\n<\/tr>\n<tr>\n<td width=\"113\">Desidratac\u0327a\u0303o<\/td>\n<td width=\"189\">&#8211; Presen\u00e7a de diarreia, v\u00f4mito, febre<br \/>\n&#8211; Baixa oferta de \u00e1gua<\/td>\n<td width=\"189\">&#8211; Sede<\/p>\n<p>&#8211; Pele seca e\/ou descamando<\/p>\n<p>&#8211; Paciente confuso e prostrado<\/td>\n<td width=\"189\">&#8211; Verificar se oferta h\u00eddrica est\u00e1 acontecendo corretamente<\/p>\n<p>&#8211; Verificar com a equipe a necessidade de aumentar ingest\u00e3o de l\u00edquidos<\/p>\n<p>&#8211; Controlar complica\u00e7\u00f5es que causam a desidrata\u00e7\u00e3o (diarreia, v\u00f4mito, febre)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>Veja tamb\u00e9m: <a href=\"https:\/\/nutritotal.com.br\/pro\/tv-nutritotal\/conexao-segura-para-nutricao-enteral\/\"><strong>Conex\u00e3o segura para Nutri\u00e7\u00e3o Enteral<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Manejo da Nutri\u00e7\u00e3o enteral: quando deve ocorrer a troca da sonda? <\/strong><\/p>\n<p>O cuidado com sondas, equipos, conectores e frascos de dieta deve seguir protocolos de manejo de nutri\u00e7\u00e3o enteral determinados para cada institui\u00e7\u00e3o, mas sempre guiados pelas informa\u00e7\u00f5es dos fabricantes.<\/p>\n<p>Importante destacar que a durabilidade depender\u00e1 dos cuidados na manipula\u00e7\u00e3o, inclu\u00eddo cuidados de higiene, e da qualidade do material utilizado.<\/p>\n<p>Veja algumas recomenda\u00e7\u00f5es:<\/p>\n<p><strong>&#8211; Sondas de curta dura\u00e7\u00e3o:<\/strong> deve ser seguir a recomenda\u00e7\u00e3o do fabricante ou ser substitu\u00edda em casos de deteriora\u00e7\u00e3o do material ou qualquer outra intercorr\u00eancia, como retirada ou obstru\u00e7\u00e3o da sonda.<\/p>\n<p><strong>&#8211; Sonda de longa perman\u00eancia:<\/strong> podem ter validade de at\u00e9 12 meses, mas dever\u00e1 ser substitu\u00edda sempre que houver alguma intercorr\u00eancia, como rompimento do bal\u00e3o interno, ruptura do trato estomacal, f\u00edstulas gastroc\u00f3licas ou colocut\u00e2neas e complica\u00e7\u00f5es da regi\u00e3o periestomal, como infec\u00e7\u00e3o periestomal recorrente, escoria\u00e7\u00f5es e \u00falceras de dif\u00edcil cicatriza\u00e7\u00e3o<\/p>\n<p>Para saber mais, assista ao v\u00eddeo: <a href=\"https:\/\/nutritotal.com.br\/pro\/tv-nutritotal\/sondas-de-longa-permanencia\/\"><strong>Indica\u00e7\u00e3o, tipos e import\u00e2ncia das sondas de longa perman\u00eancia<\/strong><\/a><\/p>\n<p><strong>&#8211; Frascos de nutri\u00e7\u00e3o para uso em sistema aberto<\/strong>: recomenda-se a troca a cada 4 horas ap\u00f3s a instala\u00e7\u00e3o<\/p>\n<p><strong>&#8211; Frascos de sistema fechado:<\/strong> seguir recomenda\u00e7\u00e3o do fabricante (normalmente deve ser descartado ap\u00f3s 24 horas da instala\u00e7\u00e3o)<\/p>\n<p><strong>&#8211; Equipos (sistema fechado e aberto):<\/strong>\u00a0 a troca dever\u00e1 ocorrer a cada 24h, desde que os protocolos para lavagem da sonda sejam seguidos corretamente a cada troca de dieta e administra\u00e7\u00e3o da medica\u00e7\u00e3o<\/p>\n<p><strong>&#8211; Conectores em Y: <\/strong>a troca deve seguir as recomenda\u00e7\u00f5es dos fabricantes ou protocolos institucionais para instala\u00e7\u00e3o e higieniza\u00e7\u00e3o<\/p>\n<p>&nbsp;<\/p>\n<p>Profissionais que trabalham com terapia nutricional devem estar sempre atentos aos protocolos de manejo de nutri\u00e7\u00e3o enteral, assim evita-se a ocorr\u00eancia de complica\u00e7\u00f5es, visando o maior sucesso da terapia para o paciente.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Patrocinio\"><\/span>Patroc\u00ednio:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><a href=\"https:\/\/www.cardinalhealth.com.br\/pt_br.html\" class=\"broken_link\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-53999\" src=\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/04\/logo_cardinalhealth.png\" alt=\"\" width=\"181\" height=\"57\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Refer\u00eancias: <\/strong><\/p>\n<p>DUNN, Sasha. <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/26087203\/\">Maintaining adequate hydration and nutrition in adult enteral tube feeding<\/a>. British Journal Of Community Nursing, [s.l.], v. 20, n. 6, p.18-23, jun. 2015<\/p>\n<p>MATSUBA, Claudia S. Takemura et al. \u00a0<a href=\"https:\/\/www.braspen.org\/_files\/ugd\/66b28c_8ff5068bd2574851b9d61a73c3d6babf.pdf\">Diretriz BRASPEN de Enfermagem em Terapia Nutricional Oral, Enteral e Parenteral<\/a>. BRASPEN J, v. 36, supl.3, p.2-62, 2021.<\/p>\n<p>Waitzberg, Dan L. Nutri\u00e7\u00e3o Oral, Enteral e Parenteral na Pr\u00e1tica Cl\u00ednica. 5ed. Rio de Janeiro: Atheneu, 2017.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A nutri\u00e7\u00e3o enteral \u00e9 uma estrat\u00e9gia para garantir a oferta de nutrientes a pacientes que, por diversas raz\u00f5es, n\u00e3o conseguem ou n\u00e3o podem se alimentar pela via oral. Estes passam a receber macro e micronutrientes atrav\u00e9s de solu\u00e7\u00f5es que chegam direto ao est\u00f4mago ou intestino. A desnutri\u00e7\u00e3o hospitalar \u00e9 uma realidade observada a muitos anos, [&hellip;]<\/p>\n","protected":false},"author":115168,"featured_media":53983,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[576],"tags":[427,178,2406,195,194],"divisao":[2185,3327],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Protocolos no manejo da Nutri\u00e7\u00e3o Enteral - Nutritotal PRO<\/title>\n<meta name=\"description\" content=\"O manejo da nutri\u00e7\u00e3o enteral garante o sucesso da terapia e contribui para que o paciente receba adequadamente os nutrientes que necessitam.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Protocolos no manejo da Nutri\u00e7\u00e3o Enteral - Nutritotal PRO\" \/>\n<meta property=\"og:description\" content=\"O manejo da nutri\u00e7\u00e3o enteral garante o sucesso da terapia e contribui para que o paciente receba adequadamente os nutrientes que necessitam.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/\" \/>\n<meta property=\"og:site_name\" content=\"Nutritotal PRO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nutritotalPRO\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-11T13:22:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-02T12:18:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/04\/Protocolos-no-Manejo-da-Nutricao-Enteral_destacada.png\" \/>\n\t<meta property=\"og:image:width\" content=\"582\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nat\u00e1lia C Lopes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nat\u00e1lia C Lopes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/\"},\"author\":{\"name\":\"Nat\u00e1lia C Lopes\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/baad02eb88d6c284f9dd88cbfefeaa41\"},\"headline\":\"Protocolos no manejo da Nutri\u00e7\u00e3o Enteral\",\"datePublished\":\"2022-04-11T13:22:44+00:00\",\"dateModified\":\"2023-06-02T12:18:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/\"},\"wordCount\":1757,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/04\/Protocolos-no-Manejo-da-Nutricao-Enteral_destacada.png\",\"keywords\":[\"alimenta\u00e7\u00e3o\",\"dieta\",\"dieta enteral\",\"Enteral\",\"nutri\u00e7\u00e3o enteral\"],\"articleSection\":[\"Nutri\u00e7\u00e3o Enteral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/\",\"name\":\"Protocolos no manejo da Nutri\u00e7\u00e3o Enteral - Nutritotal PRO\",\"isPartOf\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/04\/Protocolos-no-Manejo-da-Nutricao-Enteral_destacada.png\",\"datePublished\":\"2022-04-11T13:22:44+00:00\",\"dateModified\":\"2023-06-02T12:18:53+00:00\",\"description\":\"O manejo da nutri\u00e7\u00e3o enteral garante o sucesso da terapia e contribui para que o paciente receba adequadamente os nutrientes que necessitam.\",\"breadcrumb\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/#primaryimage\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/04\/Protocolos-no-Manejo-da-Nutricao-Enteral_destacada.png\",\"contentUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/04\/Protocolos-no-Manejo-da-Nutricao-Enteral_destacada.png\",\"width\":582,\"height\":400,\"caption\":\"manejo da Nutri\u00e7\u00e3o Enteral\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nutritotal.com.br\/pro\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Protocolos no manejo da Nutri\u00e7\u00e3o Enteral\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"name\":\"Nutritotal PRO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\",\"name\":\"Nutri Total\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"contentUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"width\":426,\"height\":426,\"caption\":\"Nutri Total\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/nutritotalPRO\/\",\"https:\/\/www.instagram.com\/nutritotalpro\/\",\"https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/baad02eb88d6c284f9dd88cbfefeaa41\",\"name\":\"Nat\u00e1lia C Lopes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2f49bf58d72bf06cd94e17dde6fd8043?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2f49bf58d72bf06cd94e17dde6fd8043?s=96&d=mm&r=g\",\"caption\":\"Nat\u00e1lia C Lopes\"},\"description\":\"Nutricionista pelo Centro Universit\u00e1rio S\u00e3o Camilo. Mestranda pela Faculdade de Medicina da Universidade de S\u00e3o Paulo \u2013 FMUSP. Especializa\u00e7\u00e3o em Obesidade, Emagrecimento e Sa\u00fade pela Unifesp. Tutora de cursos EAD do Ganep Educa\u00e7\u00e3o. Coordenadora do Nutritotal.\",\"sameAs\":[\"@nutrinatalialopes\",\"https:\/\/www.linkedin.com\/in\/nataliaclopes\"],\"url\":\"https:\/\/nutritotal.com.br\/pro\/author\/nataliaclopes\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Protocolos no manejo da Nutri\u00e7\u00e3o Enteral - Nutritotal PRO","description":"O manejo da nutri\u00e7\u00e3o enteral garante o sucesso da terapia e contribui para que o paciente receba adequadamente os nutrientes que necessitam.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/","og_locale":"pt_BR","og_type":"article","og_title":"Protocolos no manejo da Nutri\u00e7\u00e3o Enteral - Nutritotal PRO","og_description":"O manejo da nutri\u00e7\u00e3o enteral garante o sucesso da terapia e contribui para que o paciente receba adequadamente os nutrientes que necessitam.","og_url":"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/","og_site_name":"Nutritotal PRO","article_publisher":"https:\/\/www.facebook.com\/nutritotalPRO\/","article_published_time":"2022-04-11T13:22:44+00:00","article_modified_time":"2023-06-02T12:18:53+00:00","og_image":[{"width":582,"height":400,"url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/04\/Protocolos-no-Manejo-da-Nutricao-Enteral_destacada.png","type":"image\/png"}],"author":"Nat\u00e1lia C Lopes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Nat\u00e1lia C Lopes","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/#article","isPartOf":{"@id":"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/"},"author":{"name":"Nat\u00e1lia C Lopes","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/baad02eb88d6c284f9dd88cbfefeaa41"},"headline":"Protocolos no manejo da Nutri\u00e7\u00e3o Enteral","datePublished":"2022-04-11T13:22:44+00:00","dateModified":"2023-06-02T12:18:53+00:00","mainEntityOfPage":{"@id":"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/"},"wordCount":1757,"commentCount":0,"publisher":{"@id":"https:\/\/nutritotal.com.br\/pro\/#organization"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/#primaryimage"},"thumbnailUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/04\/Protocolos-no-Manejo-da-Nutricao-Enteral_destacada.png","keywords":["alimenta\u00e7\u00e3o","dieta","dieta enteral","Enteral","nutri\u00e7\u00e3o enteral"],"articleSection":["Nutri\u00e7\u00e3o Enteral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/","url":"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/","name":"Protocolos no manejo da Nutri\u00e7\u00e3o Enteral - Nutritotal PRO","isPartOf":{"@id":"https:\/\/nutritotal.com.br\/pro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/#primaryimage"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/#primaryimage"},"thumbnailUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/04\/Protocolos-no-Manejo-da-Nutricao-Enteral_destacada.png","datePublished":"2022-04-11T13:22:44+00:00","dateModified":"2023-06-02T12:18:53+00:00","description":"O manejo da nutri\u00e7\u00e3o enteral garante o sucesso da terapia e contribui para que o paciente receba adequadamente os nutrientes que necessitam.","breadcrumb":{"@id":"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/#primaryimage","url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/04\/Protocolos-no-Manejo-da-Nutricao-Enteral_destacada.png","contentUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/04\/Protocolos-no-Manejo-da-Nutricao-Enteral_destacada.png","width":582,"height":400,"caption":"manejo da Nutri\u00e7\u00e3o Enteral"},{"@type":"BreadcrumbList","@id":"https:\/\/nutritotal.com.br\/pro\/protocolos-no-manejo-da-nutricao-enteral\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nutritotal.com.br\/pro\/"},{"@type":"ListItem","position":2,"name":"Protocolos no manejo da Nutri\u00e7\u00e3o Enteral"}]},{"@type":"WebSite","@id":"https:\/\/nutritotal.com.br\/pro\/#website","url":"https:\/\/nutritotal.com.br\/pro\/","name":"Nutritotal PRO","description":"","publisher":{"@id":"https:\/\/nutritotal.com.br\/pro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nutritotal.com.br\/pro\/#organization","name":"Nutri Total","url":"https:\/\/nutritotal.com.br\/pro\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/","url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","contentUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","width":426,"height":426,"caption":"Nutri Total"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nutritotalPRO\/","https:\/\/www.instagram.com\/nutritotalpro\/","https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA"]},{"@type":"Person","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/baad02eb88d6c284f9dd88cbfefeaa41","name":"Nat\u00e1lia C Lopes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2f49bf58d72bf06cd94e17dde6fd8043?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2f49bf58d72bf06cd94e17dde6fd8043?s=96&d=mm&r=g","caption":"Nat\u00e1lia C Lopes"},"description":"Nutricionista pelo Centro Universit\u00e1rio S\u00e3o Camilo. Mestranda pela Faculdade de Medicina da Universidade de S\u00e3o Paulo \u2013 FMUSP. Especializa\u00e7\u00e3o em Obesidade, Emagrecimento e Sa\u00fade pela Unifesp. Tutora de cursos EAD do Ganep Educa\u00e7\u00e3o. Coordenadora do Nutritotal.","sameAs":["@nutrinatalialopes","https:\/\/www.linkedin.com\/in\/nataliaclopes"],"url":"https:\/\/nutritotal.com.br\/pro\/author\/nataliaclopes\/"}]}},"views":21860,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/53981"}],"collection":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/users\/115168"}],"replies":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/comments?post=53981"}],"version-history":[{"count":1,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/53981\/revisions"}],"predecessor-version":[{"id":60471,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/53981\/revisions\/60471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/media\/53983"}],"wp:attachment":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/media?parent=53981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/categories?post=53981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/tags?post=53981"},{"taxonomy":"divisao","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/divisao?post=53981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}