
{"id":63437,"date":"2023-09-04T10:00:01","date_gmt":"2023-09-04T13:00:01","guid":{"rendered":"https:\/\/nutritotal.com.br\/pro\/?p=63437"},"modified":"2023-09-01T10:21:34","modified_gmt":"2023-09-01T13:21:34","slug":"comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos","status":"publish","type":"post","link":"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/","title":{"rendered":"Comer oleaginosas melhora a fun\u00e7\u00e3o vascular cerebral e a mem\u00f3ria de idosos"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_75 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Conte\u00fado<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabela de conte\u00fado\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/#Marcador_para_saude_cerebral_e_criterios_da_pesquisa\" >Marcador para sa\u00fade cerebral e crit\u00e9rios da pesquisa<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/#Qual_o_papel_das_oleaginosas\" >Qual o papel das oleaginosas?<\/a><\/li><\/ul><\/nav><\/div>\n<p>No consult\u00f3rio, no atendimento domiciliar ou na alta hospitalar \u00e9 comum que os nutricionistas indiquem aos seus pacientes o consumo frequente de oleaginosas, essa orienta\u00e7\u00e3o \u00e9 muitas vezes pautada no teor nutricional das nozes e castanhas.<\/p>\n<p>Mas, voc\u00ea sabe exatamente como as oleaginosas atuam na sa\u00fade? Pesquisadores revelaram que comer oleaginosas pode melhorar a fun\u00e7\u00e3o cerebral, especialmente a mem\u00f3ria de idosos.<\/p>\n<p>Nas oleaginosas s\u00e3o encontrados \u00e1cidos graxos insaturados, polifen\u00f3is, fibras, <a href=\"https:\/\/nutritotal.com.br\/pro\/fitoesterois-e-saude-cardiovascular-quais-os-niveis-de-evidencia\/\">fitoester\u00f3is<\/a>, tocofer\u00f3is e prote\u00ednas que demonstram relev\u00e2ncia \u00e0 sa\u00fade cognitiva.<\/p>\n<p>Os resultados sobre o consumo desses alimentos podem n\u00e3o ser observados com tanta clareza em pessoas saud\u00e1veis, mas quando falamos de pessoas com risco de decl\u00ednio cognitivo, como os idosos, os achados revelam que o consumo de oleaginosas \u00e9 uma interven\u00e7\u00e3o valiosa.<\/p>\n<p>Mas quais mecanismos comprovam tal efic\u00e1cia? Foi essa a pergunta que pesquisadores da Holanda decidiram responder para completar o quebra-cabe\u00e7as da rela\u00e7\u00e3o entre oleaginosas e fun\u00e7\u00e3o cerebral.<\/p>\n<div id=\"attachment_63438\" style=\"width: 1160px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-63438\" class=\"wp-image-63438 size-full\" src=\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2023\/08\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos.png\" alt=\"oleaginosas e fun\u00e7\u00e3o cerebral\" width=\"1150\" height=\"460\" srcset=\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2023\/08\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos.png 1150w, https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2023\/08\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos-300x120.png 300w, https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2023\/08\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos-1024x410.png 1024w, https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2023\/08\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos-768x307.png 768w\" sizes=\"(max-width: 1150px) 100vw, 1150px\" \/><p id=\"caption-attachment-63438\" class=\"wp-caption-text\">Fonte: Canva.com<\/p><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Marcador_para_saude_cerebral_e_criterios_da_pesquisa\"><\/span>Marcador para sa\u00fade cerebral e crit\u00e9rios da pesquisa<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Os pesquisadores da Metabolic Research Unit Maastricht escolheram um marcador fisiol\u00f3gico essencial para a sa\u00fade cerebral para avaliar o efeito das oleaginosas. O marcador escolhido foi o fluxo sangu\u00edneo cerebral total que permite compreender os efeitos nas art\u00e9rias centrais que est\u00e3o mais diretamente associadas ao desempenho cognitivo.<\/p>\n<p>Dessa forma, foram para al\u00e9m dos efeitos j\u00e1 conhecidos das oleaginosas nas art\u00e9rias perif\u00e9ricas. O fluxo sangu\u00edneo foi avaliado a partir de resson\u00e2ncia magn\u00e9tica com um m\u00e9todo que gera resultados mais robustos e al\u00e9m dele outros crit\u00e9rios foram escolhidos para aumentar a validade do estudo.<\/p>\n<p>O estudo foi cruzado, randomizado, controlado, simples-cego com um per\u00edodo de interven\u00e7\u00e3o e controle de 16 semanas, separados por um per\u00edodo de <em>washout <\/em>de 8 semanas. Os participantes consumiram 60 g de oleaginosas sem sal e sem torra, o que corresponderia por 15% da ingest\u00e3o cal\u00f3rica di\u00e1ria.<\/p>\n<p>Cada sach\u00ea continha 15 g de <a href=\"https:\/\/nutritotal.com.br\/pro\/quais-sao-as-propriedades-nutricionais-das-nozes\/\">nozes<\/a>, 15 g de castanha de caju, 15 g de avel\u00e3 e 15 g de pistache. O grupo analisado tamb\u00e9m foi orientado a seguir as diretrizes para alimenta\u00e7\u00e3o saud\u00e1vel da Holanda e tinham alguns itens aliment\u00edcios proibidos nesse per\u00edodo.<\/p>\n<p>Nos controles, realizados no in\u00edcio, no meio e no final do estudo, os participantes tinham suas medidas antropom\u00e9tricas aferidas, respondiam um QFA e recebiam avalia\u00e7\u00f5es do desempenho cognitivo. Ao final, a popula\u00e7\u00e3o que completou a pesquisa foi de 28 idosos, sendo 14 homens e 14 mulheres com idade m\u00e9dia de 64,6 anos.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Qual_o_papel_das_oleaginosas\"><\/span>Qual o papel das oleaginosas?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Mesmo com uma orienta\u00e7\u00e3o de dieta mais criteriosa, os participantes apresentaram uma <a href=\"https:\/\/nutritotal.com.br\/pro\/material\/como-melhorar-a-adesao-do-paciente-ao-plano-alimentar\/\">excelente ades\u00e3o<\/a> \u00e0s exig\u00eancias do estudo. O maior consumo de oleaginosas promoveu uma menor ingest\u00e3o de carboidrato e de colesterol com aumento na <a href=\"https:\/\/nutritotal.com.br\/pro\/fibras-alimentares-podem-ajudar-a-baixar-o-colesterol-tipo-ldl-sa-rico\/\">ingest\u00e3o de fibras<\/a>.<\/p>\n<p>O fluxo sangu\u00edneo cerebral apresentou aumento com a ingest\u00e3o do mix de nozes nos lobos frontal direito e parietal (efeito do tratamento: 5,0 \u00b1 6,5 mL\/100 g\/min; P &lt; 0,001), lobo frontal esquerdo (5,4 \u00b1 7,1 mL\/100 g\/min; P &lt; 0,001) e c\u00f3rtex pr\u00e9-frontal bilateral (5,6 \u00b1 6,6 mL\/100 g\/min; P &lt; 0,001). Tamb\u00e9m foram observadas melhora nas mem\u00f3rias visuoespacial (\u22124 erros [16%]; IC95%: \u22128 a 0; P = 0,045) e verbal (+1 correto [16%]; 0 a 2; P = 0,035).<\/p>\n<p>Segundo os estudiosos, os achados que justificam os efeitos das oleaginosas na fun\u00e7\u00e3o cerebral s\u00e3o a presen\u00e7a de componentes bioativos espec\u00edficos nas oleaginosas, como os polifen\u00f3is, que aumentam a biodisponibilidade de \u00f3xido n\u00edtrico (NO), melhorando o fluxo sangu\u00edneo cerebral em regi\u00f5es do c\u00e9rebro que s\u00e3o importantes para os processos cognitivos, como a mem\u00f3ria.<\/p>\n<p>Se voc\u00ea j\u00e1 orientava o consumo de oleaginosas variadas, como nozes e diferentes castanhas, pode continuar fazendo. E, se o seu paciente for idoso, agora voc\u00ea sabe que a recomenda\u00e7\u00e3o pode ser muito importante para prevenir e melhorar os efeitos do <a href=\"https:\/\/nutritotal.com.br\/pro\/alimentacao-previne-declinio-cognitivo\/\">decl\u00ednio cognitivo<\/a> que aparecem com o avan\u00e7o da idade.<\/p>\n<p><strong>Gostou desse conte\u00fado? Apostamos que voc\u00ea vai querer ler esses:<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/nutritotal.com.br\/pro\/efeitos-da-suplementacao-de-acidos-graxos-e-carotenoides-na-memoria-de-idosos\/\">Efeitos da suplementa\u00e7\u00e3o de \u00e1cidos graxos e caroten\u00f3ides na mem\u00f3ria de idosos<\/a><\/li>\n<li><a href=\"https:\/\/nutritotal.com.br\/pro\/guideline-oms-reducao-do-risco-de-declinio-cognitivo-e-demencia\/\">Suplementa\u00e7\u00e3o de vitaminas e dem\u00eancias<\/a><\/li>\n<li><a href=\"https:\/\/nutritotal.com.br\/pro\/material\/tabela-de-composicao-nutricional-frutas-secas-e-oleaginosas\/\">Tabela de composi\u00e7\u00e3o nutricional: frutas secas e oleaginosas<\/a><\/li>\n<\/ul>\n<p><strong>Refer\u00eancia<\/strong><\/p>\n<p>Nijssen, Kevin MR, et al. <a href=\"https:\/\/www.clinicalnutritionjournal.com\/article\/S0261-5614(23)00167-X\/fulltext#secsectitle0010\" class=\"broken_link\"><strong>&#8220;Longer-term mixed nut consumption improves brain vascular function and memory: a randomized, controlled crossover trial in older adults.&#8221;<\/strong><\/a> Clinical Nutrition (2023).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No consult\u00f3rio, no atendimento domiciliar ou na alta hospitalar \u00e9 comum que os nutricionistas indiquem aos seus pacientes o consumo frequente de oleaginosas, essa orienta\u00e7\u00e3o \u00e9 muitas vezes pautada no teor nutricional das nozes e castanhas. Mas, voc\u00ea sabe exatamente como as oleaginosas atuam na sa\u00fade? Pesquisadores revelaram que comer oleaginosas pode melhorar a fun\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":114981,"featured_media":63440,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3237,3239],"tags":[1100,3446,3445,932,1782],"divisao":[3163,2186,3232],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comer oleaginosas melhora a fun\u00e7\u00e3o vascular cerebral e a mem\u00f3ria de idosos<\/title>\n<meta name=\"description\" content=\"Descubra como as oleaginosas podem impulsionar a sa\u00fade cerebral e a mem\u00f3ria em idosos. Entenda os mecanismos por tr\u00e1s desses efeitos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comer oleaginosas melhora a fun\u00e7\u00e3o vascular cerebral e a mem\u00f3ria de idosos\" \/>\n<meta property=\"og:description\" content=\"Descubra como as oleaginosas podem impulsionar a sa\u00fade cerebral e a mem\u00f3ria em idosos. Entenda os mecanismos por tr\u00e1s desses efeitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/\" \/>\n<meta property=\"og:site_name\" content=\"Nutritotal PRO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nutritotalPRO\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/nutritotalPRO\/?ref=pages_you_manage&amp;_rdc=1&amp;_rdr\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-04T13:00:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-01T13:21:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2023\/09\/oleaginosas-e-funcao-cerebral.png\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Nutritotal PRO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Nutritotal PRO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Nutritotal PRO\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/ebc724f6275a533739e9d1ad603f21a2\"},\"headline\":\"Comer oleaginosas melhora a fun\u00e7\u00e3o vascular cerebral e a mem\u00f3ria de idosos\",\"datePublished\":\"2023-09-04T13:00:01+00:00\",\"dateModified\":\"2023-09-01T13:21:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/\"},\"wordCount\":753,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2023\/09\/oleaginosas-e-funcao-cerebral.png\",\"keywords\":[\"castanhas\",\"cogni\u00e7\u00e3o\",\"mem\u00f3ria\",\"nozes\",\"oleaginosas\"],\"articleSection\":[\"Longevidade\",\"Nutri\u00e7\u00e3o em consult\u00f3rio\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/\",\"name\":\"Comer oleaginosas melhora a fun\u00e7\u00e3o vascular cerebral e a mem\u00f3ria de idosos\",\"isPartOf\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2023\/09\/oleaginosas-e-funcao-cerebral.png\",\"datePublished\":\"2023-09-04T13:00:01+00:00\",\"dateModified\":\"2023-09-01T13:21:34+00:00\",\"description\":\"Descubra como as oleaginosas podem impulsionar a sa\u00fade cerebral e a mem\u00f3ria em idosos. Entenda os mecanismos por tr\u00e1s desses efeitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/#primaryimage\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2023\/09\/oleaginosas-e-funcao-cerebral.png\",\"contentUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2023\/09\/oleaginosas-e-funcao-cerebral.png\",\"width\":580,\"height\":400,\"caption\":\"Fonte: Canva.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nutritotal.com.br\/pro\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comer oleaginosas melhora a fun\u00e7\u00e3o vascular cerebral e a mem\u00f3ria de idosos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#website\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"name\":\"Nutritotal PRO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#organization\",\"name\":\"Nutri Total\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"contentUrl\":\"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png\",\"width\":426,\"height\":426,\"caption\":\"Nutri Total\"},\"image\":{\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/nutritotalPRO\/\",\"https:\/\/www.instagram.com\/nutritotalpro\/\",\"https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/ebc724f6275a533739e9d1ad603f21a2\",\"name\":\"Reda\u00e7\u00e3o Nutritotal PRO\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0b28a44567fd9e96213e21d1d40eeb15?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0b28a44567fd9e96213e21d1d40eeb15?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o Nutritotal PRO\"},\"description\":\"A Reda\u00e7\u00e3o Nutritotal PRO \u00e9 formada por nutricionistas, m\u00e9dicos e estudantes de nutri\u00e7\u00e3o que t\u00eam a preocupa\u00e7\u00e3o de produzir conte\u00fados atuais, baseados em evid\u00eancia cient\u00edficas, sempre com o objetivo de facilitar a pr\u00e1tica cl\u00ednica de profissionais da \u00e1rea da sa\u00fade.\",\"sameAs\":[\"https:\/\/www.facebook.com\/nutritotalPRO\/?ref=pages_you_manage&_rdc=1&_rdr\",\"https:\/\/www.instagram.com\/nutritotalpro\/?utm_medium=copy_link\",\"https:\/\/www.linkedin.com\/company\/nutritotal-pro\/?viewAsMember=true\",\"https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA\"],\"url\":\"https:\/\/nutritotal.com.br\/pro\/author\/nutritotal\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comer oleaginosas melhora a fun\u00e7\u00e3o vascular cerebral e a mem\u00f3ria de idosos","description":"Descubra como as oleaginosas podem impulsionar a sa\u00fade cerebral e a mem\u00f3ria em idosos. Entenda os mecanismos por tr\u00e1s desses efeitos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/","og_locale":"pt_BR","og_type":"article","og_title":"Comer oleaginosas melhora a fun\u00e7\u00e3o vascular cerebral e a mem\u00f3ria de idosos","og_description":"Descubra como as oleaginosas podem impulsionar a sa\u00fade cerebral e a mem\u00f3ria em idosos. Entenda os mecanismos por tr\u00e1s desses efeitos.","og_url":"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/","og_site_name":"Nutritotal PRO","article_publisher":"https:\/\/www.facebook.com\/nutritotalPRO\/","article_author":"https:\/\/www.facebook.com\/nutritotalPRO\/?ref=pages_you_manage&_rdc=1&_rdr","article_published_time":"2023-09-04T13:00:01+00:00","article_modified_time":"2023-09-01T13:21:34+00:00","og_image":[{"width":580,"height":400,"url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2023\/09\/oleaginosas-e-funcao-cerebral.png","type":"image\/png"}],"author":"Reda\u00e7\u00e3o Nutritotal PRO","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Nutritotal PRO","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/#article","isPartOf":{"@id":"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/"},"author":{"name":"Reda\u00e7\u00e3o Nutritotal PRO","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/ebc724f6275a533739e9d1ad603f21a2"},"headline":"Comer oleaginosas melhora a fun\u00e7\u00e3o vascular cerebral e a mem\u00f3ria de idosos","datePublished":"2023-09-04T13:00:01+00:00","dateModified":"2023-09-01T13:21:34+00:00","mainEntityOfPage":{"@id":"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/"},"wordCount":753,"commentCount":0,"publisher":{"@id":"https:\/\/nutritotal.com.br\/pro\/#organization"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/#primaryimage"},"thumbnailUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2023\/09\/oleaginosas-e-funcao-cerebral.png","keywords":["castanhas","cogni\u00e7\u00e3o","mem\u00f3ria","nozes","oleaginosas"],"articleSection":["Longevidade","Nutri\u00e7\u00e3o em consult\u00f3rio"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/","url":"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/","name":"Comer oleaginosas melhora a fun\u00e7\u00e3o vascular cerebral e a mem\u00f3ria de idosos","isPartOf":{"@id":"https:\/\/nutritotal.com.br\/pro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/#primaryimage"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/#primaryimage"},"thumbnailUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2023\/09\/oleaginosas-e-funcao-cerebral.png","datePublished":"2023-09-04T13:00:01+00:00","dateModified":"2023-09-01T13:21:34+00:00","description":"Descubra como as oleaginosas podem impulsionar a sa\u00fade cerebral e a mem\u00f3ria em idosos. Entenda os mecanismos por tr\u00e1s desses efeitos.","breadcrumb":{"@id":"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/#primaryimage","url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2023\/09\/oleaginosas-e-funcao-cerebral.png","contentUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2023\/09\/oleaginosas-e-funcao-cerebral.png","width":580,"height":400,"caption":"Fonte: Canva.com"},{"@type":"BreadcrumbList","@id":"https:\/\/nutritotal.com.br\/pro\/comer-oleaginosas-melhora-a-funcao-vascular-cerebral-e-a-memoria-de-idosos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nutritotal.com.br\/pro\/"},{"@type":"ListItem","position":2,"name":"Comer oleaginosas melhora a fun\u00e7\u00e3o vascular cerebral e a mem\u00f3ria de idosos"}]},{"@type":"WebSite","@id":"https:\/\/nutritotal.com.br\/pro\/#website","url":"https:\/\/nutritotal.com.br\/pro\/","name":"Nutritotal PRO","description":"","publisher":{"@id":"https:\/\/nutritotal.com.br\/pro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nutritotal.com.br\/pro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nutritotal.com.br\/pro\/#organization","name":"Nutri Total","url":"https:\/\/nutritotal.com.br\/pro\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/","url":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","contentUrl":"https:\/\/nutritotal.com.br\/pro\/wp-content\/uploads\/2022\/12\/Nutritotal-Pro-Vertical-02.png","width":426,"height":426,"caption":"Nutri Total"},"image":{"@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nutritotalPRO\/","https:\/\/www.instagram.com\/nutritotalpro\/","https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA"]},{"@type":"Person","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/ebc724f6275a533739e9d1ad603f21a2","name":"Reda\u00e7\u00e3o Nutritotal PRO","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nutritotal.com.br\/pro\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0b28a44567fd9e96213e21d1d40eeb15?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0b28a44567fd9e96213e21d1d40eeb15?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o Nutritotal PRO"},"description":"A Reda\u00e7\u00e3o Nutritotal PRO \u00e9 formada por nutricionistas, m\u00e9dicos e estudantes de nutri\u00e7\u00e3o que t\u00eam a preocupa\u00e7\u00e3o de produzir conte\u00fados atuais, baseados em evid\u00eancia cient\u00edficas, sempre com o objetivo de facilitar a pr\u00e1tica cl\u00ednica de profissionais da \u00e1rea da sa\u00fade.","sameAs":["https:\/\/www.facebook.com\/nutritotalPRO\/?ref=pages_you_manage&_rdc=1&_rdr","https:\/\/www.instagram.com\/nutritotalpro\/?utm_medium=copy_link","https:\/\/www.linkedin.com\/company\/nutritotal-pro\/?viewAsMember=true","https:\/\/www.youtube.com\/channel\/UCf01IyXkHLYUDGG0-XHR-YA"],"url":"https:\/\/nutritotal.com.br\/pro\/author\/nutritotal\/"}]}},"views":1956,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/63437"}],"collection":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/users\/114981"}],"replies":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/comments?post=63437"}],"version-history":[{"count":3,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/63437\/revisions"}],"predecessor-version":[{"id":63449,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/posts\/63437\/revisions\/63449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/media\/63440"}],"wp:attachment":[{"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/media?parent=63437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/categories?post=63437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/tags?post=63437"},{"taxonomy":"divisao","embeddable":true,"href":"https:\/\/nutritotal.com.br\/pro\/wp-json\/wp\/v2\/divisao?post=63437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}